{"id":548700,"date":"2026-05-13T10:47:16","date_gmt":"2026-05-13T10:47:16","guid":{"rendered":"https:\/\/www.europesays.com\/es\/548700\/"},"modified":"2026-05-13T10:47:16","modified_gmt":"2026-05-13T10:47:16","slug":"muere-a-los-47-anos-jason-collins-el-primer-jugador-de-la-nba-que-se-declaro-homosexual-en-activo","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/548700\/","title":{"rendered":"Muere a los 47 a\u00f1os Jason Collins, el primer jugador de la NBA que se declar\u00f3 homosexual en activo"},"content":{"rendered":"<p style=\"\">El estadounidense Jason Collins, <a href=\"https:\/\/www.abc.es\/deportes\/baloncesto\/\" title=\"www.abc.es\" data-voc-vtm-id=\"in-text-traffic\" data-mrf-link=\"www.abc.es\" rel=\"nofollow noopener\" target=\"_blank\">exjugador de New Jersey Nets y Atlanta Hawks,<\/a> entre otros, y el primer deportista de la <a href=\"https:\/\/www.abc.es\/noticias\/nba\/\" title=\"www.abc.es\" data-voc-vtm-id=\"in-text-traffic\" data-mrf-link=\"www.abc.es\" rel=\"nofollow noopener\" target=\"_blank\">NBA <\/a>en declararse abiertamente homosexual, ha fallecido este martes a los 47 a\u00f1os por un c\u00e1ncer cerebral que le fue diagnosticado el a\u00f1o pasado,  &#8230; seg\u00fan ha confirmado su familia en un comunicado.<\/p>\n<p class=\"v-d-p\" style=\"\">\u00abNos rompe el coraz\u00f3n compartir que Jason Collins, nuestro amado marido, hijo, hermano y t\u00edo, ha fallecido tras una valiente lucha contra el glioblastoma. Jason cambi\u00f3 vidas de maneras inesperadas y fue una inspiraci\u00f3n para todos los que lo conocieron y para aquellos que lo admiraron desde lejos. Estamos agradecidos por la avalancha de amor y oraciones durante los \u00faltimos ocho meses, y por la atenci\u00f3n m\u00e9dica excepcional que Jason recibi\u00f3 de sus m\u00e9dicos y enfermeras. Nuestra familia lo extra\u00f1ar\u00e1 profundamente\u00bb, se\u00f1al\u00f3 su familia.<\/p>\n<p class=\"v-d-p\" style=\"\">Collins desvel\u00f3 en noviembre de 2025 que le hab\u00edan diagnosticado glioblastoma en etapa 4, una de las formas m\u00e1s letales de c\u00e1ncer cerebral. Recibi\u00f3 un tratamiento experimental en Singapur, pero recientemente reapareci\u00f3 el c\u00e1ncer y este martes falleci\u00f3 en su casa.<\/p>\n<ul class=\"v-cmp-rld__u\">\n<li class=\"v-cmp-rld__l\">\n<p><a class=\"v-a-lnk\" href=\"http:\/\/www.abc.es\/deportes\/baloncesto\/luka-doncic-renuncia-seleccion-eslovena-hijas-20260512121057-nt.html#vtm_modulosEngag=noticiasrelacionadas-cmp-uno:deportes:noticia:1\" title=\"Luka Doncic renuncia a la selecci\u00f3n eslovena por sus hijas\" data-voc-vtm-id=\"in-text-traffic\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/luka-doncic-U22007361378cfk-366x256@diario_abc.jpg\" class=\"v-a-img\" width=\"258\" height=\"180\" alt=\"Luka Doncic renuncia a la selecci\u00f3n eslovena por sus hijas\"\/><br \/>\n<\/a><\/p>\n<\/li>\n<\/ul>\n<p class=\"v-d-p\" style=\"\">Collins se retir\u00f3 en 2014 tras una carrera de 13 a\u00f1os en la liga norteamericana en la que pas\u00f3 por New Jersey Nets (2001-2008), Memphis Grizzlies (2008), Minnesota Timberwolves (2008-2009), Atlanta Hawks (2009-2012), Boston Celtics (2012-2013), Washington Wizards (2013) y Brooklyn Nets (2014).<\/p>\n<p>\nRevel\u00f3 su homosexualidad a\u00fan en activo\n<\/p>\n<p class=\"v-d-p\" style=\"\">En 2013, desvel\u00f3 su homosexualidad en un art\u00edculo de portada de Sports Illustrated, convirti\u00e9ndose en el primer deportista abiertamente gay en jugar en cualquiera de las cuatro principales ligas deportivas de Norteam\u00e9rica.<\/p>\n<p class=\"v-d-p\" style=\"\">El comisionado de la NBA, Adam Silver, destac\u00f3 que \u00abel impacto e influencia de Jason Collins se extendieron mucho m\u00e1s all\u00e1 del baloncesto\u00bb. \u00abAyud\u00f3 a hacer que la NBA, la WNBA y la comunidad deportiva en general fueran m\u00e1s inclusivas y acogedoras para las generaciones futuras. Ejemplific\u00f3 un liderazgo y profesionalismo excepcionales a lo largo de su carrera de 13 a\u00f1os en la NBA y en su dedicado trabajo como embajador de NBA Cares\u00bb, apunt\u00f3.<\/p>\n<p class=\"v-d-p\" style=\"\">\u00abJason ser\u00e1 recordado no solo por romper barreras, sino tambi\u00e9n por la amabilidad y humanidad que definieron su vida y tocaron a tantas otras personas. En nombre de la NBA, env\u00edo mis m\u00e1s sentidas condolencias a Brunson, esposo de Jason, y a su familia, amigos y colegas en todas nuestras ligas\u00bb, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"El estadounidense Jason Collins, exjugador de New Jersey Nets y Atlanta Hawks, entre otros, y el primer deportista&hellip;\n","protected":false},"author":2,"featured_media":548701,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93],"tags":[3418,24778,106651,168,25,24,36448,7739,378,8938,1725,977,23,167],"class_list":{"0":"post-548700","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"tag-activo","9":"tag-collins","10":"tag-declaro","11":"tag-deportes","12":"tag-es","13":"tag-espana","14":"tag-homosexual","15":"tag-jason","16":"tag-jugador","17":"tag-muere","18":"tag-nba","19":"tag-primer","20":"tag-spain","21":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116566874457851695","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=548700"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/548701"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=548700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=548700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=548700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}