{"id":548938,"date":"2026-05-13T13:40:18","date_gmt":"2026-05-13T13:40:18","guid":{"rendered":"https:\/\/www.europesays.com\/es\/548938\/"},"modified":"2026-05-13T13:40:18","modified_gmt":"2026-05-13T13:40:18","slug":"bolsas-suben-por-impulso-tecnologico-mientras-sigue-cerrado-hormuz","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/548938\/","title":{"rendered":"Bolsas suben por impulso tecnol\u00f3gico mientras sigue cerrado Hormuz"},"content":{"rendered":"<p>    <img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/ee6daad5491713efbf8cdfd4f403385d.jpeg\" alt=\"Foto: Bloomberg\" loading=\"eager\" height=\"640\" width=\"960\" class=\"yf-lglytj  loaded\"\/> Foto: Bloomberg      <\/p>\n<p class=\"yf-1fy9kyt\">(Bloomberg) &#8212; Los compradores de oportunidad impulsaron al alza las acciones tecnol\u00f3gicas, con operadores apostando a que el rally de los fabricantes de chips a\u00fan tiene margen para continuar. El petr\u00f3leo fluctu\u00f3 despu\u00e9s de una racha de tres alzas diarias, mientras el estrecho de Ormuz segu\u00eda cerrado.<\/p>\n<p class=\"yf-1fy9kyt\">Los contratos del Nasdaq 100 avanzaron 0,7%, junto con un repunte del \u00edndice Kospi de Corea del Sur y un m\u00e1ximo hist\u00f3rico de un indicador clave con fuerte peso tecnol\u00f3gico en China. Los futuros del S&amp;P 500 ganaron 0,2%, mientras que las acciones mineras lideraron un avance de 0,3% en Europa.<\/p>\n<p class=\"yf-1fy9kyt\">Lo m\u00e1s le\u00eddo de Bloomberg<\/p>\n<p class=\"yf-1fy9kyt\">Nvidia Corp. subi\u00f3 2,5% en las operaciones previas a la apertura en EE.UU. despu\u00e9s de que su cofundador, Jensen Huang, se uniera al presidente Donald Trump en su visita a China. Los fabricantes de procesadores y chips de memoria registraron ganancias generalizadas. El d\u00f3lar subi\u00f3 0,2%.<\/p>\n<p class=\"yf-1fy9kyt\">Los bonos del Tesoro y los bonos gubernamentales europeos avanzaron modestamente. Los gilts recortaron sus ganancias iniciales mientras continuaba el drama pol\u00edtico en Reino Unido. En el giro m\u00e1s reciente, el Times inform\u00f3 que Wes Streeting, un posible aspirante al cargo de primer ministro, se preparaba para renunciar al gabinete del primer ministro Keir Starmer.<\/p>\n<p class=\"yf-1fy9kyt\">El alza en el sector tecnol\u00f3gico se sustenta en que los inversionistas conf\u00edan en el enorme potencial de ganancias de la IA para resistir las preocupaciones por los elevados precios del petr\u00f3leo, en momentos que los flujos desde Medio Oriente no muestran se\u00f1ales de normalizarse. Los operadores tambi\u00e9n apuestan a que la cumbre de esta semana entre Trump y el presidente chino Xi Jinping podr\u00eda desbloquear una serie de acuerdos comerciales, especialmente en torno a los semiconductores.<\/p>\n<p class=\"yf-1fy9kyt\">\u201cLa pregunta m\u00e1s dif\u00edcil para los inversionistas en este momento es encontrar operaciones de cobertura en caso de que la guerra en Ir\u00e1n se prolongue y los precios del petr\u00f3leo se mantengan altos\u201d, dijo Marija Veitmane, jefa de investigaci\u00f3n de renta variable de State Street Global Markets. \u201cEl mejor lugar para refugiarse ser\u00edan las compa\u00f1\u00edas con ganancias y m\u00e1rgenes m\u00e1s s\u00f3lidos, as\u00ed como ganancias muy visibles y predecibles. Todos los caminos conducen a la tecnolog\u00eda\u201d.<\/p>\n<p class=\"yf-1fy9kyt\">Principales movimientos del mercado<\/p>\n<p class=\"yf-1fy9kyt\">\u00a0<\/p>\n<p class=\"yf-1fy9kyt\">Acciones<\/p>\n<ul class=\"yf-1p2hw41\">\n<li class=\"yf-1p2hw41\">\n<p class=\"yf-1fy9kyt\">Los futuros del S&amp;P 500 subieron 0,2% a las 6:37 a.m., hora de Nueva York.<\/p>\n<\/li>\n<li class=\"yf-1p2hw41\">\n<p class=\"yf-1fy9kyt\">Los futuros del Nasdaq 100 subieron 0,7%.<\/p>\n<\/li>\n<li class=\"yf-1p2hw41\">\n<p class=\"yf-1fy9kyt\">Los futuros del Promedio Industrial Dow Jones bajaron 0,3%.<\/p>\n<\/li>\n<li class=\"yf-1p2hw41\">\n<p class=\"yf-1fy9kyt\">El Stoxx Europe 600 subi\u00f3 0,3%.<\/p>\n<\/li>\n<li class=\"yf-1p2hw41\">\n<p class=\"yf-1fy9kyt\">El \u00edndice MSCI World oper\u00f3 con pocos cambios.<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"Foto: Bloomberg (Bloomberg) &#8212; Los compradores de oportunidad impulsaron al alza las acciones tecnol\u00f3gicas, con operadores apostando a&hellip;\n","protected":false},"author":2,"featured_media":548939,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[14278,24744,82,95,94,25,24,81680,72018,41714,14588,23,106675],"class_list":{"0":"post-548938","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia","8":"tag-bloomberg","9":"tag-bonos-del-tesoro","10":"tag-business","11":"tag-economia","12":"tag-economy","13":"tag-es","14":"tag-espana","15":"tag-estrecho-de-ormuz","16":"tag-hora-de-nueva-york","17":"tag-jensen-huang","18":"tag-precios-del-petroleo","19":"tag-spain","20":"tag-wes-streeting"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116567555276362844","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=548938"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/548939"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=548938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=548938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=548938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}