{"id":548972,"date":"2026-05-13T14:03:16","date_gmt":"2026-05-13T14:03:16","guid":{"rendered":"https:\/\/www.europesays.com\/es\/548972\/"},"modified":"2026-05-13T14:03:16","modified_gmt":"2026-05-13T14:03:16","slug":"la-inflacion-ppi-de-estados-unidos-se-dispara-al-6","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/548972\/","title":{"rendered":"La inflaci\u00f3n PPI de Estados Unidos se dispara al 6%"},"content":{"rendered":"<p style=\"line-height:1.38\">La lectura de abril del PPI de Estados Unidos ha mostrado el <strong>mayor aumento de los precios de producci\u00f3n desde 2022<\/strong>, al situarse en un 6%. El incremento se debe, como era de esperar, en gran parte a los <strong>mayores precios de la gasolina<\/strong>. Aun as\u00ed, la medida subyacente \u2014que excluye alimentos y energ\u00eda\u2014 tambi\u00e9n repunt\u00f3 con fuerza, hasta el <strong>5,2%<\/strong>.\u00a0<\/p>\n<p><img decoding=\"async\" alt=\"Gr\u00c3\u00a1fico con la el IPC y el PPI de EE.\u00e2\u0080\u00afUU. (2018\u00e2\u0080\u00932026)\" data-source-description=\"Fuente: XTB Research, 13.05.2026\" style=\"width: 1200px; height: 722px;\" src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2026\/05\/image-20260513145745-1.png\" class=\"lazyload\"\/><\/p>\n<p><strong>Todas las lecturas del PPI sorprenden al alza<\/strong><\/p>\n<p>Los datos han superado ampliamente las previsiones del mercado, situ\u00e1ndose muy por encima de los niveles esperados.<\/p>\n<ul>&#13;<\/p>\n<li>&#13;\n<p><strong>PPI interanual:<\/strong> 6,0% (consenso: 4,8%)<\/p>\n<p>&#13;\n\t<\/li>\n<p>&#13;<\/p>\n<li>&#13;\n<p><strong>PPI mensual:<\/strong> 1,4% (consenso: 0,5%)<\/p>\n<p>&#13;\n\t<\/li>\n<p>&#13;<\/p>\n<li>&#13;\n<p><strong>Core PPI interanual:<\/strong> 5,2% (consenso: 4,3%)<\/p>\n<p>&#13;\n\t<\/li>\n<p>&#13;<\/p>\n<li>&#13;\n<p><strong>Core PPI mensual:<\/strong> 1,0% (consenso: 0,3%)<\/p>\n<p>&#13;\n\t<\/li>\n<p>&#13;<\/p>\n<li>&#13;\n<p><strong>Super\u2011core PPI interanual:<\/strong> 5,2% (consenso: 4,3%)<\/p>\n<p>&#13;\n\t<\/li>\n<p>&#13;<\/p>\n<li>&#13;\n<p><strong>Super\u2011core PPI mensual:<\/strong> 1,0% (consenso: 0,3%)<\/p>\n<p>&#13;\n\t<\/li>\n<p>&#13;\n<\/ul>\n<p>El Core PPI excluye alimentos y energ\u00eda, mientras que el super\u2011core excluye alimentos, energ\u00eda y servicios comerciales.<\/p>\n<p style=\"color:rgba(24,24,30,0.4); font-size: 12px; text-align: justify;\">El contenido que se presenta en la secci\u00f3n de FORMACI\u00d3N s\u00f3lo tiene fines informativos, educativos y de apoyo para utilizar la plataforma. El material presentado, incluyendo los an\u00e1lisis, precios, opiniones u otros contenidos, no es una recomendaci\u00f3n de inversi\u00f3n o informaci\u00f3n que recomiende o sugiera una estrategia de inversi\u00f3n ni se incluye en el \u00e1mbito del asesoramiento en materia de inversi\u00f3n recogido en la Ley 6\/2023 de los Mercados de Valores y de los Servicios de Inversi\u00f3n (art\u00edculo 125.1 g). Este v\u00eddeo se ha preparado sin tener en cuenta las necesidades del cliente ni su situaci\u00f3n financiera individual.<br \/>&#13;<br \/>\nXTB no aceptar\u00e1 responsabilidad por ning\u00fan tipo de p\u00e9rdidas o da\u00f1os, incluyendo, entre otros, cualquier lucro cesante, que pueda surgir directa o indirectamente del uso o dependencia de la informaci\u00f3n incluida en este v\u00eddeo. XTB S.A. no es responsable de las acciones u omisiones del cliente, especialmente por la adquisici\u00f3n o disposici\u00f3n de instrumentos financieros, realizados con base en la informaci\u00f3n que contiene este v\u00eddeo.<br \/>&#13;<br \/>\nEl rendimiento pasado no es necesariamente indicativo de resultados futuros y cualquier persona que act\u00fae sobre esta informaci\u00f3n lo hace bajo su propio riesgo.<br \/>&#13;<br \/>\nCopyright \u00a9 XTB S.A. Todos los derechos reservados. Est\u00e1 prohibido copiar, modificar y distribuir este v\u00eddeo sin el consentimiento expreso de XTB S.A.<\/p>\n","protected":false},"excerpt":{"rendered":"La lectura de abril del PPI de Estados Unidos ha mostrado el mayor aumento de los precios de&hellip;\n","protected":false},"author":2,"featured_media":535051,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[82,95,94,25,24,23],"class_list":{"0":"post-548972","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia","8":"tag-business","9":"tag-economia","10":"tag-economy","11":"tag-es","12":"tag-espana","13":"tag-spain"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@es\/116567645156306216","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=548972"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/548972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/535051"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=548972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=548972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=548972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}