{"id":75484,"date":"2025-08-27T10:45:09","date_gmt":"2025-08-27T10:45:09","guid":{"rendered":"https:\/\/www.europesays.com\/es\/75484\/"},"modified":"2025-08-27T10:45:09","modified_gmt":"2025-08-27T10:45:09","slug":"aranceles-de-eeuu-a-india-se-duplican-al-50-por-compras-de-petroleo-ruso","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/es\/75484\/","title":{"rendered":"Aranceles de EEUU a India se duplican al 50% por compras de petr\u00f3leo ruso"},"content":{"rendered":"<p>    <img src=\"https:\/\/www.europesays.com\/es\/wp-content\/uploads\/2025\/08\/72jp7kg-item01-ipad-89900056.jpg\" width=\"1024\" height=\"682\" alt=\"\" loading=\"eager\" decoding=\"sync\" fetchpriority=\"high\"\/><\/p>\n<p>            afp_tickers        <\/p>\n<p>        Este contenido fue publicado en    <\/p>\n<p>        27 agosto 2025 &#8211; 12:13\n<\/p>\n<p>Los aranceles de Estados Unidos aplicados a las importaciones de India, que desde principios de mes eran del 25%, se duplicaron el mi\u00e9rcoles al 50%, una forma del presidente Donald Trump de castigar a Nueva Delhi por comprar petr\u00f3leo de Rusia.<\/p>\n<p>India es uno de los principales importadores de petr\u00f3leo ruso, despu\u00e9s de China, y el mandatario estadounidense acusa a Nueva\u00a0Delhi de ayudar a Mosc\u00fa a financiar su guerra en Ucrania.<\/p>\n<p>India calific\u00f3 la medida como \u00abinjusta, injustificada e irrazonable, y su gremio de exportadores pidi\u00f3 una intervenci\u00f3n del gobierno para aplacar el temor a una p\u00e9rdida de empleos.<\/p>\n<p>Con la medida, las relaciones entre Estados Unidos e India se tensan a\u00fan m\u00e1s, lo que da a Nueva Delhi un nuevo incentivo para mejorar sus v\u00ednculos con su rival hist\u00f3rico, China.<\/p>\n<p>Aunque Trump ha impuesto nuevos aranceles tanto a aliados como a competidores desde que volvi\u00f3 a la Casa Blanca en enero, esta tarifa del 50% es una de las m\u00e1s altas a la que se enfrentan los socios comerciales de Estados Unidos.\u00a0<\/p>\n<p>No obstante, persisten exenciones para sectores que podr\u00edan verse afectados por grav\u00e1menes separados, como los productos farmac\u00e9uticos y los semiconductores de las computadoras.<\/p>\n<p>El gobierno de Trump ha lanzado investigaciones sobre estas y otras industrias que podr\u00edan culminar en nuevos aranceles.\u00a0<\/p>\n<p>Los tel\u00e9fonos inteligentes tambi\u00e9n figuran en la lista de productos exentos.<\/p>\n<p>Sectores que ya han sido se\u00f1alados, como el acero, el aluminio y los autom\u00f3viles, tambi\u00e9n se libran de estos grav\u00e1menes a nivel nacional.<\/p>\n<p>Estados Unidos fue el principal destino de las exportaciones de India en 2024, con env\u00edos por 87.300 millones de d\u00f3lares.<\/p>\n<p>Analistas, sin embargo, advierten que un arancel del 50% equivale a un embargo comercial y probablemente perjudique a las peque\u00f1as empresas.<\/p>\n<p>\u2013 Pedidos cancelados \u2013<\/p>\n<p>Los exportadores indios de textiles, mariscos y joyer\u00eda reportaron la anulaci\u00f3n de pedidos a Estados Unidos, lo que fue aprovechado por rivales como Banglad\u00e9s y Vietnam, despertando temores de p\u00e9rdidas de empleo.<\/p>\n<p>Ajay Sahai, director general de la Federaci\u00f3n de Organizaciones Exportadoras de India, pidi\u00f3 \u00abapoyo de liquidez de parte del gobierno\u00bb.<\/p>\n<p>\u00abQueremos asegurar que, incluso si se frenan los negocios, podemos seguir pagando a los empleados\u00bb, declar\u00f3 a AFP.<\/p>\n<p>Ante el golpe econ\u00f3mico, el primer ministro indio, Narendra Modi, prometi\u00f3 \u00abbajar la carga tributaria sobre la gente del com\u00fan\u00bb, en un discurso anual pronunciado con motivo de la Independencia.<\/p>\n<p>El Ministerio de Relaciones Exteriores hab\u00eda declarado anteriormente que India hab\u00eda comenzado a importar petr\u00f3leo de Rusia, en un escenario en que sus proveedores tradicionales se desviaron a Europa debido a la invasi\u00f3n rusa de Ucrania.<\/p>\n<p>Se\u00f1al\u00f3 que Washington foment\u00f3 activamente estas importaciones en ese momento para reforzar la estabilidad del mercado energ\u00e9tico mundial.<\/p>\n<p>Rusia represent\u00f3 casi el 36% del total de las importaciones de crudo de India en 2024.<\/p>\n<p>La compra de petr\u00f3leo ruso supuso para Nueva Delhi un ahorro de miles de millones de d\u00f3lares en costos de importaci\u00f3n.<\/p>\n<p>El asesor econ\u00f3mico de Trump, Peter Navarro, dijo previamente a periodistas que \u00abIndia no parece querer reconocer su papel en el derramamiento de sangre\u00bb.\u00a0<\/p>\n<p>\u00abSe est\u00e1 acercando a Xi Jinping\u00bb, a\u00f1adi\u00f3 en referencia al presidente chino.<\/p>\n<p>Wendy Cutler, vicepresidenta senior del Asia Society Policy Institute, consider\u00f3 \u00abpreocupante\u00bb que India pasara de \u00abser un candidato prometedor para un acuerdo comercial temprano\u00bb a una naci\u00f3n que enfrenta uno de los \u00abaranceles m\u00e1s altos\u00bb impuestos a socios comerciales de Washington.\u00a0<\/p>\n<p>\u00abLos elevados aranceles han erosionado r\u00e1pidamente la confianza entre los dos pa\u00edses, que podr\u00eda tardar a\u00f1os en reconstruirse\u00bb, dijo a AFP.<\/p>\n<p>Trump ha usado los aranceles como herramienta para abordar desde lo que Washington considera pr\u00e1cticas comerciales desleales hasta desequilibrios comerciales.<\/p>\n<p>Los aranceles estadounidenses sobre productos brasile\u00f1os tambi\u00e9n aumentaron al 50% este mes, aunque con amplias exenciones.<\/p>\n<p>els\/myl\/ph\/gmo\/atm\/arm\/mas<\/p>\n","protected":false},"excerpt":{"rendered":"afp_tickers Este contenido fue publicado en 27 agosto 2025 &#8211; 12:13 Los aranceles de Estados Unidos aplicados a&hellip;\n","protected":false},"author":2,"featured_media":75485,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[17,18,82,83,84,13,14,11,61,62,85,63,86,64,19,20,87,9,10,15,16,88,89,90,12,21,22,65,66,67],"class_list":{"0":"post-75484","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"tag-breaking-news","9":"tag-breakingnews","10":"tag-business","11":"tag-diplomacy","12":"tag-economy-general","13":"tag-featured-news","14":"tag-featurednews","15":"tag-headlines","16":"tag-internacional","17":"tag-international","18":"tag-international-foreign-trade","19":"tag-international-news","20":"tag-international-relations","21":"tag-internationalnews","22":"tag-latest-news","23":"tag-latestnews","24":"tag-macro-economics","25":"tag-news","26":"tag-noticias","27":"tag-noticias-destacadas","28":"tag-noticiasdestacadas","29":"tag-politics","30":"tag-tariff","31":"tag-ticker","32":"tag-titulares","33":"tag-ultimas-noticias","34":"tag-ultimasnoticias","35":"tag-world","36":"tag-world-news","37":"tag-worldnews"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/75484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/comments?post=75484"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts\/75484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media\/75485"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/media?parent=75484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/categories?post=75484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags?post=75484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}