{"id":94932,"count":3,"description":"","link":"https:\/\/www.europesays.com\/es\/tag\/moses-wright\/","name":"moses wright","slug":"moses-wright","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags\/94932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/es\/wp-json\/wp\/v2\/posts?tags=94932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}