{"id":11187,"count":1,"description":"","link":"https:\/\/www.europesays.com\/fi\/tag\/husqvarna-ab\/","name":"Husqvarna AB","slug":"husqvarna-ab","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fi\/wp-json\/wp\/v2\/tags\/11187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/fi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/fi\/wp-json\/wp\/v2\/posts?tags=11187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}