{"id":24179,"count":2,"description":"","link":"https:\/\/www.europesays.com\/fi\/tag\/soutuveneet\/","name":"soutuveneet","slug":"soutuveneet","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fi\/wp-json\/wp\/v2\/tags\/24179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/fi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/fi\/wp-json\/wp\/v2\/posts?tags=24179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}