{"id":253049,"date":"2025-07-17T04:47:10","date_gmt":"2025-07-17T04:47:10","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/253049\/"},"modified":"2025-07-17T04:47:10","modified_gmt":"2025-07-17T04:47:10","slug":"grenoble-lance-son-plan-chien-sept-hectares-dans-la-ville-pour-laisser-les-chiens-en-liberte","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/253049\/","title":{"rendered":"Grenoble lance son \u00ab\u00a0Plan Chien\u00a0\u00bb, sept hectares dans la ville pour laisser les chiens en libert\u00e9"},"content":{"rendered":"<p>\u00c0 partir de ce lundi 21 juillet, les parcs de Grenoble vont peu \u00e0 peu ouvrir des espaces de libert\u00e9 pour les chiens. Des zones o\u00f9 ils pourront gambader sans laisse. Une exp\u00e9rimentation qui doit durer un an. <\/p>\n<p>C&rsquo;est une nouvelle mesure pour am\u00e9liorer le quotidien des chiens \u00e0 Grenoble. Progressivement \u00e0 partir de cette fin du mois de juillet, les parcs de la ville vont se doter de zones o\u00f9 les chiens pourront \u00eatre l\u00e2ch\u00e9s sans laisse. Au total <strong>7 hectares sont concern\u00e9s d\u00e8s les premi\u00e8res semaines<\/strong> avec des espaces de libert\u00e9 dans le Parc Paul Mistral, le Parc Vallier Catane, le Jardin Hoche et le Square Roger Genin.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"VisualPreview svelte-1rldrkz\" src=\"data:image\/jpeg;base64,\/9j\/2wBDACgcHiMeGSgjISMtKygwPGRBPDc3PHtYXUlkkYCZlo+AjIqgtObDoKrarYqMyP\/L2u71\/\/\/\/m8H\/\/\/\/6\/+b9\/\/j\/2wBDASstLTw1PHZBQXb4pYyl+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj\/wAARCAAXACoDASIAAhEBAxEB\/8QAFgABAQEAAAAAAAAAAAAAAAAAAAEC\/8QAFhABAQEAAAAAAAAAAAAAAAAAAAER\/8QAFQEBAQAAAAAAAAAAAAAAAAAAAAH\/xAAUEQEAAAAAAAAAAAAAAAAAAAAA\/9oADAMBAAIRAxEAPwBWK3WaIgKgsXCKCVkFBQQaigo\/\/9k=\" alt=\"Dans le Parc Paul Mistral (\u00e0 gauche) et le Parc Vallier Catane (\u00e0 droite), il y aura d\u00e9sormais des zones o\u00f9 les chiens pourront \u00eatre sans laisse\" width=\"600\" height=\"337\"\/>  Dans le Parc Paul Mistral (\u00e0 gauche) et le Parc Vallier Catane (\u00e0 droite), il y aura d\u00e9sormais des zones o\u00f9 les chiens pourront \u00eatre sans laisse  &#8211; Ville de Grenoble<\/p>\n<p>Ces nouvelles zones ne seront pas d\u00e9limit\u00e9es physiquement par des cl\u00f4tures, des panneaux indiqueront simplement leur p\u00e9rim\u00e8tre. La municipalit\u00e9, en plus de vouloir agir sur le bien-\u00eatre des chiens, entend aussi <strong>mettre un cadre \u00e0 une pratique qui est d\u00e9j\u00e0 r\u00e9pandue dans les parcs grenoblois<\/strong>.<\/p>\n<p>Le calendrier de l&rsquo;exp\u00e9rimentation cet \u00e9t\u00e9\u00a0:\u00a0<br \/>\u2022 Parc Paul Mistral \u2013 \u00e0 partir du 21 juillet<br \/>\u2022 Jardin Hoche \u2013 \u00e0 partir du 28 juillet<br \/>\u2022 Parc Vallier Catane \u2013 \u00e0 partir du 4 ao\u00fbt<br \/>\u2022 Square Roger Genin \u2013 \u00e0 partir du 11 ao\u00fbt<\/p>\n<p>D&rsquo;autres espaces suivront au mois de septembre\u00a0:<br \/>\u2022 Parc des Champs-\u00c9lys\u00e9es \u2013 \u00e0 partir du 8 septembre<br \/>\u2022 Parc Pompidou \u2013 \u00e0 partir du 15 septembre<br \/>\u2022 Berges de l\u2019Is\u00e8re \u2013 \u00e0 partir du 22 septembre<br \/>\u2022 Chemin de halage \u2013 \u00e0 partir du 29 septembre<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"VisualPreview svelte-1rldrkz\" src=\"data:image\/jpeg;base64,\/9j\/2wBDACgcHiMeGSgjISMtKygwPGRBPDc3PHtYXUlkkYCZlo+AjIqgtObDoKrarYqMyP\/L2u71\/\/\/\/m8H\/\/\/\/6\/+b9\/\/j\/2wBDASstLTw1PHZBQXb4pYyl+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj\/wAARCAAXACoDASIAAhEBAxEB\/8QAGAABAQEBAQAAAAAAAAAAAAAAAAECAwT\/xAAYEAEBAQEBAAAAAAAAAAAAAAAAARECEv\/EABYBAQEBAAAAAAAAAAAAAAAAAAABAv\/EABURAQEAAAAAAAAAAAAAAAAAAAAB\/9oADAMBAAIRAxEAPwD0x05rlK1KDrrNrPotQZrK2oomroM1DTQQTQGh\/9k=\" alt=\"Le panneau qui indique les nouveaux espaces de libert\u00e9 pour les chiens dans les parcs grenoblois\" width=\"600\" height=\"337\"\/>  Le panneau qui indique les nouveaux espaces de libert\u00e9 pour les chiens dans les parcs grenoblois  &#8211; Ville de Grenoble<\/p>\n<p>Pour pouvoir laisser son chien en libert\u00e9 dans les zones pr\u00e9vues \u00e0 cet effet, <strong>il faudra pouvoir garder le contr\u00f4le \u00e0 tout moment sur son compagnon<\/strong>. La municipalit\u00e9 fixe certains crit\u00e8res\u00a0: avoir une laisse sur soi, rappel en trois fois maximum, chien \u00e0 port\u00e9e de voix et de vue. Autre point de vigilance, les chiens en libert\u00e9 ne devront pas s&rsquo;approcher de mani\u00e8re intempestive des passants.<\/p>\n<p><strong>Des \u00e9quipes de m\u00e9diation seront d\u00e9ploy\u00e9es dans les parcs<\/strong> d\u00e8s le d\u00e9but de l&rsquo;exp\u00e9rimentation pour aller \u00e0 la rencontre des propri\u00e9taires de chiens et rappeler les bonnes pratiques. La police municipale sera elle aussi plus vigilante pour faire respecter les r\u00e8gles et les nouvelles zones.<\/p>\n<p>Cette mesure est accueillie tr\u00e8s favorablement par les habitu\u00e9s du parc Paul Mistral. Pour Francis, venu avec son Jack Russel Terrier, c&rsquo;est \u00ab\u00a0enfin une bonne chose\u00a0\u00bb. Il l&rsquo;avoue, lui l\u00e2chait d\u00e9j\u00e0 r\u00e9guli\u00e8rement son chien malgr\u00e9 l&rsquo;interdiction. Pour Denise et Jo\u00eblle, qui fr\u00e9quentent le parc avec leurs petits-enfants, c&rsquo;est aussi une tr\u00e8s bonne id\u00e9e\u00a0: \u00ab\u00a0le but c&rsquo;est qu&rsquo;ils aient leur espace et nous le notre, on ne marchera plus dans les crottes, et on pourra leur dire d&rsquo;aller faire jouer leur chien dans l&rsquo;espace fait pour\u00a0\u00bb.<\/p>\n<p>\u00c0 lire aussi   <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2025\/07\/200x200_maxstockworld149388.jpg\" alt=\"Un chihuahua\" style=\"--_image-preview:url('data:image\/jpeg;base64,\/9j\/2wBDACgcHiMeGSgjISMtKygwPGRBPDc3PHtYXUlkkYCZlo+AjIqgtObDoKrarYqMyP\/L2u71\/\/\/\/m8H\/\/\/\/6\/+b9\/\/j\/2wBDASstLTw1PHZBQXb4pYyl+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj4+Pj\/wAARCAAqACoDASIAAhEBAxEB\/8QAFwABAQEBAAAAAAAAAAAAAAAAAQIAA\/\/EABYQAQEBAAAAAAAAAAAAAAAAAAABEf\/EABcBAQEBAQAAAAAAAAAAAAAAAAEAAgP\/xAAWEQEBAQAAAAAAAAAAAAAAAAAAARH\/2gAMAwEAAhEDEQA\/ALYaNc4FVNbU2nEKk2hJ00Wi1NoiNo1NoaKtYEUKqVVIiDYWbLMxFT\/\/2Q==');\" loading=\"lazy\" fetchpriority=\"low\" aria-hidden=\"true\" class=\"svelte-1pnmlwx rounded\" onload=\"this.__e=event\" onerror=\"this.__e=event\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"\u00c0 partir de ce lundi 21 juillet, les parcs de Grenoble vont peu \u00e0 peu ouvrir des espaces&hellip;\n","protected":false},"author":2,"featured_media":253050,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9566],"tags":[1111,11,2430,1777,674,1011,27,2731,12,25],"class_list":{"0":"post-253049","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-grenoble","8":"tag-actu","9":"tag-actualites","10":"tag-auvergne-rhone-alpes","11":"tag-eu","12":"tag-europe","13":"tag-fr","14":"tag-france","15":"tag-grenoble","16":"tag-news","17":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/114866765519737973","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/253049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=253049"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/253049\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/253050"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=253049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=253049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=253049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}