{"id":490259,"date":"2025-10-26T02:20:13","date_gmt":"2025-10-26T02:20:13","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/490259\/"},"modified":"2025-10-26T02:20:13","modified_gmt":"2025-10-26T02:20:13","slug":"la-chaine-parlementaire-replay-du-25-10-2025-ici-leurope","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/490259\/","title":{"rendered":"La Cha\u00eene parlementaire replay du 25\/10\/2025 : Ici l&rsquo;Europe"},"content":{"rendered":"<p>  25\/10\/2025  35min  4 vues<\/p>\n<p class=\"lead2 p-1 bg-body-tertiary rounded mt-2\">Apr\u00e8s l&rsquo;Italie de Giorgia Meloni, la Hongrie de Viktor Orb\u00e1n ou la Slovaquie de Robert Fico, les N\u00e9erlandais appel\u00e9s aux urnes ce 29 octobre feront-ils des Pays-Bas, le nouveau pays des 27 \u00e0 pl\u00e9bisciter un gouvernement de droite radicale ? Trumpiste et proche de Vladimir Poutine, Geert Wilders viendra-t-il grossir les rangs de l&rsquo;extr\u00eame droite europ\u00e9enne qui repr\u00e9sente d\u00e9j\u00e0 un quart de l&rsquo;h\u00e9micycle \u00e0 Strasbourg ? Caroline de Camaret et Alexandre Poussart lancent le d\u00e9bat et interrogent dans Ici l&rsquo;Europe des d\u00e9put\u00e9s autrichiens, espagnols et fran\u00e7ais.Invit\u00e9s??En premi\u00e8re partie, Caroline de Camaret re\u00e7oit Jos\u00e9 Manuel Albares En seconde partie, Caroline de Camaret et Alexandre Poussart re\u00e7oivent les eurod\u00e9put\u00e9s :- Virginie Joron, Patriote pour l&rsquo;Europe,- Helmut Brandst\u00e4tter, autrichien Renew Europe,- Javier Moreno Sanchez SD espagnol.Ici, l&rsquo;EuropeChaque semaine, LCP Assembl\u00e9e nationale, Public S\u00e9nat et France24 vous plongent au coeur des questions qui secouent l&rsquo;Europe : Covid-19, questions migratoires, \u00ab Green deal \u00bb, Brexit ou encore souverainet\u00e9 digitale. Quel avenir pour l&rsquo;Union et ses 450 millions d&rsquo;habitants ? Une demi-heure d&rsquo;information pour mieux comprendre les enjeux europ\u00e9ens.<\/p>\n","protected":false},"excerpt":{"rendered":"25\/10\/2025 35min 4 vues Apr\u00e8s l&rsquo;Italie de Giorgia Meloni, la Hongrie de Viktor Orb\u00e1n ou la Slovaquie de&hellip;\n","protected":false},"author":2,"featured_media":490260,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1586],"tags":[39020,11,6394,39019,1777,674,1011,27,39014,39013,12,39016,39017,39018,503,39015,502,39022,39021,362,58157,58158,25,39012],"class_list":["post-490259","post","type-post","status-publish","format-standard","has-post-thumbnail","category-europe","tag-a-la-tv","tag-actualites","tag-ce-soir-tv","tag-en-ce-moment-tv","tag-eu","tag-europe","tag-fr","tag-france","tag-guide-tele","tag-guide-tv","tag-news","tag-programme-canalsat","tag-programme-freebox","tag-programme-orange","tag-programme-tele","tag-programme-tnt","tag-programme-tv","tag-que-regarder-a-la-tv","tag-regarder-la-tv","tag-replay","tag-replay-tv","tag-replaytv","tag-republique-francaise","tag-soiree-tv"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/115438080743460640","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/490259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=490259"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/490259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/490260"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=490259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=490259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=490259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}