{"id":591630,"date":"2025-12-10T23:34:16","date_gmt":"2025-12-10T23:34:16","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/591630\/"},"modified":"2025-12-10T23:34:16","modified_gmt":"2025-12-10T23:34:16","slug":"le-pari-audacieux-de-la-royal-navy-pour-controler-le-passage-du-giuk","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/591630\/","title":{"rendered":"Le pari audacieux de la Royal Navy pour contr\u00f4ler le passage du GIUK"},"content":{"rendered":"<p>\n      Au d\u00e9but de la semaine, le ministre de la D\u00e9fense du Royaume-Uni a officiellement d\u00e9voil\u00e9 un programme qui pourrait marquer un tournant dans la guerre sous-marine moderne. Baptis\u00e9 Atlantic Bastion, ce plan vise \u00e0 d\u00e9ployer \u00e0 partir de 2026 un maillage in\u00e9dit de syst\u00e8mes autonomes destin\u00e9s \u00e0 d\u00e9tecter et surveiller les menaces sous-marines sur les approches britanniques et atlantiques.\n    <\/p>\n<p>Selon les responsables britanniques, la recrudescence d\u2019activit\u00e9s sous-marines russes vers et dans l\u2019Atlantique Nord impose d\u2019innover tant dans les moyens de d\u00e9tection que d\u2019intervention, et ce afin de contr\u00f4ler et \u00e9ventuellement interdire l\u2019acc\u00e8s au GIUK, ce passage strat\u00e9gique qui relie le Gro\u00ebnland, l\u2019Islande et le Royaume-Uni (ou Greenland, Iceland, United Kingdom &#8211; GIUK).<\/p>\n<p>L\u2019importance de ma\u00eetriser le GIUK<\/p>\n<p>Le Royaume-Uni disposant d\u2019un contr\u00f4le direct sur la Manche, Londres a entrepris, tout au long du XXe si\u00e8cle, de ma\u00eetriser autant que possible les acc\u00e8s nord de l\u2019Atlantique. Pour le Royaume-Uni, le contr\u00f4le du passage du GIUK permettait de s\u2019assurer qu\u2019aucun pays d\u2019Europe du Nord ou d\u2019Europe de l\u2019Est (ce qui incluait l\u2019Allemagne pendant les deux Guerres mondiales et l\u2019Union Sovi\u00e9tique durant la Guerre froide) ne serait en mesure d\u2019imposer sa domination sur l\u2019Atlantique Nord et d\u2019isoler le Royaume-Uni.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Au cours de la Guerre froide, le contr\u00f4le du GIUK a ainsi \u00e9t\u00e9 l\u2019une des priorit\u00e9s des marines de l\u2019OTAN, principalement l\u2019US Navy, mais avec un soutien r\u00e9gulier des unit\u00e9s britanniques notamment. La surveillance des transits en surface pouvait se faire via des avions de surveillance maritime ou des fr\u00e9gates, mais la d\u00e9tection et le suivi des sous-marins sovi\u00e9tiques, principale menace \u00e0 cette \u00e9poque, n\u00e9cessitait le d\u00e9ploiement d\u2019un important r\u00e9seau d\u2019hydrophones passifs (le syst\u00e8me SOSUS), combin\u00e9s \u00e0 des patrouilles r\u00e9guli\u00e8res de sous-marins d\u2019attaque, de fr\u00e9gates anti-sous-marines et autres avions de patrouille maritime bard\u00e9s de capteurs et d\u2019armements anti-sous-marins.<\/p>\n<p>Des moyens conventionnels \u00e0 bout de souffle<\/p>\n<p>A la fin de la Guerre froide, quand la menace sous-marine sovi\u00e9tique a virtuellement disparu, les moyens anti-sous-marins d\u00e9ploy\u00e9s dans le GIUK ont \u00e9galement p\u00e9riclit\u00e9, tout particuli\u00e8rement du c\u00f4t\u00e9 britannique. Aujourd\u2019hui encore, m\u00eame si Londres tente de renforcer ses moyens conventionnels afin de faire face \u00e0 des incursions russes de plus en plus nombreuses et aventureuses, les forces britanniques peinent \u00e0 retrouver un niveau d\u2019expertise suffisant. Alors m\u00eame que les moyens mat\u00e9riels sont bien moins nombreux que durant la Guerre froide, la Royal Navy et la Royal Air Force souffrent \u00e9galement de s\u00e9rieux probl\u00e8mes qualitatifs.<\/p>\n<p>\u00a0<\/p>\n<p>      Entre le retrait des derniers Nimrod, en 2011, et l&rsquo;arriv\u00e9e des premiers P-8 Poseidon, la Royal Air Force a pass\u00e9 pr\u00e8s d&rsquo;une d\u00e9cennie sans aucun avion de patrouille maritime. Certaines comp\u00e9tences ayant \u00e9t\u00e9 irr\u00e9m\u00e9diablement perdues, les \u00e9quipages de P-8 britanniques sont encore dans une phase de remont\u00e9e en puissance.<\/p>\n<p>\u00a0<\/p>\n<p>Ainsi, apr\u00e8s avoir compl\u00e8tement abandonn\u00e9 son aviation de patrouille maritime pendant plusieurs ann\u00e9es <a href=\"https:\/\/www.meretmarine.com\/fr\/defense\/nimrod-mra-4-en-abandonnant-le-programme-londres-fragilise-sa-dissuasion\" target=\"_blank\" rel=\"noopener\">suite au retrait du service des anciens Nimrod<\/a>, la Royal Air Force a certes remis la main sur des appareils modernes, des Boeing P-8 Poseidon, mais elle doit r\u00e9apprendre compl\u00e8tement \u00e0 ma\u00eetriser cet outil. Du c\u00f4t\u00e9 de la Royal Navy, les principaux probl\u00e8mes actuels se situent au niveau de <a href=\"https:\/\/www.meretmarine.com\/fr\/defense\/royal-navy-le-desarmement-de-cinq-grands-batiments-acte-pour-faire-des-economies\" target=\"_blank\" rel=\"noopener\">la disponibilit\u00e9 des unit\u00e9s navales majeures<\/a>, mais aussi \u2013\u00a0dans certains cas\u00a0\u2013 de la qualit\u00e9 des \u00e9quipages. En effet, la marine britannique ne dispose plus que de sept fr\u00e9gates anti-sous-marines (ASM) de <a href=\"https:\/\/www.meretmarine.com\/fr\/defense\/royal-navy-plus-que-9-fregates-du-type-23-operationnelles\" target=\"_blank\" rel=\"noopener\">Type\u00a023<\/a>, contre 13 en 2021. Et il faudra probablement le d\u00e9but des ann\u00e9es 2030 pour que la Royal Navy retrouve un format de 13 fr\u00e9gates, pour peu que les derni\u00e8res Type\u00a023 tiennent le choc et que les nouvelles <a href=\"https:\/\/www.meretmarine.com\/fr\/defense\/royal-navy-une-capacite-operationnelle-initiale-attendue-en-2028-pour-la-premiere-t26\" target=\"_blank\" rel=\"noopener\">Type\u00a026<\/a> et <a href=\"https:\/\/www.meretmarine.com\/fr\/defense\/royal-navy-la-premiere-fregate-du-type-31-s-apprete-a-etre-mise-a-l-eau\" target=\"_blank\" rel=\"noopener\">Type\u00a031<\/a> soient livr\u00e9es dans les temps.<\/p>\n<p>\u00a0<\/p>\n<p>      Pour l&rsquo;heure, la Royal Navy ne dispose plus que de sept fr\u00e9gates ASM de Type\u00a023 dont la disponibilit\u00e9 reste tr\u00e8s faible, tant en raison de l&rsquo;\u00e2ge des navires que des indispensables chantiers de modernisation.<\/p>\n<p>\u00a0<\/p>\n<p>Mais m\u00eame avec l\u2019arriv\u00e9e de nouvelles classes de navires, la recrudescence d\u2019activit\u00e9 dans l\u2019Atlantique Nord inqui\u00e8te Londres. Le secr\u00e9taire \u00e0 la D\u00e9fense, John Healey, a ainsi <a href=\"https:\/\/www.gov.uk\/government\/news\/uk-unveils-new-undersea-warfare-technology-to-counter-threat-from-russia\" target=\"_blank\" rel=\"noopener\">d\u00e9clar\u00e9 r\u00e9cemment<\/a> : \u00ab Il ne fait aucun doute que le Royaume-Uni et ses alli\u00e9s sont confront\u00e9s \u00e0 de nouvelles menaces sous-marines, o\u00f9 nos adversaires ciblent des infrastructures essentielles \u00e0 notre mode de vie \u00bb. Il fait notamment allusions aux menaces de sabotage d&rsquo;infrastructures critiques, comme les c\u00e2bles de puissance et de t\u00e9l\u00e9communication.\u00a0<\/p>\n<p>De quoi pousser Londres \u00e0 adopter une nouvelle strat\u00e9gie\u00a0: Atlantic Bastion. L\u2019objectif\u00a0? Renouer avec le principe du SOSUS afin de faire face non seulement aux nouvelles g\u00e9n\u00e9rations de sous-marins nucl\u00e9aires et de sous-marins conventionnels russes, toujours plus silencieux, mais aussi afin de contrer les strat\u00e9gies d\u2019action russes sur le plancher oc\u00e9anique (le fameux \u00ab\u00a0seabed warfare\u00a0\u00bb) et de prot\u00e9ger des infrastructures strat\u00e9giques pour l\u2019Europe (approvisionnement \u00e9nerg\u00e9tiques, c\u00e2bles sous-marins, etc.).<\/p>\n<p>Tout miser sur les nouvelles technologies<\/p>\n<p>Pour faire d\u2019Atlantic Bastion un SOSUS de nouvelle g\u00e9n\u00e9ration, le minist\u00e8re de la d\u00e9fense britannique semble vouloir beaucoup miser sur les nouvelles technologies disponibles ou en cours de d\u00e9veloppement. Tel que d\u00e9crit par la Royal Navy elle-m\u00eame, Atlantic Bastion \u00ab\u00a0permettra de connecter des navires, des sous-marins, des avions et des drones gr\u00e2ce \u00e0 une technologie de d\u00e9tection acoustique aliment\u00e9e par l&rsquo;IA et int\u00e9gr\u00e9e \u00e0 un r\u00e9seau num\u00e9rique de ciblage. Il s&rsquo;agit d&rsquo;un r\u00e9seau pionnier de syst\u00e8mes d&rsquo;armes qui permet de prendre et d&rsquo;ex\u00e9cuter plus rapidement les d\u00e9cisions sur le champ de bataille pour cibler les menaces ennemies\u00a0\u00bb.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>      Inonder le passage du GIUK de drones, gliders et senseurs sous-marins ne suffira pas \u00e0 assurer un contr\u00f4le de la zone. Comme pour le r\u00e9seau SOSUS durant la Guerre froide, Atlantic Bastion aura besoin d&rsquo;importants moyens d&rsquo;analyse et de traitement de l&rsquo;information, et d&rsquo;une coordination \u00e9troite avec les centres de commandement. Si l&rsquo;IA pourrait aider, elle ne saurait se substituer totalement aux op\u00e9rateurs humains pour ces t\u00e2ches.<\/p>\n<p>\u00a0<\/p>\n<p>Dit autrement, le programme reposera principalement sur de nouveaux capteurs acoustiques dispos\u00e9s sur le plancher oc\u00e9anique, des v\u00e9hicules sous-marins autonomes (drones et gliders), mais aussi des syst\u00e8mes de traitement des donn\u00e9es par des IA embarqu\u00e9es\u2026 De nombreux efforts devront \u00e9galement \u00eatre faits en mati\u00e8re de fusion de donn\u00e9es, de communications s\u00e9curis\u00e9es et de liaisons de donn\u00e9es, afin que ces nouvelles g\u00e9n\u00e9rations d\u2019engins autonomes puissent alimenter en informations les navires et avions pilot\u00e9s, et interagir avec eux.<\/p>\n<p>D\u2019ores et d\u00e9j\u00e0, d\u2019apr\u00e8s la Royal Navy, pr\u00e8s de 26 entreprises britanniques et europ\u00e9ennes auraient propos\u00e9 de d\u00e9velopper de nouveaux capteurs pour alimenter le programme Atlantic Bastion, et \u00ab\u00a020 entreprises, allant des grands groupes aux PME du secteur technologique, pr\u00e9sentent d\u00e9j\u00e0 des d\u00e9monstrateurs technologiques, avec un ratio d&rsquo;investissement public et priv\u00e9 de 4 pour 1 \u00e0 ce jour\u00a0\u00bb.<\/p>\n<p>Une occasion r\u00eav\u00e9e pour les industriels<\/p>\n<p>Parmi les entreprises impliqu\u00e9es dans le programme, et \u00e9voqu\u00e9es par le gouvernement britannique, on retrouve des acteurs historiques, comme BAE Systems Defence Solutions, mais aussi certains leaders de la \u00ab\u00a0New Defense\u00a0\u00bb, ces entreprises de la tech qui cherchent \u00e0 r\u00e9volutionner l\u2019industrie de l\u2019armement, comme l\u2019entreprise am\u00e9ricaine Anduril (\u00e0 travers sa branche Anduril UK), ou la plus europ\u00e9enne Helsing.<\/p>\n<p>Anduril UK propose notamment Seabed Sentry, un syst\u00e8me de surveillance destin\u00e9 \u00e0 pr\u00e9positionner divers capteurs sur le plancher oc\u00e9anique. D\u00e9velopp\u00e9 au Royaume-Uni, ce syst\u00e8me propose une enveloppe pressuris\u00e9e capable de recevoir divers capteurs, une IA embarqu\u00e9e capable de collecter, combiner et traiter les signaux re\u00e7us, ainsi que des syst\u00e8mes de communication permettant d\u2019exporter les donn\u00e9es en question (principalement acoustiques).<\/p>\n<p>BAE Systems, de son c\u00f4t\u00e9, \u00e9voque son drone sous-marin de grande taille Herne, ainsi que son syst\u00e8me de conduite, de contr\u00f4le et de combat pour v\u00e9hicules autonomes de surface ou sous-marins\u00a0: Nautomate. Dans la m\u00eame veine, Helsing compte positionner son planeur sous-marin autonome SG-1 Fathom, pouvant \u00eatre produit en s\u00e9rie dans son usine de Plymouth, ainsi que Lura, sa plateforme logicielle boost\u00e9e \u00e0 l\u2019IA con\u00e7ue pour assurer une surveillance sous-marine continue, notamment \u00e0 proximit\u00e9 des infrastructures critiques.<\/p>\n<p>\u00a0<\/p>\n<p>\n                  Diaporama                <\/p>\n<p>Trois industriels majeurs ont \u00e9t\u00e9 explicitement cit\u00e9s par les autorit\u00e9s britanniques lors de la pr\u00e9sentation d\u2019Atlantic Bastion. BAE Systems, Anduril UK et Helsing pr\u00e9sentent globalement des solutions similaires, qui s\u2019appuient \u00e0 la fois sur des vecteurs sous-marins autonomes de nouvelle g\u00e9n\u00e9ration et sur des logiciels d\u2019analyse du signal et de traitement de l\u2019information faisant la part belle \u00e0 l\u2019intelligence artificielle. Du c\u00f4t\u00e9 de BAE Systems, on retrouve notamment le drone sous-marin de grande taille Herne et la solution de surveillance Nautomate. Anduril, de son c\u00f4t\u00e9, s\u2019appuie sur des senseurs fixes \u2013 les Seabed Sentry \u2013 pouvant \u00eatre positionn\u00e9s par des drones sous-marins. Helsing, enfin, souhaite produire en s\u00e9rie son glider SG-1 Fathom, \u00e9paul\u00e9 par la solution IA Lura.<\/p>\n<p>\u00a0<\/p>\n<p>En marge des annonces officielles, d\u2019autres industriels semblent vouloir profiter de la manne potentielle apport\u00e9e par Atlantic Bastion, et proposent spontan\u00e9ment leurs solutions. C\u2019est notamment le cas du britannique Babcock, qui se positionne assez agressivement avec sa solution ARMOR Force (Autonomous and Remote, Maritime Operational Response), une architecture distribu\u00e9e de syst\u00e8mes et de plateformes autonomes capables d\u2019interagie avec et au profit d\u2019unit\u00e9s navales majeures, notamment des fr\u00e9gates.<\/p>\n<p>\u00a0<\/p>\n<p>      La solution ARMOR Force de Babcock s&rsquo;articule autour d&rsquo;une fr\u00e9gate T31 modifi\u00e9e en b\u00e2timent de commandement pour des flottilles de drones maritimes.<\/p>\n<p>\u00a0<\/p>\n<p>\u00c9paul\u00e9 par le groupe am\u00e9ricain Huntington Ingalls Industries (HII), qui dispose d\u00e9j\u00e0 d\u2019une famille de drones de surface, les ROMULUS, ainsi que par le sp\u00e9cialiste en intelligence artificielle Arondite, Babcock pousse sa vision d\u2019une \u00ab\u00a0marine hybride\u00a0\u00bb combinant navires habit\u00e9s et navires autonomes. Le c\u0153ur de ces op\u00e9rations hybrides serait alors, bien \u00e9videmment, <a href=\"https:\/\/www.meretmarine.com\/fr\/defense\/babcock-met-sur-cale-la-troisieme-fregate-britannique-du-type-31\" target=\"_blank\" rel=\"noopener\">des fr\u00e9gates Type 31<\/a> (con\u00e7ues et fabriqu\u00e9es par Babcock) que l\u2019industriel proposerait dans une nouvelle variante CCV (Common Command Vessel). Cette T31 CCV serait alors capable de g\u00e9rer, \u00e0 la mer, les diff\u00e9rentes couches de d\u00e9tection et de protection n\u00e9cessaires \u00e0 Atlantic Bastion.<\/p>\n<p>De bien belles ambitions, parfois compl\u00e9mentaires, parfois contradictoires, qu\u2019il conviendra donc de concr\u00e9tiser d\u2019une mani\u00e8re ou d\u2019une autre.<\/p>\n<p>Strat\u00e9gie des moyens ou strat\u00e9gie d\u00e9claratoire\u00a0?<\/p>\n<p>Du c\u00f4t\u00e9 britannique, on le promet, \u00ab\u00a0la prochaine phase de d\u00e9veloppement et d&rsquo;essais verra les entreprises retenues poursuivre le travail de d\u00e9veloppement, du concept \u00e0 la mise en service, avec un d\u00e9ploiement pr\u00e9vu en 2026, suivi d&rsquo;investissements suppl\u00e9mentaires visant \u00e0 acc\u00e9l\u00e9rer et \u00e0 \u00e9tendre le programme\u00a0\u00bb. Reste cependant \u00e0 voir \u00e0 quelle hauteur un tel projet pourra \u00eatre financ\u00e9 par le Tr\u00e9sor britannique, d\u00e8s lors qu\u2019il sera n\u00e9cessaire de passer de la phase d\u2019essai \u00e0 une phase d\u2019industrialisation massive. Un contexte qui n&rsquo;est pas sans rappeler de pr\u00e9c\u00e9dentes d\u00e9clarations du minist\u00e8re de la D\u00e9fense britannique, notamment concernant l&rsquo;utilisation d&rsquo;essaims de drones depuis les deux porte-avions de la Royal Navy. Si de nombreuses d\u00e9monstrations tr\u00e8s m\u00e9diatis\u00e9es avaient eu lieu \u00e0 l&rsquo;\u00e9poque, les r\u00e9sultats concrets de ces annonces ne sont pas encore perceptibles sur le plan op\u00e9rationnel, loin s&rsquo;en faut.<\/p>\n<p>\u00a0<\/p>\n<p>      La Royal Navy a l&rsquo;habitude de proc\u00e9der \u00e0 des d\u00e9monstrations ambitieuses afin d&rsquo;\u00e9valuer de futures capacit\u00e9s. Dans le domaine des drones a\u00e9riens embarqu\u00e9s, cela ne s&rsquo;est pas encore traduit en capacit\u00e9s op\u00e9rationnelles concr\u00e8tes. Reste \u00e0 voir si Atlantic Bastion pourra passer plus rapidement de la phase d&rsquo;essais \u00e0 la phase op\u00e9rationnelle.<\/p>\n<p>\u00a0<\/p>\n<p>De fait, m\u00eame si Atlantic Bastion rev\u00eat un caract\u00e8re strat\u00e9gique \u2013\u00a0et urgent\u00a0\u2013 indubitable, d\u2019autres programme britanniques, tout aussi importants et vitaux, souffrent de sous-investissements majeurs. D\u00e8s lors, le timing et le contexte des d\u00e9clarations autour d\u2019Atlantic Bastion sont sans doute tout aussi int\u00e9ressants \u00e0 analyser que leur contenu. En l\u2019occurrence, le lancement d\u2019Atlantic Bastion intervient alors que le First Sea Lord, le g\u00e9n\u00e9ral Sir Gwyn Jenkins, a pr\u00e9sent\u00e9 sa vision de l&rsquo;avenir de la Royal Navy lors de l\u2019International Sea Power Conference qui s\u2019est tenue \u00e0 Londres le 8 d\u00e9cembre.<\/p>\n<p>A cette occasion, il a ainsi d\u00e9clar\u00e9 qu&rsquo; \u00ab\u00a0un r\u00e9seau sous-marin r\u00e9volutionnaire est en train de prendre forme, de la dorsale m\u00e9dio-atlantique \u00e0 la mer de Norv\u00e8ge. Plus autonome, plus r\u00e9silient, plus meurtrier, et construit par les Britanniques. Nous avons d\u00e9j\u00e0 r\u00e9alis\u00e9 des progr\u00e8s rapides et significatifs dans la mise en place d&rsquo;Atlantic Bastion. Une force qui assure notre s\u00e9curit\u00e9 chez nous et notre puissance \u00e0 l&rsquo;\u00e9tranger \u00bb.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>      Ventes d&rsquo;armes, enjeux g\u00e9opolitiques et diplomatie vont souvent de paire. Au-del\u00e0 d&rsquo;\u00eatre un partenaire commercial du Royaume-Uni, avec l&rsquo;achat de fr\u00e9gates Type 26, la Norv\u00e8ge est aussi un partenaire strat\u00e9gique de premier ordre pour Londres. R\u00e9cemment, une fr\u00e9gate de la classe Nansen a accompagn\u00e9 le groupe a\u00e9ronaval britannique lors de son d\u00e9ploiement de 8\u00a0mois en Indopacifique. De telles collaborations strat\u00e9giques pourraient sans doute se prolonger dans le cadre d&rsquo;Atlantic Bastion.<\/p>\n<p>\u00a0<\/p>\n<p>Ainsi, les autorit\u00e9s britanniques pr\u00e9sentent Atlantic Bastion comme une initiative tout autant britannique qu\u2019europ\u00e9enne et alli\u00e9e, destin\u00e9e \u00e0 prot\u00e9ger l\u2019ensemble de ses partenaires europ\u00e9ens et otaniens. Une pr\u00e9sentation qui intervient quelques jours \u00e0 peine apr\u00e8s avoir d\u00e9voil\u00e9 le<a href=\"https:\/\/www.meretmarine.com\/fr\/defense\/lunna-house-agreement-le-royaume-uni-et-la-norvege-renforcent-leur-collaboration-dans-la-lutte-anti\" target=\"_blank\" rel=\"noopener\"> Lunna House Agreement<\/a>, un accord de coop\u00e9ration strat\u00e9gique qui lie le Royaume-Uni et la Norv\u00e8ge justement autour des questions de lutte anti-sous-marine et de \u00ab\u00a0seabed warfare\u00a0\u00bb. De fait, et \u00e0 bien des \u00e9gards, la puissance britannique dans la r\u00e9gion n\u2019est pas uniquement li\u00e9e au nombre de b\u00e2timents que sa marine peut aligner, mais \u00e9galement \u00e0<a href=\"https:\/\/www.meretmarine.com\/fr\/defense\/la-royal-navy-va-envoyer-une-flottille-de-patrouilleurs-cotiers-en-norvege\" target=\"_blank\" rel=\"noopener\"> la solidit\u00e9 et \u00e0 la fid\u00e9lit\u00e9 des r\u00e9seaux d\u2019alliance r\u00e9gionaux <\/a>que Londres arrive \u00e0 mettre en place et \u00e0 entretenir au fil des ann\u00e9es.<\/p>\n<p>En pr\u00e9sentant Atlantic Bastion comme un bouclier pour le nord de l\u2019Europe, Londres vient ainsi probablement de renforcer encore un peu plus ses liens avec la Norv\u00e8ge, tout en marquant peut-\u00eatre un certain nombre de points aupr\u00e8s d\u2019autres pays de la r\u00e9gion, notamment le Danemark et la Su\u00e8de. Deux pays qui, justement, doivent prochainement choisir leurs futures fr\u00e9gates ASM, <a href=\"https:\/\/www.meretmarine.com\/fr\/defense\/naval-group-propose-la-fdi-avec-des-missiles-britanniques-camm\" target=\"_blank\" rel=\"noopener\">probablement entre des mod\u00e8les fran\u00e7ais et britanniques<\/a>, justement.<\/p>\n<p><strong>\u00a9 Un article de la r\u00e9daction de Mer et Marine.\u00a0Reproduction interdite sans consentement du ou des auteurs. \u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Au d\u00e9but de la semaine, le ministre de la D\u00e9fense du Royaume-Uni a officiellement d\u00e9voil\u00e9 un programme qui&hellip;\n","protected":false},"author":2,"featured_media":591631,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1588],"tags":[11,6130,6141,6131,6138,2380,6135,554,1777,6136,674,6139,6134,3135,6128,567,6129,6127,12,6132,4838,6133,473,1853,6140,6137,1851,1850,1852],"class_list":{"0":"post-591630","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-royaume-uni","8":"tag-actualites","9":"tag-chantiers","10":"tag-commando","11":"tag-construction-navale","12":"tag-costa","13":"tag-croisiere","14":"tag-dcns","15":"tag-defense","16":"tag-eu","17":"tag-euronaval","18":"tag-europe","19":"tag-fremm","20":"tag-interviews","21":"tag-littoral","22":"tag-marine","23":"tag-marine-nationale","24":"tag-maritime","25":"tag-mer","26":"tag-news","27":"tag-offshore","28":"tag-peche","29":"tag-reportages","30":"tag-royaume-uni","31":"tag-royaume-uni-de-grande-bretagne-et-dirlande-du-nord","32":"tag-sncm","33":"tag-stx","34":"tag-uk","35":"tag-united-kingdom","36":"tag-united-kingdom-of-great-britain-and-northern-ireland"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/115697894242937838","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/591630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=591630"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/591630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/591631"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=591630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=591630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=591630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}