{"id":642587,"date":"2026-01-05T13:50:09","date_gmt":"2026-01-05T13:50:09","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/642587\/"},"modified":"2026-01-05T13:50:09","modified_gmt":"2026-01-05T13:50:09","slug":"sur-ces-axes-tres-empruntes-autour-de-rennes-certains-vehicules-interdits-de-circuler","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/642587\/","title":{"rendered":"sur ces axes tr\u00e8s emprunt\u00e9s autour de Rennes, certains v\u00e9hicules interdits de circuler"},"content":{"rendered":"<p>                    Par<br \/>\n        <strong><br \/>\n            <a href=\"https:\/\/actu.fr\/auteur\/clemence-pays02-actu-fr\" title=\"Consulter tous les articles de Cl\u00e9mence Pays\" target=\"_blank\" rel=\"noopener\">Cl\u00e9mence Pays<\/a><br \/>\n                    <\/strong><\/p>\n<p>        Publi\u00e9 le<\/p>\n<p>            5 janv. 2026 \u00e0 12h55        <\/p>\n<p><a href=\"https:\/\/actu.fr\/bretagne\/rennes_35238\/en-bretagne-de-la-neige-pour-la-rentree-vigilance-orange-declenchee-par-meteo-france_63647457.html\" target=\"_blank\" rel=\"noopener\">La Bretagne est en vigilance orange neige-verglas<\/a> ce lundi 5\u00a0janvier 2026 et <a href=\"https:\/\/actu.fr\/bretagne\/rennes_35238\/3-a-4-cm-de-neige-attendus-a-rennes-voici-a-quelle-heure-les-flocons-vont-tomber_63649732.html\" target=\"_blank\" rel=\"noopener\">les flocons sont attendus \u00e0 Rennes dans la journ\u00e9e<\/a>. Face \u00e0 cette situation m\u00e9t\u00e9orologique exceptionnelle, les autorit\u00e9s <strong>appellent \u00e0 la vigilance,<\/strong> en particulier sur les routes.<\/p>\n<p class=\" wall-content\">Dans ce but, <a href=\"https:\/\/actu.fr\/bretagne\/rennes_35238\/neige-verglas-en-ille-et-vilaine-transports-scolaires-suspendus-et-restrictions-pour-les-poids-lourds_63648949.html\" target=\"_blank\" rel=\"noopener\">les transports scolaires ont \u00e9t\u00e9 suspendus dans tout le d\u00e9partement<\/a>.<\/p>\n<p>Les routes interdites aux camions<\/p>\n<p class=\" wall-content\">La pr\u00e9fecture d\u2019Ille-et-Vilaine a par ailleurs annonc\u00e9<strong> l\u2019interdiction pour les poids lourds de plus de 7,5 tonnes<\/strong> de circuler sur le<strong> r\u00e9seau routier national.<\/strong><\/p>\n<p class=\" wall-content\">D\u2019autre part, les <strong>axes d\u00e9partementaux<\/strong> suivant sont \u00e9galement interdits \u00e0 ces m\u00eames v\u00e9hicules\u2009:<\/p>\n<ul class=\" wall-content\">\n<li>la <strong>RD137<\/strong> (axe Rennes-Saint-Malo)\u2009;<\/li>\n<li>la <strong>RD173<\/strong> (axe Rennes-Angers)\u2009;<\/li>\n<li>la <strong>RD177<\/strong> (axe Rennes-Redon).<\/li>\n<\/ul>\n<p class=\" wall-content\">Le D\u00e9partement pr\u00e9cise toutefois que ces interdictions <strong>ne s\u2019appliquent pas<\/strong> aux\u2009:<\/p>\n<ul class=\" wall-content\">\n<li>v\u00e9hicules d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral prioritaires ou b\u00e9n\u00e9ficiant de facilit\u00e9s de passage tels que d\u00e9finis \u00e0 l\u2019article R.311-1 du Code de la route\u2009;<\/li>\n<li>v\u00e9hicules d\u2019exploitation des gestionnaires routiers, v\u00e9hicules servant au transport de sel de d\u00e9neigement ou de fondants routiers\u2009;<\/li>\n<li>v\u00e9hicules de d\u00e9pannage et de remorquage\u2009;<\/li>\n<li>v\u00e9hicules indispensables aux op\u00e9rations non programm\u00e9es de d\u00e9pannage et de r\u00e9paration des \u00e9quipements et r\u00e9seaux publics d\u2019\u00e9nergie, d\u2019eau potable, d\u2019assainissement, de chauffage, de communication lorsque ces v\u00e9hicules concourent \u00e0 des op\u00e9rations\u2009;<\/li>\n<li>v\u00e9hicules de transports de personnes.<\/li>\n<\/ul>\n<p class=\" wall-content\">Personnalisez votre actualit\u00e9 en ajoutant vos villes et m\u00e9dias en favori avec <a href=\"https:\/\/moncompte.actu.fr\" title=\"D\u00e9couvez Mon Actu\" rel=\"nofollow noopener\" data-trk=\"{&quot;cta&quot;:{&quot;action&quot;:&quot;https:\\\/\\\/moncompte.actu.fr&quot;,&quot;category&quot;:&quot;mon compte&quot;,&quot;from&quot;:&quot;article footer&quot;,&quot;name&quot;:&quot;Mon actu&quot;,&quot;type&quot;:&quot;cta&quot;}}\" target=\"_blank\">Mon Actu<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Par Cl\u00e9mence Pays Publi\u00e9 le 5 janv. 2026 \u00e0 12h55 La Bretagne est en vigilance orange neige-verglas ce&hellip;\n","protected":false},"author":2,"featured_media":642588,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2821],"tags":[1111,11,829,3542,1777,674,1011,27,803,2487,10584,12,584,25],"class_list":{"0":"post-642587","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-rennes","8":"tag-actu","9":"tag-actualites","10":"tag-bretagne","11":"tag-circulation","12":"tag-eu","13":"tag-europe","14":"tag-fr","15":"tag-france","16":"tag-info-trafic","17":"tag-meteo","18":"tag-neige","19":"tag-news","20":"tag-rennes","21":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/115842818174136042","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/642587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=642587"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/642587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/642588"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=642587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=642587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=642587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}