{"id":674758,"date":"2026-01-19T16:42:11","date_gmt":"2026-01-19T16:42:11","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/674758\/"},"modified":"2026-01-19T16:42:11","modified_gmt":"2026-01-19T16:42:11","slug":"convoque-avec-lequipe-de-rugby-a-7-enzo-benmegal-manquera-les-deplacements-a-grenoble-et-oyonnax-avec-le-rc-vannes","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/674758\/","title":{"rendered":"Convoqu\u00e9 avec l\u2019\u00e9quipe de rugby \u00e0 7, Enzo Benmegal manquera les d\u00e9placements \u00e0 Grenoble et Oyonnax avec le RC Vannes"},"content":{"rendered":"<p><a href=\"https:\/\/www.letelegramme.fr\/fiches\/rugby\/rc-vannes\/rugby\/enzo-benmegal-6925e8299775c2c4cc04937f.php\" target=\"_blank\" rel=\"noopener\">Enzo Benmegal<\/a> manquera les deux derniers matchs du bloc de Pro D2. L\u2019ailier du RC Vannes va participer aux tournois de Singapour (31 janvier &#8211; 1er f\u00e9vrier) et de Perth (7-8 f\u00e9vrier) avec l\u2019\u00e9quipe de France de rugby \u00e0 7.<\/p>\n<p>En cons\u00e9quence, il ne sera pas disponible pour les d\u00e9placements du RCV \u00e0 Grenoble, vendredi, et \u00e0 Oyonnax, jeudi 29 janvier. Il avait d\u00e9j\u00e0 manqu\u00e9 la r\u00e9ception de Brive, samedi dernier, car il \u00e9tait en stage \u00e0 Marcoussis.<\/p>\n<p>Sept essais en onze matchs de Pro D2<\/p>\n<p>Cette saison, l\u2019ailier supersonique de 22 ans s\u2019impose avec le club morbihannais. Il a disput\u00e9 onze matchs, tous comme titulaires, et inscrit sept essais, dont plusieurs en solitaire, comme face \u00e0 Mont-de-Marsan lors de son dernier match.<\/p>\n<p>Benmegal devrait \u00eatre de retour pour le prochain bloc, qui d\u00e9butera par la r\u00e9ception de Carcassonne, le vendredi 13 f\u00e9vrier (19 h 30).<\/p>\n","protected":false},"excerpt":{"rendered":"Enzo Benmegal manquera les deux derniers matchs du bloc de Pro D2. L\u2019ailier du RC Vannes va participer&hellip;\n","protected":false},"author":2,"featured_media":674759,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9566],"tags":[1111,11,2430,3166,1777,674,1011,27,2731,12,2308,3164,3167,25,479,60,3165],"class_list":{"0":"post-674758","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-grenoble","8":"tag-actu","9":"tag-actualites","10":"tag-auvergne-rhone-alpes","11":"tag-en-continu-sports","12":"tag-eu","13":"tag-europe","14":"tag-fr","15":"tag-france","16":"tag-grenoble","17":"tag-news","18":"tag-pro-d2","19":"tag-rc-vannes","20":"tag-rcv","21":"tag-republique-francaise","22":"tag-rugby","23":"tag-sports","24":"tag-vannes"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/115922766671078794","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/674758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=674758"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/674758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/674759"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=674758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=674758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=674758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}