{"id":674883,"date":"2026-01-19T17:51:18","date_gmt":"2026-01-19T17:51:18","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/674883\/"},"modified":"2026-01-19T17:51:18","modified_gmt":"2026-01-19T17:51:18","slug":"grenoble-avec-samedi-cest-veloski-montee-collective-a-velo-jusquau-col-de-porte","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/674883\/","title":{"rendered":"Grenoble. Avec \u201cSamedi c\u2019est v\u00e9loski\u201d, mont\u00e9e collective \u00e0 v\u00e9lo jusqu\u2019au col de Porte"},"content":{"rendered":"<p class=\"insetTitle\">Alpes l\u00e0, le collectif qui relie la ville aux sommets<\/p>\n<p>Alpes l\u00e0 est aujourd\u2019hui reconnue comme une association phare dans la promotion des mobilit\u00e9s douces et des pratiques sportives respectueuses de l\u2019environnement dans l\u2019espace alpin. Son histoire puise ses racines dans un mouvement informel de sportifs sensibilis\u00e9s aux enjeux \u00e9cologiques et d\u00e9sireux de repenser la mani\u00e8re de rejoindre la montagne.<\/p>\n<p>\u00ab\u00a0Nous sommes une dizaine de sportifs d\u2019environ 30 ans, venus d\u2019horizons vari\u00e9s, passionn\u00e9s par le v\u00e9lo, la montagne et la nature\u00a0\u00bb, r\u00e9sume Lucie Bouvier, porteuse du projet au sein d\u2019Alpes l\u00e0. Cette diversit\u00e9 d\u2019exp\u00e9riences constitue l\u2019un des atouts de l\u2019association\u00a0: chacun apporte sa sensibilit\u00e9, ses comp\u00e9tences et son \u00e9nergie pour faire vivre des projets innovants autour de la mobilit\u00e9 douce.<\/p>\n<p>Si Alpes l\u00e0 porte aujourd\u2019hui des \u00e9v\u00e9nements structurants comme Samedi c\u2019est v\u00e9loski, son ambition d\u00e9passe largement l\u2019organisation de journ\u00e9es sportives. L\u2019association milite pour une reconnexion durable entre la ville et la montagne, en valorisant des pratiques simples et accessibles, comme le v\u00e9lo \u00e0 assistance \u00e9lectrique, les transports actifs, ou encore l\u2019usage combin\u00e9 du v\u00e9lo et des sports de neige.<\/p>\n","protected":false},"excerpt":{"rendered":"Alpes l\u00e0, le collectif qui relie la ville aux sommets Alpes l\u00e0 est aujourd\u2019hui reconnue comme une association&hellip;\n","protected":false},"author":2,"featured_media":674884,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9566],"tags":[1111,11,2430,1687,207,112,436,1777,674,1011,27,2731,2732,9588,12,25],"class_list":{"0":"post-674883","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-grenoble","8":"tag-actu","9":"tag-actualites","10":"tag-auvergne-rhone-alpes","11":"tag-culture-loisirs","12":"tag-cyclisme","13":"tag-edition-grenoble-agglomeration","14":"tag-environnement","15":"tag-eu","16":"tag-europe","17":"tag-fr","18":"tag-france","19":"tag-grenoble","20":"tag-grenoble-bassin","21":"tag-ici-on-agit","22":"tag-news","23":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/115923037953681195","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/674883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=674883"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/674883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/674884"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=674883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=674883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=674883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}