{"id":676030,"date":"2026-01-20T05:37:10","date_gmt":"2026-01-20T05:37:10","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/676030\/"},"modified":"2026-01-20T05:37:10","modified_gmt":"2026-01-20T05:37:10","slug":"le-fontanil-cornillon-une-belle-affluence-pour-les-voeux-2026","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/676030\/","title":{"rendered":"Le Fontanil-Cornillon. Une belle affluence pour les v\u0153ux 2026"},"content":{"rendered":"<p class=\"heading\">&#8230;pour lire la suite, rejoignez notre communaut\u00e9 d&rsquo;abonn\u00e9s<\/p>\n<p class=\"subtitle\">et acc\u00e9dez \u00e0 l&rsquo;int\u00e9gralit\u00e9 de nos articles sur le site et l&rsquo;application mobile<\/p>\n<p class=\"price-detail\">&#13;<br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\u00e0 partir de 1 \u20ac  le 1er mois, sans engagement de dur\u00e9e&#13;\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p class=\"listSKU\" style=\"display:none\">{&lsquo;skus&rsquo;: [&lsquo;ldlswgpremium16&rsquo;]}<\/p>\n<p class=\"google-sub-infos\">Google : 1\u20ac le 1er mois puis 12,99\u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"&#8230;pour lire la suite, rejoignez notre communaut\u00e9 d&rsquo;abonn\u00e9s et acc\u00e9dez \u00e0 l&rsquo;int\u00e9gralit\u00e9 de nos articles sur le site&hellip;\n","protected":false},"author":2,"featured_media":676031,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9566],"tags":[1111,11,2430,1687,112,1777,674,3326,12127,1011,27,2731,12,25,276],"class_list":{"0":"post-676030","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-grenoble","8":"tag-actu","9":"tag-actualites","10":"tag-auvergne-rhone-alpes","11":"tag-culture-loisirs","12":"tag-edition-grenoble-agglomeration","13":"tag-eu","14":"tag-europe","15":"tag-fete-locale","16":"tag-fontanil-cornillon","17":"tag-fr","18":"tag-france","19":"tag-grenoble","20":"tag-news","21":"tag-republique-francaise","22":"tag-saint-egreve-et-autour"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/115925814130138903","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/676030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=676030"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/676030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/676031"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=676030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=676030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=676030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}