{"id":680088,"date":"2026-01-21T23:15:11","date_gmt":"2026-01-21T23:15:11","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/680088\/"},"modified":"2026-01-21T23:15:11","modified_gmt":"2026-01-21T23:15:11","slug":"delogu-accuse-nunez-de-laisser-crever-police-judiciaire-marseillaise-dans-une-passe-darmes-sur-fond-daffaire-trident","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/680088\/","title":{"rendered":"Delogu accuse Nu\u00f1ez de laisser \u00ab\u00a0crever police judiciaire marseillaise\u00a0\u00bb dans une passe d&rsquo;armes sur fond d&rsquo;affaire Trident"},"content":{"rendered":"<p><strong>Passe d\u2019armes<\/strong> entre <a href=\"https:\/\/www.laprovence.com\/article\/elections\/25374352922679\/municipales-2026-a-marseille-sebastien-delogu-lfi-ou-le-rapport-de-force-comme-programme\" target=\"_blank\" rel=\"noopener\">S\u00e9bastien Delogu<\/a> et <a href=\"https:\/\/www.laprovence.com\/article\/faits-divers-justice\/87312411818138\/exclusif-marseille-doit-arreter-de-voir-mourir-ses-enfants-entretien-avec-gerald-darmanin-et-laurent-nunez\" target=\"_blank\" rel=\"noopener\">Laurent Nu\u00f1ez<\/a> \u00e0 l\u2019Assembl\u00e9e nationale. Le d\u00e9put\u00e9 LFI de la 7\u1d49 circonscription des Bouches-du-Rh\u00f4ne a profit\u00e9 des questions au gouvernement, ce mercredi 21\u00a0janvier, pour interpeller le ministre de l&rsquo;Int\u00e9rieur \u00e0 propos de <a href=\"https:\/\/www.laprovence.com\/article\/faits-divers-justice\/5427487610698614\/affaire-trident-apres-marseille-le-siege-de-loffice-antistupefiants-a-nanterre-perquisitionne\" target=\"_blank\" rel=\"noopener\">l\u2019affaire Trident<\/a>, une op\u00e9ration polici\u00e8re de livraison surveill\u00e9e de coca\u00efne qui avait vir\u00e9 au fiasco <strong>d\u00e9but\u00a02023<\/strong>\u00a0et pour laquelle plusieurs fonctionnaires de l\u2019antenne de l\u2019Office antistup\u00e9fiants (Ofast) de <a href=\"https:\/\/www.laprovence.com\/bouches-du-rhone\/marseille-13055\" target=\"_blank\" rel=\"noopener\">Marseille<\/a> ont d\u00e9j\u00e0 \u00e9t\u00e9 mis en examen depuis avril\u00a02025, dont <a href=\"https:\/\/www.laprovence.com\/article\/faits-divers-justice\/38469495270860\/operation-trident-la-chef-de-lantenne-de-loffice-anti-stups-de-marseille-mise-en-examen\" target=\"_blank\" rel=\"noopener\">la cheffe et son adjoint<\/a>.<\/p>\n<p>\u00ab\u00a0Y a-t-il eu 387\u00a0kilos de coca\u00efne achet\u00e9s par l\u2019\u00c9tat\u00a0?\u00a0\u00bb, demande Delogu<\/p>\n<p><a href=\"https:\/\/www.laprovence.com\/article\/elections\/25374352922679\/municipales-2026-a-marseille-sebastien-delogu-lfi-ou-le-rapport-de-force-comme-programme\" target=\"_blank\" rel=\"noopener\">La t\u00eate de liste insoumise<\/a> pour les prochaines <a href=\"https:\/\/www.laprovence.com\/elections\/municipales\" target=\"_blank\" rel=\"noopener\">\u00e9lections municipales<\/a> \u00e0 Marseille interroge (voir extrait ci-dessous)\u00a0: \u00ab\u00a0Y a-t-il eu, oui ou non, 387\u00a0kilos de coca\u00efne achet\u00e9s par l\u2019\u00c9tat puis revendus \u00e0 l\u2019insu des magistrats suite \u00e0 l\u2019\u00e9chec d\u2019une op\u00e9ration\u00a0? Et est-il vrai qu\u2019une partie de l\u2019argent de la vente aurait \u00e9t\u00e9 cach\u00e9e dans les locaux de la police\u00a0?\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Une livraison surveill\u00e9e avec un certain nombre de difficult\u00e9s\u00a0\u00bb, r\u00e9pond Nu\u00f1ez<\/p>\n<p>\u00ab\u00a0De mani\u00e8re tout \u00e0 fait inhabituelle, je vais vous renvoyer moi une question\u00a0\u00bb, lance alors <strong>Laurent Nu\u00f1ez<\/strong>. \u00ab\u00a0Oui, il y a <a href=\"https:\/\/www.laprovence.com\/article\/faits-divers-justice\/5427487610698614\/affaire-trident-apres-marseille-le-siege-de-loffice-antistupefiants-a-nanterre-perquisitionne\" target=\"_blank\" rel=\"noopener\">l\u2019affaire Trident<\/a> pour laquelle l\u2019inspection g\u00e9n\u00e9rale de la police nationale a \u00e9t\u00e9 saisie. Il y a une enqu\u00eate en cours sur une livraison surveill\u00e9e sur laquelle il y a eu un certain nombre de difficult\u00e9s [\u2026]. Est-ce que pour autant \u00e7a suffit \u00e0 jeter l\u2019opprobre sur l\u2019ensemble des fonctionnaires de police qui luttent contre les trafics\u00a0? Alors, monsieur le d\u00e9put\u00e9, je vous pose une question [\u2026]\u00a0: est-ce que vous soutenez les policiers quand ils luttent contre les trafics de stup&rsquo;, et est-ce que vous condamnez fermement, sans ambigu\u00eft\u00e9, le trafic de stup\u00e9fiants, partout sur le territoire national et notamment \u00e0 <a href=\"https:\/\/www.laprovence.com\/bouches-du-rhone\/marseille-13055\" target=\"_blank\" rel=\"noopener\">Marseille<\/a>?\u00a0\u00bb<\/p>\n<p>Si S\u00e9bastien Delogu ne r\u00e9pond pas directement au ministre de l&rsquo;Int\u00e9rieur, <strong>il s\u2019exclame<\/strong> dans la foul\u00e9e\u00a0: \u00ab\u00a0Quand la presse d\u2019extr\u00eame droite, Bolloris\u00e9e, m\u2019attaque et m\u2019accuse, vous, vous faites le relais de la presse. Par contre, d\u00e8s qu\u2019il s\u2019agit de reprendre l\u2019excellente investigation de <a href=\"https:\/\/www.mediapart.fr\/\" target=\"_blank\" rel=\"noopener\">Mediapart<\/a> sur l\u2019op\u00e9ration Trident, vous n\u2019avez plus de r\u00e9seau\u2026 Je vous sens mal \u00e0 l\u2019aise, monsieur le ministre de l&rsquo;Int\u00e9rieur. Tr\u00e8s mal \u00e0 l\u2019aise avec cette pr\u00e9tendue op\u00e9ration antidrogue men\u00e9e entre la Colombie et Marseille en\u00a02023. Cette pr\u00e9tendue livraison surveill\u00e9e de coca\u00efne pour permettre l\u2019interpellation d\u2019un trafiquant majeur de notre pays. Et tout cela pour quel r\u00e9sultat\u00a0? Aucune des cibles principales arr\u00eat\u00e9es.\u00a0\u00bb<\/p>\n<p>Un peu plus loin dans son intervention, il ajoute\u00a0: \u00ab\u00a0C\u2019est vous qui \u00eates contre Marseille et \u00eates un anti-police en laissant crever la police judiciaire marseillaise.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Oui, je suis tr\u00e8s mal \u00e0 l\u2019aise quand j\u2019entends un d\u00e9put\u00e9 de la Nation qui, \u00e0 partir d\u2019une affaire trait\u00e9e de mani\u00e8re exemplaire [\u2026], jette le discr\u00e9dit sur les fonctionnaires de la police nationale\u00a0\u00bb, conclut <strong>Laurent Nu\u00f1ez<\/strong>.<\/p>\n<p>\u00c0 ce jour, l\u2019Inspection g\u00e9n\u00e9rale de la Police nationale continue d\u2019enqu\u00eater sur les raisons de <strong>cet \u00e9chec spectaculaire<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"Passe d\u2019armes entre S\u00e9bastien Delogu et Laurent Nu\u00f1ez \u00e0 l\u2019Assembl\u00e9e nationale. Le d\u00e9put\u00e9 LFI de la 7\u1d49 circonscription&hellip;\n","protected":false},"author":2,"featured_media":680089,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2814],"tags":[5734,10983,1111,11,77780,17418,1777,674,274,1011,27,8639,469,884,12,52758,1072,882,25],"class_list":{"0":"post-680088","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-marseille","8":"tag-5734","9":"tag-accuse","10":"tag-actu","11":"tag-actualites","12":"tag-crever","13":"tag-delogu","14":"tag-eu","15":"tag-europe","16":"tag-faits-divers-justice","17":"tag-fr","18":"tag-france","19":"tag-judiciaire","20":"tag-laisser","21":"tag-marseille","22":"tag-news","23":"tag-nunez","24":"tag-police","25":"tag-provence-alpes-cote-dazur","26":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/115935636596930212","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/680088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=680088"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/680088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/680089"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=680088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=680088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=680088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}