{"id":685751,"date":"2026-01-24T09:54:19","date_gmt":"2026-01-24T09:54:19","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/685751\/"},"modified":"2026-01-24T09:54:19","modified_gmt":"2026-01-24T09:54:19","slug":"guerre-en-ukraine-les-questions-territoriales-au-menu-des-pourparlers-de-paix-dabou-dabi","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/685751\/","title":{"rendered":"Guerre en Ukraine : les questions territoriales au menu des pourparlers de paix d&rsquo;Abou Dabi"},"content":{"rendered":"<p>\n  Par&amp;nbsp<b>Euronews<\/b>&amp;nbspavec&amp;nbsp<b>AP<\/b>\n<\/p>\n<p>\n         Publi\u00e9 le<br \/>\n            24\/01\/2026 &#8211; 10:29 UTC+1\n            <\/p>\n<p>Le pr\u00e9sident ukrainien Volodymyr Zelensky a d\u00e9clar\u00e9 que les pourparlers tripartites \u00e0 Abou Dabi entre la Russie, les \u00c9tats-Unis et l&rsquo;Ukraine se concentreront fortement sur l&rsquo;avenir de la r\u00e9gion orientale du Donbass, alors que les efforts se poursuivent pour mettre fin \u00e0 l&rsquo;invasion totale de la Russie qui dure depuis pr\u00e8s de quatre ans.<\/p>\n<p>Les discussions, qui ont d\u00e9but\u00e9 vendredi et doivent se poursuivre samedi, ont \u00e9t\u00e9 qualifi\u00e9es de productives par la Maison Blanche. Le minist\u00e8re des Affaires \u00e9trang\u00e8res des \u00c9mirats arabes unis a quant \u00e0 lui d\u00e9clar\u00e9 qu&rsquo;elles s&rsquo;inscrivaient dans le cadre des efforts visant \u00e0 \u00ab\u00a0promouvoir le dialogue et \u00e0 identifier des solutions politiques \u00e0 la crise\u00a0\u00bb.<\/p>\n<p>Selon M. Zelensky, \u00ab\u00a0les repr\u00e9sentants ukrainiens me font un compte rendu presque toutes les heures &#8211; c&rsquo;est important car il n&rsquo;y a pas eu de telles r\u00e9unions trilat\u00e9rales depuis longtemps\u00a0\u00bb, a-t-il d\u00e9clar\u00e9 dans une vid\u00e9o publi\u00e9e sur les m\u00e9dias sociaux, ajoutant : \u00ab\u00a0\u00c0 l&rsquo;heure qu&rsquo;il est, ils auraient d\u00e9j\u00e0 d\u00fb se rendre compte de l&rsquo;importance de l&rsquo;Ukraine dans le processus de paix (&#8230;). L&rsquo;essentiel est que la Russie soit pr\u00eate \u00e0 mettre fin \u00e0 cette guerre, celle qu&rsquo;elle a elle-m\u00eame d\u00e9clench\u00e9e (&#8230;). Quant au contenu des discussions d&rsquo;aujourd&rsquo;hui, il est encore trop t\u00f4t pour tirer des conclusions\u00a0\u00bb.<\/p>\n<p>Vendredi, pour la premi\u00e8re fois, des repr\u00e9sentants de l&rsquo;administration Trump se sont entretenus en m\u00eame temps avec des n\u00e9gociateurs ukrainiens et russes. Bien que des d\u00e9fis majeurs subsistent et que l&rsquo;issue soit incertaine, certains observateurs consid\u00e8rent que la r\u00e9union a permis de progresser vers un accord.<\/p>\n<p>Le Kremlin veut r\u00e9soudre les questions territoriales<\/p>\n<p>Moscou a fourni peu de d\u00e9tails sur la r\u00e9union, la qualifiant seulement de \u00ab\u00a0groupe de travail sur les questions de s\u00e9curit\u00e9\u00a0\u00bb.<\/p>\n<p>Le porte-parole du Kremlin, Dmitri Peskov, a d\u00e9clar\u00e9 que le retrait des troupes ukrainiennes de l&rsquo;est du Donbass restait une \u00ab\u00a0condition importante\u00a0\u00bb pour la Russie, ajoutant que d&rsquo;autres \u00ab\u00a0nuances\u00a0\u00bb \u00e9taient \u00e9galement discut\u00e9es, sans donner plus de d\u00e9tails.<\/p>\n<p>Le conseiller en politique \u00e9trang\u00e8re de M. Poutine, Iouri Oushakov, qui a particip\u00e9 aux discussions avec M. Witkoff et M. Kushner, a d\u00e9clar\u00e9 qu'\u00a0\u00bbil a \u00e9t\u00e9 r\u00e9affirm\u00e9 que l&rsquo;on ne peut s&rsquo;attendre \u00e0 un r\u00e8glement \u00e0 long terme sans r\u00e9soudre la question territoriale\u00a0\u00bb. Il a qualifi\u00e9 les discussions avec les \u00c9tats-Unis de \u00ab\u00a0franches, constructives\u00a0\u00bb et \u00ab\u00a0fructueuses\u00a0\u00bb.<\/p>\n<p>L&rsquo;agence de presse russe Tass a indiqu\u00e9 que l&rsquo;ordre du jour comprenait les zones tampons possibles et les m\u00e9canismes de contr\u00f4le.<\/p>\n<p>Qui participe aux discussions d&rsquo;Abou Dhabi ?<\/p>\n<p>Le porte-parole du Kremlin, Dmitri Peskov, a d\u00e9clar\u00e9 que la d\u00e9l\u00e9gation russe, dirig\u00e9e par l&rsquo;amiral Igor Kostlioukov, \u00e9tait compos\u00e9e de responsables militaires. Il a ajout\u00e9 que l&rsquo;envoy\u00e9 de Poutine, Kirill Dmitriev, rencontrerait s\u00e9par\u00e9ment M. Witkoff pour discuter de questions \u00e9conomiques.<\/p>\n<p>Washington a confirm\u00e9 que Steve Witkoff et Jared Kushner participeraient aux pourparlers d&rsquo;Abou Dhabi aux c\u00f4t\u00e9s du secr\u00e9taire d&rsquo;\u00c9tat \u00e0 l&rsquo;arm\u00e9e, Dan Driscoll, et du plus haut commandant militaire de l&rsquo;OTAN, le g\u00e9n\u00e9ral Alexus Grynkewich de l&rsquo;arm\u00e9e de l&rsquo;air am\u00e9ricaine.<\/p>\n<p>L&rsquo;Ukraine est repr\u00e9sent\u00e9e par Rustem Umerov, chef du conseil national de s\u00e9curit\u00e9 et de d\u00e9fense, Andrii Hnatov, chef de l&rsquo;\u00e9tat-major g\u00e9n\u00e9ral, et Kyrylo Boudanov, chef du bureau pr\u00e9sidentiel.<\/p>\n<p>La veille<\/p>\n<p>Jeudi, les \u00e9missaires du pr\u00e9sident am\u00e9ricain Donald Trump, Steve Witkoff et Jared Kushner, ont \u00e9t\u00e9 re\u00e7us \u00e0 Moscou par le pr\u00e9sident russe Vladimir Poutine et ont discut\u00e9 d&rsquo;un accord sur l&rsquo;Ukraine lors de discussions qui se sont poursuivies jusqu&rsquo;au d\u00e9but de la matin\u00e9e de vendredi et au cours desquelles le Kremlin a d\u00e9clar\u00e9 que tout accord de paix exigerait que Kyiv retire ses forces des territoires de l&rsquo;est que la Russie a ill\u00e9galement annex\u00e9s mais qu&rsquo;elle ne contr\u00f4le pas enti\u00e8rement.<\/p>\n<p>Simultan\u00e9ment, jeudi, M. Zelensky a d\u00e9clar\u00e9, \u00e0 la suite d&rsquo;une rencontre avec M. Trump \u00e0 Davos, que la question des terres actuellement occup\u00e9es n&rsquo;\u00e9tait pas encore r\u00e9solue, mais que les propositions de paix \u00e9taient \u00ab\u00a0presque pr\u00eates\u00a0\u00bb.<\/p>\n<p>M. Zelensky a \u00e9galement d\u00e9clar\u00e9 qu&rsquo;il restait ouvert \u00e0 la cr\u00e9ation d&rsquo;une zone de libre-\u00e9change dans l&rsquo;est de l&rsquo;Ukraine sous le contr\u00f4le de Kiev, ajoutant qu&rsquo;il avait \u00e9voqu\u00e9 cette id\u00e9e avec M. Trump. \u00ab\u00a0Je pense que ce sera positif pour nos affaires\u00a0\u00bb, a-t-il d\u00e9clar\u00e9 aux journalistes.<\/p>\n<p>Video editor<strong> \u2022 Lucy Davalou<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Par&amp;nbspEuronews&amp;nbspavec&amp;nbspAP Publi\u00e9 le 24\/01\/2026 &#8211; 10:29 UTC+1 Le pr\u00e9sident ukrainien Volodymyr Zelensky a d\u00e9clar\u00e9 que les pourparlers tripartites&hellip;\n","protected":false},"author":2,"featured_media":685752,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1591],"tags":[11,1887,2025,12,20354,33040,1885,1886,132],"class_list":{"0":"post-685751","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-russie","8":"tag-actualites","9":"tag-federation-de-russie","10":"tag-invasion-de-la-russie-en-ukraine","11":"tag-news","12":"tag-pourparlers","13":"tag-processus-de-paix","14":"tag-russia","15":"tag-russian-federation","16":"tag-russie"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/115949473828036996","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/685751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=685751"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/685751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/685752"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=685751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=685751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=685751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}