{"id":722714,"date":"2026-02-09T16:48:10","date_gmt":"2026-02-09T16:48:10","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/722714\/"},"modified":"2026-02-09T16:48:10","modified_gmt":"2026-02-09T16:48:10","slug":"cyclisme-tour-doman-mauro-schmid-jai-eu-beaucoup-de-chance-deviter-deux-chutes","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/722714\/","title":{"rendered":"Cyclisme. Tour d&rsquo;Oman &#8211; Mauro Schmid : \u00abJ\u2019ai eu beaucoup de chance d\u2019\u00e9viter deux chutes\u00bb"},"content":{"rendered":"<p><strong>Mauro Schmid<\/strong> a frapp\u00e9 un grand coup sur les pentes d\u2019Eastern Mountain. Vainqueur au sommet de la 3e \u00e9tape du <a href=\"https:\/\/www.cyclismactu.net\/..\/news-tour-d-oman-route-mauro-schmid-remporte-3e-etape-valentin-paret-peintre-malchanceux-91955.html\" target=\"_blank\" rel=\"nofollow noopener\"><strong>Tour d\u2019Oman<\/strong><\/a> ce lundi, le champion de Suisse a domin\u00e9 l\u2019Italien <strong>Christian Scaroni<\/strong> au terme d\u2019un mano a mano intense dans les derniers m\u00e8tres. D\u00e9j\u00e0 victorieux vendredi sur la <strong><a href=\"https:\/\/www.cyclismactu.net\/..\/news-muscat-classic-route-mauro-schmid-vainqueur-de-muscat-classic-apres-un-final-anime-91909.html\" target=\"_blank\" rel=\"nofollow noopener\">Muscat Classic<\/a><\/strong>, le coureur de la<strong> Jayco AlUla <\/strong>encha\u00eene et s\u2019empare du maillot de leader, profitant aussi du travail pr\u00e9cieux de son co\u00e9quipier <strong>Paul Double<\/strong> dans l\u2019ascension finale. Une d\u00e9monstration de force qui le place en t\u00eate du classement g\u00e9n\u00e9ral.<\/p>\n<p>Vid\u00e9o &#8211; Mauro Schmid, d\u00e9j\u00e0 vainqueur de la Muscat Classic vendredi Lire la suite de l&rsquo;article&#13;<\/p>\n<p>\u00a0<\/p>\n<p>&#13;<\/p>\n<p>\u00ab\u00a0Cette victoire est pour l\u2019\u00e9quipe ; sans l\u2019aide de mes co\u00e9quipiers, je n\u2019aurais pas pu gagner\u00a0\u00bb, a d\u00e9clar\u00e9 <strong>Schmid <\/strong>\u00e0 l&rsquo;arriv\u00e9e.\u00a0\u00ab\u00a0La course a \u00e9t\u00e9 bien plus difficile que je ne le pensais, avec une \u00e9chapp\u00e9e forte et bien organis\u00e9e. Le travail de l\u2019\u00e9quipe a \u00e9t\u00e9 crucial et ils m\u2019ont tr\u00e8s bien prot\u00e9g\u00e9 dans la derni\u00e8re partie de la course. J\u2019ai aussi eu beaucoup de chance d\u2019\u00e9viter deux chutes dans le final, et puis dans la derni\u00e8re mont\u00e9e, Paul a \u00e9t\u00e9 superbe.\u00a0\u00bb<\/p>\n<p>Tour d&rsquo;Oman &#8211; Classement de la 3\u00e8 \u00e9tape Tour d&rsquo;Oman &#8211; Classement g\u00e9n\u00e9ral provisoire apr\u00e8s la 3\u00e8 \u00e9tape<\/p>\n","protected":false},"excerpt":{"rendered":"Mauro Schmid a frapp\u00e9 un grand coup sur les pentes d\u2019Eastern Mountain. Vainqueur au sommet de la 3e&hellip;\n","protected":false},"author":2,"featured_media":722715,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1586],"tags":[11,207,1777,674,1779,1011,27,12,25,209,3318,1778,364,208],"class_list":{"0":"post-722714","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europe","8":"tag-actualites","9":"tag-cyclisme","10":"tag-eu","11":"tag-europe","12":"tag-european-union","13":"tag-fr","14":"tag-france","15":"tag-news","16":"tag-republique-francaise","17":"tag-route","18":"tag-tour-d","19":"tag-ue","20":"tag-union-europeenne","21":"tag-velo"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116041699114740755","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/722714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=722714"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/722714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/722715"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=722714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=722714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=722714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}