{"id":736735,"date":"2026-02-15T17:54:11","date_gmt":"2026-02-15T17:54:11","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/736735\/"},"modified":"2026-02-15T17:54:11","modified_gmt":"2026-02-15T17:54:11","slug":"un-militaire-grievement-blesse-un-sdf-retrouve-mort-karl-olive-les-infos-du-week-end-en-ile-de-france","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/736735\/","title":{"rendered":"Un militaire gri\u00e8vement bless\u00e9, un SDF retrouv\u00e9 mort, Karl Olive &#8230; Les infos du week-end en \u00cele-de-France"},"content":{"rendered":"<p>                    Par<br \/>\n        <strong><br \/>\n            <a href=\"https:\/\/actu.fr\/auteur\/antoine-grotteria02\" title=\"Consulter tous les articles de Antoine Grotteria\" rel=\"nofollow noopener\" target=\"_blank\">Antoine Grotteria<\/a><br \/>\n                    <\/strong><\/p>\n<p>        Publi\u00e9 le<\/p>\n<p>            15 f\u00e9vr. 2026 \u00e0 18h08        <\/p>\n<p>Une soir\u00e9e qui d\u00e9g\u00e9n\u00e8re et un <strong>soldat<\/strong> avec un <strong>pronostic vital engag\u00e9<\/strong>. Dans la nuit du samedi 14 au dimanche 15 f\u00e9vrier, un militaire d\u00e9tach\u00e9 en garde \u00e0 l\u2019h\u00f4pital Percy de <a href=\"https:\/\/actu.fr\/ile-de-france\/clamart_92023\" rel=\"nofollow noopener\" target=\"_blank\">Clamart<\/a> (<a href=\"https:\/\/actu.fr\/ile-de-france\/hauts-de-seine_92\" rel=\"nofollow noopener\" target=\"_blank\">Hauts-de-Seine<\/a>) a \u00e9t\u00e9 gri\u00e8vement bless\u00e9 par balles. Il est entre la vie et la mort. L\u2019un de ses camarades, suspect\u00e9 d\u2019\u00eatre impliqu\u00e9, a \u00e9t\u00e9 plac\u00e9 en garde \u00e0 vue.\u00a0<\/p>\n<p class=\" wall-content\">Voici les principales informations \u00e0 retenir de <strong>ces samedi 14 et dimanche 15 f\u00e9vrier<\/strong> 2026 dans votre r\u00e9gion.<\/p>\n<p class=\" wall-content\"><strong>Les infos marquantes du week-end \u00e0 Paris et en \u00cele-de-France<\/strong><\/p>\n<p class=\" wall-content\"><strong>Hauts-de-Seine. <\/strong><a title=\"Lire l&#039;article\" href=\"https:\/\/actu.fr\/ile-de-france\/clamart_92023\/un-militaire-entre-la-vie-et-la-mort-apres-s-etre-fait-tire-dessus-par-un-camarade-dans-un-hopital-de-clamart_63844478.html\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Un militaire entre la vie et la mort apr\u00e8s s\u2019\u00eatre fait tirer dessus par un camarade dans un h\u00f4pital de Clamart<\/strong><\/a><br \/>L\u2019\u00c9tat-major a annonc\u00e9 qu\u2019un militaire avait \u00e9t\u00e9 gri\u00e8vement bless\u00e9 par balle \u00e0 l\u2019h\u00f4pital Percy de Clamart. Soup\u00e7onn\u00e9 d\u2019avoir tir\u00e9, un de ses camarades a \u00e9t\u00e9 plac\u00e9 en garde \u00e0 vue.<\/p>\n<p class=\" wall-content\"><strong>Paris. <\/strong><a title=\"Lire l&#039;article\" href=\"https:\/\/actu.fr\/ile-de-france\/paris_75056\/paris-un-homme-retrouve-mort-pres-de-la-porte-de-la-villette-la-piste-du-meurtre-privilegiee_63844373.html\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Paris : un homme retrouv\u00e9 mort pr\u00e8s de la porte de la Villette, la piste du meurtre privil\u00e9gi\u00e9e<\/strong><\/a><br \/>Un homme est d\u00e9c\u00e9d\u00e9, samedi 14 f\u00e9vrier 2026, sur la place Auguste Baron, dans le 19e arrondissement de Paris. Le parquet a ouvert une enqu\u00eate pour homicide volontaire.<\/p>\n<p class=\" wall-content\"><strong>Yvelines. <\/strong><a title=\"Lire l&#039;article\" href=\"https:\/\/actu.fr\/ile-de-france\/poissy_78498\/une-campagne-nest-pas-une-guerre-karl-olive-vise-par-des-tirs-de-mortier-cinq-blesses-legers-a-poissy_63843425.html\" rel=\"nofollow noopener\" target=\"_blank\"><strong>\u00ab Une campagne n\u2019est pas une guerre \u00bb : Karl Olive vis\u00e9 par des tirs de mortier, cinq bless\u00e9s l\u00e9gers \u00e0 Poissy<\/strong><\/a><br \/>Le d\u00e9put\u00e9 et candidat aux municipales Karl Olive a \u00e9t\u00e9 vis\u00e9 par des tirs de mortiers alors qu\u2019il organisait un nouveau caf\u00e9-quartier \u00e0 Poissy (Yvelines), ce samedi 14\u00a0f\u00e9vrier 2026.<\/p>\n<p class=\" wall-content\"><strong>Val-de-Marne. <\/strong><a title=\"Lire l&#039;article\" href=\"https:\/\/actu.fr\/ile-de-france\/chevilly-larue_94021\/du-soutien-pas-de-stigmatisation-a-chevilly-les-sourires-d-hussein-cachent-une-maladie-genetique-rare_63839523.html\" rel=\"nofollow noopener\" target=\"_blank\"><strong>\u00ab\u00a0Du soutien, pas de stigmatisation\u00a0\u00bb : \u00e0 Chevilly, les sourires d\u2019Hussein cachent une maladie g\u00e9n\u00e9tique rare<\/strong><\/a><br \/>\u00c0 l\u2019occasion de la Journ\u00e9e internationale du syndrome d\u2019Angelman, A\u00efcha t\u00e9moigne du quotidien de son fils Hussein, n\u00e9 avec cette maladie g\u00e9n\u00e9tique rare et m\u00e9connue.<\/p>\n<p class=\" wall-content\"><strong>Seine-Saint-Denis. <\/strong><a title=\"Lire l&#039;article\" href=\"https:\/\/actu.fr\/ile-de-france\/saint-denis_93066\/municipales-2026-les-programmes-des-candidats-pour-le-logement-a-saint-denis_63833962.html\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Municipales 2026 : les programmes des candidats pour le logement \u00e0 Saint-Denis<\/strong><\/a><br \/>S\u00c9RIE. \u00c9pisode 1 : d\u00e9couvrez les propositions des candidats aux \u00e9lections municipales du 15 et 22 mars 2026 \u00e0 Saint-Denis en mati\u00e8re de logement.<\/p>\n<p>Votre r\u00e9gion, votre actu !<\/p>\n<p>Recevez chaque jour les infos qui comptent pour vous.<\/p>\n<p>\t<a href=\"https:\/\/actu.fr\/newsletter\" class=\"ac-btn ac-btn--corner ac-btn--medium ac-btn--blue800\" rel=\"nofollow noopener\" target=\"_blank\">S&rsquo;incrire<\/a><\/p>\n<p class=\" wall-content\"><strong>Seine-et-Marne. <\/strong><a title=\"Lire l&#039;article\" href=\"https:\/\/actu.fr\/ile-de-france\/provins_77379\/seine-et-marne-vols-reguliers-transport-dorganes-football-pilote-davion-elle-a-debute-par-un-bac-s_63841743.html\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Seine-et-Marne. Vols r\u00e9guliers, transport d\u2019organes, football\u2026 pilote d\u2019avion, elle a d\u00e9but\u00e9 \u00ab\u00a0par un bac S\u00a0\u00bb<\/strong><\/a><br \/>Pauline Ahang, copilote pour la compagnie Am\u00e9lia, est venue \u00e9changer et partager son exp\u00e9rience avec les \u00e9l\u00e8ves du coll\u00e8ge Marie-Curie de Provins.<\/p>\n<p class=\" wall-content\"><strong>Essonne. <\/strong><a title=\"Lire l&#039;article\" href=\"https:\/\/actu.fr\/ile-de-france\/sainte-genevieve-des-bois_91549\/il-y-a-20-ans-ilan-halimi-etait-retrouve-agonisant-en-essonne-apres-avoir-ete-enleve-sequestre-et-torture_63835444.html\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Il y a 20 ans, Ilan Halimi \u00e9tait retrouv\u00e9 agonisant en Essonne apr\u00e8s avoir \u00e9t\u00e9 enlev\u00e9, s\u00e9questr\u00e9 et tortur\u00e9<\/strong><\/a><br \/>Le 13 f\u00e9vrier 2006, Ilan Halimi \u00e9tait retrouv\u00e9 agonisant le long des voies du RER C \u00e0 Sainte-Genevi\u00e8ve-des-Bois, apr\u00e8s avoir \u00e9t\u00e9 s\u00e9questr\u00e9 et tortur\u00e9 durant plus de trois semaines.<\/p>\n<p class=\" wall-content\"><strong>Val-d\u2019Oise. <\/strong><a title=\"Lire l&#039;article\" href=\"https:\/\/actu.fr\/ile-de-france\/le-plessis-bouchard_95491\/val-doise-feux-eteints-et-forte-odeur-dans-la-voiture-lautomobiliste-termine-en-garde-a-vue_63843632.html\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Val-d\u2019Oise : feux \u00e9teints et forte odeur dans la voiture, l\u2019automobiliste termine en garde \u00e0 vue<\/strong><\/a><br \/>Samedi 31 janvier 2026, un automobiliste a \u00e9t\u00e9 contr\u00f4l\u00e9 par les policiers au Plessis-Bouchard. La d\u00e9couverte de cargaison l\u2019a conduit en garde \u00e0 vue.\u00a0<\/p>\n<p class=\" wall-content\"><strong>Suivez-nous pour en savoir plus !<\/strong><\/p>\n<p class=\" wall-content\">Paris : retrouvez actu Paris sur Facebook et Twitter ;<br \/>Seine-et-Marne : retrouvez\u00a0La R\u00e9publique de Seine-et-Marne\u00a0(sud) sur\u00a0Facebook\u00a0et\u00a0Twitter\u00a0;\u00a0La Marne\u00a0(nord) sur\u00a0Facebook\u00a0et\u00a0Twitter\u00a0; et\u00a0Le Pays Briard\u00a0sur\u00a0Facebook\u00a0et\u00a0Twitter\u00a0;<br \/>Yvelines : retrouvez\u00a078actu\u00a0sur\u00a0Facebook\u00a0et\u00a0Twitter\u00a0;<br \/>Essonne : retrouvez\u00a0actu Essonne\u00a0sur\u00a0Facebook\u00a0et\u00a0Twitter\u00a0;<br \/>Hauts-de-Seine : retrouvez\u00a0actu Hauts-de-Seine\u00a0sur\u00a0Facebook\u00a0et\u00a0Twitter\u00a0;<br \/>Seine-Saint-Denis : retrouvez\u00a0actu Seine-Saint-Denis\u00a0sur\u00a0Facebook\u00a0et\u00a0Twitter\u00a0;<br \/>Val-de-Marne : retrouvez\u00a0actu Val-de-Marne\u00a0sur\u00a0Facebook\u00a0et\u00a0Twitter\u00a0;<br \/>Val-d\u2019Oise : retrouvez\u00a0La Gazette du Val-d\u2019Oise\u00a0sur\u00a0Facebook.<\/p>\n<p class=\" wall-content\">Personnalisez votre actualit\u00e9 en ajoutant vos villes et m\u00e9dias en favori avec <a href=\"https:\/\/moncompte.actu.fr\" title=\"D\u00e9couvez Mon Actu\" rel=\"nofollow noopener\" data-trk=\"{&quot;cta&quot;:{&quot;action&quot;:&quot;https:\\\/\\\/moncompte.actu.fr&quot;,&quot;category&quot;:&quot;mon compte&quot;,&quot;from&quot;:&quot;article footer&quot;,&quot;name&quot;:&quot;Mon actu&quot;,&quot;type&quot;:&quot;cta&quot;}}\" target=\"_blank\">Mon Actu<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Par Antoine Grotteria Publi\u00e9 le 15 f\u00e9vr. 2026 \u00e0 18h08 Une soir\u00e9e qui d\u00e9g\u00e9n\u00e8re et un soldat avec&hellip;\n","protected":false},"author":2,"featured_media":736736,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1888],"tags":[1111,1928,11,1927,1813,1777,674,1011,27,1310,12,1926,626,1925,25,3910,104],"class_list":{"0":"post-736735","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-paris","8":"tag-actu","9":"tag-actu-paris","10":"tag-actualites","11":"tag-actualites-paris","12":"tag-armee","13":"tag-eu","14":"tag-europe","15":"tag-fr","16":"tag-france","17":"tag-incendie","18":"tag-news","19":"tag-news-paris","20":"tag-paris","21":"tag-paris-news","22":"tag-republique-francaise","23":"tag-sdf","24":"tag-societe"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116075932465628901","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/736735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=736735"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/736735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/736736"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=736735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=736735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=736735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}