{"id":739470,"date":"2026-02-16T23:43:20","date_gmt":"2026-02-16T23:43:20","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/739470\/"},"modified":"2026-02-16T23:43:20","modified_gmt":"2026-02-16T23:43:20","slug":"lassociation-vrac-de-saint-jacques-de-la-lande-recherche-des-benevoles-pour-leur-permanence-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/739470\/","title":{"rendered":"L\u2019association Vrac, de Saint-Jacques-de-la-Lande, recherche des b\u00e9n\u00e9voles pour leur permanence"},"content":{"rendered":"<p>Nous avons besoin de vos cookies pour vous offrir la meilleure exp\u00e9rience de lecture possible et vous<br \/>\n                proposer des articles personnalis\u00e9s selon votre lieu de vie et des publicit\u00e9s selon vos centres<br \/>\n                d&rsquo;int\u00e9r\u00eat, avec une s\u00e9curit\u00e9 maximale du site.<\/p>\n<p>Ils contribuent au mod\u00e8le \u00e9conomique de notre entreprise et permettent aux journalistes de notre<br \/>\n                r\u00e9daction d\u00e9ploy\u00e9s \u00e0 travers la r\u00e9gion, de continuer \u00e0 concevoir une information fiable et de qualit\u00e9,<br \/>\n                toujours proche de vous.<\/p>\n","protected":false},"excerpt":{"rendered":"Nous avons besoin de vos cookies pour vous offrir la meilleure exp\u00e9rience de lecture possible et vous proposer&hellip;\n","protected":false},"author":2,"featured_media":739137,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2821],"tags":[1111,11,4077,15089,829,1777,674,1011,27,12,20993,959,584,25,18461,3728,82641],"class_list":{"0":"post-739470","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-rennes","8":"tag-actu","9":"tag-actualites","10":"tag-association","11":"tag-benevoles","12":"tag-bretagne","13":"tag-eu","14":"tag-europe","15":"tag-fr","16":"tag-france","17":"tag-news","18":"tag-permanence","19":"tag-recherche","20":"tag-rennes","21":"tag-republique-francaise","22":"tag-saint-jacques-de-la-lande","23":"tag-saint-malo","24":"tag-vrac"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116082967128886922","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/739470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=739470"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/739470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/739137"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=739470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=739470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=739470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}