{"id":759734,"date":"2026-02-25T22:23:18","date_gmt":"2026-02-25T22:23:18","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/759734\/"},"modified":"2026-02-25T22:23:18","modified_gmt":"2026-02-25T22:23:18","slug":"une-tres-chaude-piste-de-lom-rejoint-la-plus-grosse-agence-de-foot-dans-le-monde","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/759734\/","title":{"rendered":"Une tr\u00e8s chaude piste de l&rsquo;OM rejoint la plus grosse agence de foot dans le monde"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" width=\"620\" height=\"413\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/02\/Lucas-Da-Cunha-620x413.jpg\" alt=\"\" class=\"wp-image-395736\"  \/>Un transfert pour Lucas Da Cunha, qui n\u2019est pas en club.<\/p>\n<p>L\u2019<a href=\"https:\/\/sportune.20minutes.fr\/olympique-de-marseille-om\" rel=\"nofollow noopener\" target=\"_blank\">Olympique de Marseille<\/a> avait coch\u00e9 son nom lors du mercato hivernal. Lucas Da Cunha, milieu de terrain de 24 ans et capitaine de <a href=\"https:\/\/sportune.20minutes.fr\/come-1907\" rel=\"nofollow noopener\" target=\"_blank\">C\u00f4me 1907<\/a> en championnat de <a href=\"https:\/\/sportune.20minutes.fr\/serie-a\" rel=\"nofollow noopener\" target=\"_blank\">Serie A<\/a>, n\u2019a finalement pas quitt\u00e9 l\u2019Italie \u2014 son \u00e9quipe ayant refus\u00e9 de c\u00e9der celui qui est sous contrat jusqu\u2019en 2029 \u2014 mais le joueur form\u00e9 au <a href=\"https:\/\/sportune.20minutes.fr\/stade-rennais-srfc\" rel=\"nofollow noopener\" target=\"_blank\">Stade Rennais<\/a> vient de franchir une \u00e9tape notable dans sa carri\u00e8re en s\u2019engageant avec l\u2019agence CAA Base.<\/p>\n<p>Plus du milliard de commissions<\/p>\n<p>Selon le classement Forbes 2025 des agences sportives, CAA est la plus puissante du monde. Bas\u00e9e \u00e0 Los Angeles, elle g\u00e8re plus de 3 000 clients, supervise 15,9 milliards de dollars de contrats joueurs actifs et 4,59 milliards de dollars de contrats hors terrain. Ses commissions maximales atteignent 1,143 milliard de dollars, en hausse de 18 % sur trois ans. Parmi ses clients figurent notamment Josh Allen, Shohei Ohtani ou encore Sidney Crosby.<\/p>\n<p>Pass\u00e9 par <a href=\"https:\/\/sportune.20minutes.fr\/clermont-foot\" rel=\"nofollow noopener\" target=\"_blank\">Clermont Foot<\/a>, l\u2019<a href=\"https:\/\/sportune.20minutes.fr\/ogc-nice-ogcn\" rel=\"nofollow noopener\" target=\"_blank\">OGC Nice<\/a> et Lausanne avant de rejoindre l\u2019Italie, Lucas Da Cunha s\u2019est impos\u00e9 comme une pi\u00e8ce centrale de son club, qu\u2019il avait accompagn\u00e9 lors de sa mont\u00e9e en premi\u00e8re division. C\u2019est d\u00e9sormais l\u2019une des agences les plus influentes de la plan\u00e8te football qui g\u00e9rera ses int\u00e9r\u00eats, dans un contexte o\u00f9 son nom devrait continuer \u00e0 circuler sur le march\u00e9 des transferts.<\/p>\n","protected":false},"excerpt":{"rendered":"Un transfert pour Lucas Da Cunha, qui n\u2019est pas en club. L\u2019Olympique de Marseille avait coch\u00e9 son nom&hellip;\n","protected":false},"author":2,"featured_media":759735,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1410],"tags":[63,1011,27,149,60,969],"class_list":{"0":"post-759734","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-football","8":"tag-football","9":"tag-fr","10":"tag-france","11":"tag-om","12":"tag-sports","13":"tag-transfert"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116133613501589842","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/759734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=759734"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/759734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/759735"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=759734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=759734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=759734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}