{"id":761119,"date":"2026-02-26T12:51:14","date_gmt":"2026-02-26T12:51:14","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/761119\/"},"modified":"2026-02-26T12:51:14","modified_gmt":"2026-02-26T12:51:14","slug":"mediawan-est-un-groupe-francais-assure-son-fondateur","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/761119\/","title":{"rendered":"Mediawan est un groupe \u00abfran\u00e7ais\u00bb, assure son fondateur"},"content":{"rendered":"<p>\n    Le rapporteur de la commission, Charles Alloncle, a soutenu plusieurs fois que Mediawan, \u00abpremi\u00e8re soci\u00e9t\u00e9 de production \u00e0 b\u00e9n\u00e9ficier des contrats avec France T\u00e9l\u00e9visions\u00bb, serait majoritairement d\u00e9tenu \u00abpar un fonds d\u2019investissement am\u00e9ricain, KKR\u00bb.<\/p>\n<p class=\"fig-paragraph\">Le fondateur et pr\u00e9sident de Mediawan se d\u00e9fend. Devant la commission d\u2019enqu\u00eate sur l\u2019audiovisuel public, Pierre-Antoine Capton a assur\u00e9 jeudi que son entreprise, l\u2019un des leaders europ\u00e9ens de l&rsquo;audiovisuel derri\u00e8re les succ\u00e8s \u00ab10 pour cent\u00bb ou \u00abMiraculous\u00bb,\u00a0<a href=\"http:\/\/www.lefigaro.fr\/medias\/controle-de-mediawan-par-kkr-niel-pigasse-et-capton-prets-a-se-defendre-devant-la-commission-d-enquete-sur-l-audiovisuel-public-20260206\" target=\"_blank\" data-fig-type=\"NewsFlash\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\">est un groupe \u00abfran\u00e7ais\u00bb<\/a> \u00a0malgr\u00e9 la pr\u00e9sence d&rsquo;un fonds am\u00e9ricain dans son actionnariat. \u00abJ&rsquo;aimerais (&#8230;) qu&rsquo;on ne dise plus dans le cadre de cette commission d&rsquo;enqu\u00eate que Mediawan est un groupe sous contr\u00f4le am\u00e9ricain, ce qui n&rsquo;est pas le cas\u00bb, a voulu mettre au point Pierre-Antoine Capton d\u00e8s le d\u00e9but de son audition devant la commission, qui l&rsquo;auditionne au titre de ses productions pour France T\u00e9l\u00e9visions, comme \u00abC \u00e0 vous\u00bb et \u00abC dans l&rsquo;air\u00bb.<\/p>\n<p class=\"fig-paragraph\">Le d\u00e9put\u00e9 de l&rsquo;UDR, alli\u00e9 du RN, Charles Alloncle, rapporteur de cette commission d&rsquo;enqu\u00eate, a soutenu plusieurs fois que Mediawan, \u00abpremi\u00e8re soci\u00e9t\u00e9 de production \u00e0 b\u00e9n\u00e9ficier des contrats avec France T\u00e9l\u00e9visions\u00bb, serait majoritairement d\u00e9tenu \u00abpar un fonds d&rsquo;investissement am\u00e9ricain, KKR\u00bb.<\/p>\n<p class=\"fig-body-link\">\n            \u00c0 lire aussi<br \/>\n        <a class=\"fig-body-link__link fig-premium-mark\" href=\"http:\/\/www.lefigaro.fr\/medias\/pierre-antoine-capton-patron-de-mediawan-notre-adn-c-est-de-rester-europeen-et-francais-20250620\" target=\"_blank\" data-fig-type=\"Article\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\"><\/p>\n<p>        Pierre-Antoine Capton, patron de Mediawan\u00a0: \u00abNotre ADN, c\u2019est de rester europ\u00e9en et fran\u00e7ais\u00bb<br \/>\n    <\/a>\n<\/p>\n<p>                                            <a class=\"fig-a11y-skip\" href=\"#fig-a11y-skip-main-inarticle\" is=\"fig-a11y-skip\" data-trigger-mode=\"visible-once\"><br \/>\n    Passer la publicit\u00e9<br \/>\n<\/a>            <\/p>\n<p>                                            \u00abMediawan est un groupe fran\u00e7ais au sens juridique, fiscal et op\u00e9rationnel\u00bb<\/p>\n<p class=\"fig-paragraph\">Au nom du \u00absecret des affaires\u00bb, et s&rsquo;agissant d&rsquo;une soci\u00e9t\u00e9 qui n&rsquo;est plus cot\u00e9e en Bourse, Pierre-Antoine Capton n&rsquo;a pas r\u00e9v\u00e9l\u00e9 la r\u00e9partition du capital de son groupe, qui a r\u00e9alis\u00e9 1,5 milliard d&rsquo;euros de chiffre d&rsquo;affaires dans le monde en 2024. Mais il a assur\u00e9 \u00absous serment\u00bb que \u00abKKR n&rsquo;est pas l&rsquo;actionnaire majoritaire de Mediawan\u00bb. \u00abMediawan est un groupe fran\u00e7ais au sens juridique, fiscal et op\u00e9rationnel. Son contr\u00f4le est fran\u00e7ais (&#8230;) Notre si\u00e8ge est \u00e0 Paris, nos \u00e9quipes sont en France, nos d\u00e9cisions strat\u00e9giques sont prises en France, le groupe dans son ensemble est soumis au droit fran\u00e7ais, \u00e0 la fiscalit\u00e9 fran\u00e7aise et aux obligations sociales fran\u00e7aises\u00bb, a \u00e9num\u00e9r\u00e9 Pierre-Antoine Capton, qui a fond\u00e9 le groupe en 2015 avec les hommes d&rsquo;affaires Xavier Niel et Matthieu Pigasse, auditionn\u00e9s jeudi apr\u00e8s-midi.<\/p>\n<p class=\"fig-paragraph\">\u00abNous sommes les contr\u00f4lants de cette soci\u00e9t\u00e9, rien ne peut se faire sans nous. KKR est un actionnaire important qui n&rsquo;a ni le contr\u00f4le, ni la majorit\u00e9\u00bb, a insist\u00e9 Pierre-Antoine Capton. Il a aussi voulu battre en br\u00e8che l&rsquo;id\u00e9e que la sant\u00e9 financi\u00e8re de Mediawan, groupe qui rassemble 80 maisons de production, d\u00e9pend de ses contrats avec France T\u00e9l\u00e9visions. \u00abNotre d\u00e9veloppement ne repose pas sur le service public\u00bb, a-t-il assur\u00e9, pr\u00e9cisant que \u00abFrance T\u00e9l\u00e9visions repr\u00e9sente moins de 5% de l&rsquo;activit\u00e9 consolid\u00e9e de Mediawan\u00bb au niveau mondial, et \u00ab25% en France\u00bb. Mediawan avait rachet\u00e9 en 2017 AB Productions, embl\u00e9matique en France pour ses \u00e9missions de jeunesse, puis a mis un pied \u00e0 Hollywood en acqu\u00e9rant les soci\u00e9t\u00e9s am\u00e9ricaines Plan B, pr\u00e9sid\u00e9e par Brad Pitt, ou\u00a0<a href=\"http:\/\/www.lefigaro.fr\/medias\/la-planete-des-singes-love-is-blind-chief-of-war-en-rachetant-north-road-mediawan-s-ouvre-en-grand-les-portes-de-hollywood-20260130\" target=\"_blank\" data-fig-type=\"Article\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\">The north road company d\u00e9but 2026<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Le rapporteur de la commission, Charles Alloncle, a soutenu plusieurs fois que Mediawan, \u00abpremi\u00e8re soci\u00e9t\u00e9 de production \u00e0&hellip;\n","protected":false},"author":2,"featured_media":761120,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[9646,5137,58,59,1011,27,37278],"class_list":{"0":"post-761119","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-divertissement","8":"tag-audiovisuel","9":"tag-commission-denquete","10":"tag-divertissement","11":"tag-entertainment","12":"tag-fr","13":"tag-france","14":"tag-mediawan"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116137026381849491","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/761119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=761119"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/761119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/761120"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=761119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=761119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=761119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}