{"id":762510,"date":"2026-02-27T02:26:25","date_gmt":"2026-02-27T02:26:25","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/762510\/"},"modified":"2026-02-27T02:26:25","modified_gmt":"2026-02-27T02:26:25","slug":"son-livre-et-la-joie-de-vivre-en-tete-des-ventes-du-royaume-unis-au-canada","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/762510\/","title":{"rendered":"son livre \u00ab\u00a0Et la joie de vivre\u00a0\u00bb en t\u00eate des ventes du Royaume-Unis au Canada"},"content":{"rendered":"<p class=\"article-p mdl\">Les derniers classements ont confirm\u00e9 l\u2019ampleur du ph\u00e9nom\u00e8ne. L\u2019ouvrage Et la joie de vivre de Gis\u00e8le Pelicot (Flammarion)\u00a0est num\u00e9ro un des ventes au Royaume-Uni, en Allemagne, en Norv\u00e8ge, en Hongrie, en Su\u00e8de, au Danemark, en Irlande ainsi qu\u2019au Qu\u00e9bec.\u00a0<\/p>\n<p class=\"article-p mdl\">D\u2019apr\u00e8s la Soci\u00e9t\u00e9 de gestion de la banque de titres de langue fran\u00e7aise, rapport\u00e9es par\u00a0<a class=\"link\" href=\"https:\/\/ici.radio-canada.ca\/arts\/livres\/actualites-litteraires\/actualites-litteraires\/document\/nouvelles\/article\/2232382\/gisele-pelicot-livre-proces-mazan-numero-un-ventes\" target=\"_blank\" rel=\"nofollow noopener\">Radio-Canada<\/a>, il est num\u00e9ro un dans les librairies qu\u00e9b\u00e9coises ind\u00e9pendantes. Au Canada, il occupe la deuxi\u00e8me place des ventes nationales et se classe quatri\u00e8me aux Pays-Bas. Aux \u00c9tats-Unis, il figure \u00e0 la sixi\u00e8me position des meilleures ventes.<\/p>\n<p class=\"article-p mdl\">Avant d&rsquo;\u00eatre un succ\u00e8s \u00e0 l&rsquo;\u00e9tranger, l&rsquo;\u0153uvre a tr\u00e8s vite \u00e9t\u00e9 class\u00e9e best-seller en France.\u00a0<a class=\"link\" href=\"https:\/\/www.rtl.fr\/culture\/medias-people\/info-rtl-et-la-joie-de-vivre-numero-un-du-marche-le-livre-de-gisele-pelicot-s-est-deja-ecoule-a-plus-de-63-000-exemplaires-7900604982\" rel=\"nofollow noopener\" target=\"_blank\">Selon son \u00e9diteur Flammarion, le livre s\u2019est \u00e9coul\u00e9 \u00e0 63.574 exemplaires en une semaine, prenant la premi\u00e8re place du classement des ventes.<\/a>\u00a0Le tirage initial \u00e9tait de 150.000 exemplaires. Ces chiffres, fond\u00e9s sur les donn\u00e9es de l\u2019institut sp\u00e9cialis\u00e9 GfK, traduisent un lancement particuli\u00e8rement solide pour un ouvrage de t\u00e9moignage.<\/p>\n<p class=\"article-p mdl\">\u00ab\u00a0Nous sommes satisfaits. C\u2019est un tr\u00e8s bon chiffre pour le d\u00e9marrage d\u2019un livre de t\u00e9moignage\u00a0\u00bb, a indiqu\u00e9 la maison d\u2019\u00e9dition, qui souligne \u00e9galement les excellents r\u00e9sultats enregistr\u00e9s \u00e0 l\u2019\u00e9tranger.<\/p>\n<p>            Une tourn\u00e9e internationale tr\u00e8s m\u00e9diatis\u00e9e<\/p>\n<p class=\"article-p mdl\">\u00c2g\u00e9e de 73 ans, Gis\u00e8le Pelicot y raconte les viols organis\u00e9s par son ex-mari, Dominique Pelicot, avec des dizaines d\u2019hommes, ainsi que le proc\u00e8s historique d\u2019Avignon. Cette affaire, dite\u00a0<a class=\"link\" href=\"https:\/\/www.rtl.fr\/actu\/debats-societe\/enquete-rtl-l-affaire-pelicot-pourrait-elle-se-reproduire-des-dizaines-d-hommes-ont-repondu-a-notre-fausse-annonce-pour-avoir-un-rapport-sexuel-avec-une-femme-endormie-7900591713\" title=\"ENQU\u00caTE RTL - Pr\u00eats \u00e0 avoir un rapport sexuel avec une femme endormie : un an apr\u00e8s le proc\u00e8s des viols de Mazan, des dizaines d&#039;hommes ont r\u00e9pondu \u00e0 notre fausse annonce\" rel=\"nofollow noopener\" target=\"_blank\">\u00ab\u00a0des viols de Mazan\u00a0\u00bb<\/a>, a fait d\u2019elle une figure internationale.<\/p>\n<blockquote class=\"article-quote\">\n<p class=\"article-quote-text icon icon-quote-v2\">Le probl\u00e8me est universel.<\/p>\n<p>Gis\u00e8le Pelicot<\/p>\n<\/blockquote>\n<p class=\"article-p mdl\">Apr\u00e8s une pr\u00e9sentation \u00e0 Paris, elle a entam\u00e9 une tourn\u00e9e \u00e0 l\u2019\u00e9tranger. Lundi 23 f\u00e9vrier, elle a notamment \u00e9t\u00e9 re\u00e7ue \u00e0 Londres par la reine Camilla, qui s\u2019est dite \u00ab\u00a0choqu\u00e9e\u00a0\u00bb par ce qu\u2019avait subi la Fran\u00e7aise. Son d\u00e9placement doit se poursuivre en Allemagne puis en Espagne d\u00e9but mars, avant l\u2019Italie, le Canada et New York. En France, plusieurs rencontres sont pr\u00e9vues, notamment \u00e0 Aix-en-Provence.<\/p>\n<p>    La r\u00e9daction vous recommande<\/p>\n<p class=\"s-newsletter__title\">\n                L\u2019actualit\u00e9 par la r\u00e9daction de RTL dans votre bo\u00eete mail.\n            <\/p>\n<p class=\"s-newsletter__subtitle\">\n                Gr\u00e2ce \u00e0 votre compte RTL abonnez-vous \u00e0 la newsletter RTL info pour suivre toute l&rsquo;actualit\u00e9 au quotidien\n            <\/p>\n<p>\n                                    Lire la suite\n                                <\/p>\n","protected":false},"excerpt":{"rendered":"Les derniers classements ont confirm\u00e9 l\u2019ampleur du ph\u00e9nom\u00e8ne. L\u2019ouvrage Et la joie de vivre de Gis\u00e8le Pelicot (Flammarion)\u00a0est&hellip;\n","protected":false},"author":2,"featured_media":762511,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1588],"tags":[1111,11,251,1777,674,107,14,1380,12,11218,473,1853,1851,1850,1852],"class_list":{"0":"post-762510","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-royaume-uni","8":"tag-actu","9":"tag-actualites","10":"tag-culture","11":"tag-eu","12":"tag-europe","13":"tag-fil-info","14":"tag-international","15":"tag-livres","16":"tag-news","17":"tag-proces-des-viols-de-mazan","18":"tag-royaume-uni","19":"tag-royaume-uni-de-grande-bretagne-et-dirlande-du-nord","20":"tag-uk","21":"tag-united-kingdom","22":"tag-united-kingdom-of-great-britain-and-northern-ireland"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116140230951184523","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/762510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=762510"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/762510\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/762511"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=762510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=762510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=762510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}