{"id":764562,"date":"2026-02-27T23:35:27","date_gmt":"2026-02-27T23:35:27","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/764562\/"},"modified":"2026-02-27T23:35:27","modified_gmt":"2026-02-27T23:35:27","slug":"a-paris-le-combat-des-parents-pour-faire-entendre-la-voix-de-leurs-enfants-abuses","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/764562\/","title":{"rendered":"\u00e0 Paris, le combat des parents pour faire entendre la voix de leurs enfants abus\u00e9s"},"content":{"rendered":"<p>\n    <strong>ENQU\u00caTE &#8211; <\/strong>Alors que les scandales de violences sexuelles de la part d\u2019animateurs sur des \u00e9l\u00e8ves de maternelle s\u2019accumulent ces derniers mois dans la capitale, les familles doivent faire face \u00e0 de longues proc\u00e9dures, parfois b\u00e2cl\u00e9es.<\/p>\n<p class=\"fig-paragraph\">Les\u00a0<a href=\"http:\/\/www.lefigaro.fr\/actualite-france\/violences-sexuelles-sur-mineurs-apres-la-suspension-de-52-animateurs-periscolaires-la-mairie-de-paris-lance-un-plan-d-actions-20251114\" data-fig-type=\"Article\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\" rel=\"nofollow noopener\" target=\"_blank\">suspensions d\u2019animateurs p\u00e9riscolaires pleuvent<\/a>\u00a0dans les \u00e9coles parisiennes, apr\u00e8s des suspicions de violences sexuelles sur des \u00e9l\u00e8ves de maternelle. Saint-Dominique, Bullourde, \u00c9meriau, Titon\u2026 La liste ne cesse de s\u2019allonger depuis plus de trois mois. Pour faire entendre la voix de leurs enfants, les familles se lancent dans un parcours judiciaire qui s\u2019annonce long et difficile. Car derri\u00e8re l\u2019\u00e9mergence de ces affaires r\u00e9centes, d\u2019autres, plus anciennes, remontent \u00e0 la surface. Et elles sont loin d\u2019avoir trouv\u00e9 leur \u00e9pilogue.<\/p>\n<p class=\"fig-paragraph\">En 2019, des parents d\u2019\u00e9l\u00e8ves de l\u2019\u00e9cole maternelle Paul-Dubois, dans le 3e\u00a0arrondissement de Paris, signalent aupr\u00e8s de la direction, puis de la police, des abus de la part d\u2019un animateur p\u00e9riscolaire. \u00ab\u00a0Bisous partout\u00a0\u00bb, \u00ab\u00a0doigt dans les fesses\u00a0\u00bb, \u00ab\u00a0zizi touch\u00e9\u00a0\u00bb\u2026\u00a0<a href=\"http:\/\/www.lefigaro.fr\/actualite-france\/violences-dans-le-periscolaire-a-paris-la-psychose-des-parents-livres-a-eux-memes-demeure-20260217\" data-fig-type=\"Article\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\" rel=\"nofollow noopener\" target=\"_blank\">Le monde des parents s\u2019\u00e9croule\u00a0<\/a>apr\u00e8s les confessions de leurs enfants. \u00ab\u00a0Mais depuis le d\u00e9but, personne ne nous a \u00e9cout\u00e9s. Quand je l\u2019ai alert\u00e9e, la direction de l\u2019\u00e9cole m\u2019a dit que\u2026<\/p>\n<p class=\"fig-premium-paywall__infos\">\n        Cet article est r\u00e9serv\u00e9 aux abonn\u00e9s.        Il vous reste 92% \u00e0 d\u00e9couvrir.\n    <\/p>\n<p>                <img  data- alt=\"Le Figaro\" class=\"fig-img--complete fig-img\"\/><\/p>\n<p class=\"fig-premium-paywall__title\">Vous avez envie de lire la suite ?<\/p>\n<p class=\"fig-premium-paywall__subtitle\">D\u00e9bloquez tous les articles imm\u00e9diatement.<\/p>\n<p class=\"fig-premium-paywall__connect\">\n                D\u00e9j\u00e0 abonn\u00e9\u00a0?                <a class=\"fig-premium-paywall__connect-link\" href=\"https:\/\/connect.lefigaro.fr\/login?client=horizon_web&amp;type=main&amp;redirect_uri=https%3A%2F%2Fwww.lefigaro.fr%2Factualite-france%2Fperiscolaire-a-paris-le-combat-des-parents-pour-faire-entendre-la-voix-de-leurs-enfants-abuses-20260227\" data-js-gtm=\"{&quot;event&quot;:&quot;customEventGA4&quot;,&quot;eventName&quot;:&quot;click_action&quot;,&quot;feature&quot;:&quot;paywall&quot;,&quot;location&quot;:&quot;paywall&quot;,&quot;button_action&quot;:&quot;connect&quot;,&quot;click_text&quot;:&quot;Connectez-vous&quot;}\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n                    Connectez-vous<br \/>\n                <\/a>\n            <\/p>\n","protected":false},"excerpt":{"rendered":"ENQU\u00caTE &#8211; Alors que les scandales de violences sexuelles de la part d\u2019animateurs sur des \u00e9l\u00e8ves de maternelle&hellip;\n","protected":false},"author":2,"featured_media":764563,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1888],"tags":[1111,1928,11,1927,1122,1777,674,1011,27,12,1926,626,1925,25,799],"class_list":{"0":"post-764562","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-paris","8":"tag-actu","9":"tag-actu-paris","10":"tag-actualites","11":"tag-actualites-paris","12":"tag-ecole","13":"tag-eu","14":"tag-europe","15":"tag-fr","16":"tag-france","17":"tag-news","18":"tag-news-paris","19":"tag-paris","20":"tag-paris-news","21":"tag-republique-francaise","22":"tag-violences-sexuelles"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116145220910276634","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/764562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=764562"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/764562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/764563"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=764562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=764562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=764562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}