{"id":789632,"date":"2026-03-10T20:29:15","date_gmt":"2026-03-10T20:29:15","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/789632\/"},"modified":"2026-03-10T20:29:15","modified_gmt":"2026-03-10T20:29:15","slug":"grenoble-une-conference-sur-le-patrimoine-grenoblois-ce-jeudi-12-mars","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/789632\/","title":{"rendered":"Grenoble. Une conf\u00e9rence sur le patrimoine grenoblois ce jeudi 12\u00a0mars"},"content":{"rendered":"<p>Dans le cadre des conf\u00e9rences de l\u2019Acad\u00e9mie delphinale, les membres proposent un th\u00e8me qui est particuli\u00e8rement pr\u00e9sent dans la campagne des municipales\u00a0: le patrimoine grenbolois. Avec Gilles-Marie Moreau, Ren\u00e9 Favier, Henri-Samuel Cohen et Martine Jullian. Seront notamment \u00e9voqu\u00e9s l\u2019h\u00f4tel de Lesdigui\u00e8res et la coll\u00e9giale Saint-Andr\u00e9, le Palais de l\u2019Universit\u00e9, le Mus\u00e9e-biblioth\u00e8que, la Cit\u00e9 de l\u2019Abbaye\u2026<\/p>\n<p class=\"note\">Jeudi 12\u00a0mars \u00e0 18 heures \u00e0 l\u2019UIAD, G4, 6 bis boulevard Gambetta \u00e0 Grenoble. Gratuit.<\/p>\n","protected":false},"excerpt":{"rendered":"Dans le cadre des conf\u00e9rences de l\u2019Acad\u00e9mie delphinale, les membres proposent un th\u00e8me qui est particuli\u00e8rement pr\u00e9sent dans&hellip;\n","protected":false},"author":2,"featured_media":789633,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9566],"tags":[1111,11,2430,6211,1687,112,1777,674,1011,27,2731,2732,108,12,5486,25],"class_list":{"0":"post-789632","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-grenoble","8":"tag-actu","9":"tag-actualites","10":"tag-auvergne-rhone-alpes","11":"tag-conference","12":"tag-culture-loisirs","13":"tag-edition-grenoble-agglomeration","14":"tag-eu","15":"tag-europe","16":"tag-fr","17":"tag-france","18":"tag-grenoble","19":"tag-grenoble-bassin","20":"tag-isere","21":"tag-news","22":"tag-rencontre","23":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116206775076625902","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/789632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=789632"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/789632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/789633"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=789632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=789632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=789632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}