{"id":790663,"date":"2026-03-11T06:57:06","date_gmt":"2026-03-11T06:57:06","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/790663\/"},"modified":"2026-03-11T06:57:06","modified_gmt":"2026-03-11T06:57:06","slug":"municipales-2026-polemique-a-echirolles-autour-de-colistiers-certains-cherchent-a-detourner-le-debat-public-repond-vivre-unis","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/790663\/","title":{"rendered":"Municipales 2026 Pol\u00e9mique \u00e0 \u00c9chirolles autour de colistiers \u200a:\u00a0\u00ab Certains cherchent \u00e0 d\u00e9tourner le d\u00e9bat public \u00bb r\u00e9pond \u201cVivre unis\u201d"},"content":{"rendered":"<p>Depuis quelques jours, la liste \u201c<a href=\"https:\/\/www.ledauphine.com\/elections\/2026\/02\/25\/isere-municipales-2026-echirolles-vivre-unis-laetitia-rabih-devoile-sa-liste-et-ses-engagements\" target=\"_blank\" rel=\"nofollow noopener\">Vivre unis<\/a>\u201d, conduite par La\u00ebtitia Rabih (PS) est vis\u00e9e par une pol\u00e9mique, notamment relay\u00e9e dans nos colonnes \u00e0 travers les propos de\u00a0<a href=\"https:\/\/www.ledauphine.com\/elections\/2026\/03\/06\/isere-municipales-2026-echirolles-elue-6-ans-dans-l-opposition-fabienne-sarrat-soutient-la-maire-sortante\" target=\"_blank\" rel=\"nofollow noopener\">Fabienne Sarrat<\/a>\u00a0et\u00a0<a href=\"https:\/\/www.ledauphine.com\/elections\/2026\/03\/08\/bal-des-faux-culs-tromperie-quand-le-terme-socialiste-met-le-feu-aux-poudres-a-echirolles\" target=\"_blank\" rel=\"nofollow noopener\">Jean-Luc Blache<\/a>, et a d\u00e9cid\u00e9 d\u2019y r\u00e9pondre. <\/p>\n<p>\u201c\u00c0 l\u2019approche des \u00e9lections, certaines tentatives cherchent \u00e0 d\u00e9tourner le d\u00e9bat public vers des pol\u00e9miques portant sur le pass\u00e9 de deux colisti\u00e8res \u00e2g\u00e9es de 74 et 80 ans, plac\u00e9es en position non \u00e9ligible sur notre liste\u201d, indique l\u2019\u00e9quipe dans un communiqu\u00e9.<\/p>\n<p>\u201cIl a \u00e9t\u00e9 \u00e9voqu\u00e9 que certaines personnes figurant sur notre liste auraient, par le pass\u00e9, entretenu des liens ou exprim\u00e9 des sympathies avec des mouvements qualifi\u00e9s d\u2019extr\u00eames\u201d, rappellent les membres de \u201cVivre unis\u201d. Une de leurs colisti\u00e8res figurait en effet par exemple sur la liste RN d\u2019Alexis Jolly en 2020. <\/p>\n<p>\u201cCes engagements appartiennent au pass\u00e9. Les personnes concern\u00e9es ont \u00e9volu\u00e9 et s\u2019engagent d\u00e9sormais clairement dans le respect des valeurs r\u00e9publicaines qui fondent notre d\u00e9marche collective\u201d, assure l\u2019\u00e9quipe. Qui poursuit\u200a: \u201cLa vie politique comme la vie personnelle peuvent conna\u00eetre des \u00e9volutions. Ce qui compte, c\u2019est la capacit\u00e9 \u00e0 \u00e9voluer, \u00e0 reprendre sa libert\u00e9 et \u00e0 s\u2019engager aujourd\u2019hui au service de l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral et des valeurs r\u00e9publicaines. Ce qui d\u00e9finit une \u00e9quipe, ce n\u2019est pas le pass\u00e9, mais les valeurs et le projet port\u00e9s aujourd\u2019hui. Ces \u00e9volutions de parcours existent dans toutes les sensibilit\u00e9s politiques. Par exemple, certains\u00a0<a href=\"https:\/\/www.ledauphine.com\/elections\/2026\/02\/24\/amandine-demore-presente-ses-priorites-et-sa-liste-echirolles-ensemble\" target=\"_blank\" rel=\"nofollow noopener\">colistiers<\/a>\u00a0de la liste d\u2019Amandine Demore ont eux aussi connu des trajectoires politiques diff\u00e9rentes\u201d, ne manque pas de souligner \u201cVivre unis\u201d. Qui souhaite \u00ab\u200arecentrer le d\u00e9bat sur l\u2019essentiel\u200a: le projet pour notre ville et l\u2019avenir des habitants. [\u2026] \u00c9chirolles m\u00e9rite mieux que des pol\u00e9miques. Elle m\u00e9rite un d\u00e9bat de fond, une vision et un projet ambitieux. Nous pensons qu\u2019elle a besoin d\u2019un nouvel \u00e9lan et d\u2019une \u00e9quipe pr\u00eate \u00e0 agir diff\u00e9remment\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"Depuis quelques jours, la liste \u201cVivre unis\u201d, conduite par La\u00ebtitia Rabih (PS) est vis\u00e9e par une pol\u00e9mique, notamment&hellip;\n","protected":false},"author":2,"featured_media":790664,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9566],"tags":[1111,11,2430,9852,112,4188,1777,674,1011,27,2731,108,1985,12,25],"class_list":{"0":"post-790663","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-grenoble","8":"tag-actu","9":"tag-actualites","10":"tag-auvergne-rhone-alpes","11":"tag-echirolles","12":"tag-edition-grenoble-agglomeration","13":"tag-elections-municipales","14":"tag-eu","15":"tag-europe","16":"tag-fr","17":"tag-france","18":"tag-grenoble","19":"tag-isere","20":"tag-metropole-de-grenoble","21":"tag-news","22":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116209244331985108","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/790663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=790663"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/790663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/790664"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=790663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=790663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=790663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}