{"id":791031,"date":"2026-03-11T10:36:21","date_gmt":"2026-03-11T10:36:21","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/791031\/"},"modified":"2026-03-11T10:36:21","modified_gmt":"2026-03-11T10:36:21","slug":"fc-nantes-les-10-recrues-les-plus-cheres-au-cv-de-vahid-halilhodzic","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/791031\/","title":{"rendered":"FC Nantes. Les 10 recrues les plus ch\u00e8res au CV de Vahid Halilhodzic"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" width=\"620\" height=\"413\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/03\/Vahid-Halilhodzic-620x413.jpeg\" alt=\"FC Nantes. Les 10 recrues les plus ch\u00e8res au CV de Vahid Halilhodzic\" class=\"wp-image-396999\"  \/>Vahid Halilhodzic revient au secours du FC Nantes.<\/p>\n<p>Ahmed Kantari n\u2019aura tenu que quelques semaines. Apr\u00e8s le limogeage de Luis Castro en cours de saison, le <a href=\"https:\/\/sportune.20minutes.fr\/fc-nantes\" rel=\"nofollow noopener\" target=\"_blank\">FC Nantes<\/a> a d\u00e9cid\u00e9 de se s\u00e9parer de son successeur et de rappeler une figure bien connue de la Maison Jaune : Vahid Halilhodzic. Le Bosnien, 72 ans, h\u00e9rite d\u2019un chantier colossal : 17e de Ligue 1, le club nantais dispose de neuf matchs pour assurer son maintien, sans possibilit\u00e9 de renforcer l\u2019effectif lors du mercato hivernal d\u00e9sormais clos.<\/p>\n<p>Le choix est charg\u00e9 de symboles. Halilhodzic est avant tout un enfant du club. Attaquant des Canaries entre 1981 et 1986, il y a remport\u00e9 le titre de champion de France en 1983 et sign\u00e9 deux fois le record de buts en une saison \u2014 27 en 1983, 28 en 1985.<\/p>\n<p>Il y est ensuite revenu comme entra\u00eeneur entre 2018 et 2019, avant d\u2019encha\u00eener les s\u00e9lections nationales \u2014 Alg\u00e9rie, Japon, Maroc. Son adjoint Patrick Collot, lui aussi pass\u00e9 par le <a href=\"https:\/\/sportune.20minutes.fr\/fc-nantes\" rel=\"nofollow noopener\" target=\"_blank\">FC Nantes<\/a> entre 2018 et 2021, l\u2019accompagne dans cette mission. Le premier test sera imm\u00e9diat : la r\u00e9ception du <a href=\"https:\/\/sportune.20minutes.fr\/rc-strasbourg-rcsa\" rel=\"nofollow noopener\" target=\"_blank\">RC Strasbourg<\/a>, dimanche 22 mars \u00e0 la Beaujoire.<\/p>\n<p>Un top 10 qui n\u2019a plus \u00e9volu\u00e9 depuis douze ans<\/p>\n<p>Si Halilhodzic arrive cette fois sans budget de recrutement, son palmar\u00e8s de coach raconte une autre histoire. Ses dix recrues les plus on\u00e9reuses totalisent pr\u00e8s de 71 millions d\u2019euros, pour une moyenne d\u2019un peu plus de 7 millions par transfert \u2014 l\u2019\u00e9quivalent aujourd\u2019hui d\u2019un milieu de gamme du march\u00e9 fran\u00e7ais.<\/p>\n<p>Un chiffre \u00e0 relativiser : ce Top 10 n\u2019a plus boug\u00e9 depuis 2014, et c\u2019est au <a href=\"https:\/\/sportune.20minutes.fr\/paris-saint-germain-psg\" rel=\"nofollow noopener\" target=\"_blank\">Paris Saint-Germain<\/a>, entre 2003 et 2004, qu\u2019il a dispos\u00e9 de ses moyens les plus significatifs, recrutant notamment Pauleta pour 11 millions d\u2019euros et s\u2019offrant Reinaldo Oliveira, J\u00e9r\u00f4me Rothen ou Mario Yepes. Trabzonspor, entre 2013 et 2014, constitue son seul autre passage avec un investissement notable sur le march\u00e9 des transferts.<\/p>\n<p>Les 10 recrues les plus ch\u00e8res au CV de Vahid Halilhodzic<\/p>\n<p>10. Danijel Ljuboja, du RC Strasbourg Alsace au Paris Saint-Germain (2004) = 3,3 M\u20ac<br \/>9. Sefa Yilmaz, de Kayserispor \u00e0 Trabzonspor (2014) = 3,5 M\u20ac<br \/>8. Oscar Cardozo, du SL Benfica \u00e0 Trabzonspor (2014) = 5 M\u20ac<br \/>7. Sylvain Armand, du FC Nantes au Paris Saint-Germain (2004) = 5 M\u20ac<br \/>6. Branko Boskovic, de l\u2019\u00c9toile Rouge de Belgrade au Paris Saint-Germain (2003) = 6 M\u20ac<br \/>5. Majeed Waris, du Spartak Moscou \u00e0 Trabzonspor (2014) = 6,9 M\u20ac<br \/>4. Mario Yepes, du FC Nantes au Paris Saint-Germain (2004) = 10 M\u20ac<br \/>3. J\u00e9r\u00f4me Rothen, de l\u2019AS Monaco au Paris Saint-Germain (2004) = 10 M\u20ac<br \/>2. Reinaldo Oliveira, du Clube Regatas Flamengo au Paris Saint-Germain (2003) = 10 M\u20ac<br \/>1. Pauleta, du FC Girondins de Bordeaux au Paris Saint-Germain (2003) = 11 M\u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"Vahid Halilhodzic revient au secours du FC Nantes. Ahmed Kantari n\u2019aura tenu que quelques semaines. Apr\u00e8s le limogeage&hellip;\n","protected":false},"author":2,"featured_media":791032,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2818],"tags":[1111,11,1777,674,462,1011,27,766,12,2636,25,969,5958],"class_list":{"0":"post-791031","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nantes","8":"tag-actu","9":"tag-actualites","10":"tag-eu","11":"tag-europe","12":"tag-fc-nantes","13":"tag-fr","14":"tag-france","15":"tag-nantes","16":"tag-news","17":"tag-pays-de-la-loire","18":"tag-republique-francaise","19":"tag-transfert","20":"tag-vahid-halilhodzic"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116210105569988634","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/791031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=791031"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/791031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/791032"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=791031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=791031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=791031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}