{"id":798263,"date":"2026-03-14T12:48:15","date_gmt":"2026-03-14T12:48:15","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/798263\/"},"modified":"2026-03-14T12:48:15","modified_gmt":"2026-03-14T12:48:15","slug":"nouveau-spectacle-nouveaux-talents-les-castings-de-very-love-trip-commencent-bientot-au-casino-barriere-toulouse","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/798263\/","title":{"rendered":"Nouveau spectacle, nouveaux talents : Les castings de \u00ab\u00a0Very Love Trip\u00a0\u00bb commencent bient\u00f4t au Casino Barri\u00e8re Toulouse !"},"content":{"rendered":"<p data-path-to-node=\"1\">Apr\u00e8s l\u2019immense succ\u00e8s de Time for Love, qui a fait vibrer plus de 15 000 spectateurs, le Th\u00e9\u00e2tre du Casino Barri\u00e8re Toulouse se pr\u00e9pare d\u00e9j\u00e0 pour sa prochaine grande aventure th\u00e9\u00e2trale et musicale. Pr\u00e9vue pour l\u2019automne prochain, la nouvelle cr\u00e9ation intitul\u00e9e <b data-path-to-node=\"1\" data-index-in-node=\"262\">\u00ab\u00a0Very Love Trip\u00a0\u00bb<\/b> promet de repousser les limites du divertissement toulousain. Le compte \u00e0 rebours est lanc\u00e9 : <b data-path-to-node=\"1\" data-index-in-node=\"373\">nouveau spectacle, nouveaux talents, les castings commencent bient\u00f4t !<\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-904425 aligncenter\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/03\/Casting-Casino-300x183.png.webp.webp\" alt=\"\" width=\"300\" height=\"183\"  \/><br \/>\n\u00ab\u00a0Very Love Trip\u00a0\u00bb : Un voyage flamboyant et extravagant<\/p>\n<p data-path-to-node=\"4\">Plus qu\u2019une simple com\u00e9die musicale, cette nouvelle production s\u2019annonce comme un tour du monde rocambolesque m\u00ealant humour, amour et r\u00e9v\u00e9lations croustillantes.<\/p>\n<p>Un synopsis qui promet des \u00e9tincelles<\/p>\n<p data-path-to-node=\"6\">L\u2019histoire suit Ava et Enzo, un couple sur le point de se dire \u00ab\u00a0oui\u00a0\u00bb. Mais c\u2019\u00e9tait sans compter sur Sansfiltre, le dro\u00efde invent\u00e9 par Enzo, qui l\u00e2che une v\u00e9ritable bombe : Enzo est en r\u00e9alit\u00e9 d\u00e9j\u00e0 mari\u00e9 ! Une nuit d\u2019ivresse \u00e0 Las Vegas, dix ans plus t\u00f4t, l\u2019a uni \u00e0 une femme myst\u00e9rieuse devenue depuis\u2026 Gloria Shine, la plus grande star mondiale de la chanson.<\/p>\n<p data-path-to-node=\"7\">Soucieuse de prot\u00e9ger son image, Gloria refuse cat\u00e9goriquement de signer les papiers du divorce et poursuit sa tourn\u00e9e internationale. S\u2019engage alors une course folle autour du globe pour le couple. Sous l\u2019\u0153il attentif (et indiscret) du dro\u00efde Sansfiltre, les secrets \u00e9clatent et la jalousie s\u2019en m\u00eale. Leur amour r\u00e9sistera-t-il \u00e0 ce p\u00e9riple sous les projecteurs du monde entier ?<\/p>\n<p>Une cr\u00e9ation audacieuse et moderne<\/p>\n<p data-path-to-node=\"9\">Port\u00e9e par une troupe de <b data-path-to-node=\"9\" data-index-in-node=\"25\">15 artistes polyvalents<\/b>, la com\u00e9die musicale abordera de nombreux enjeux soci\u00e9taux \u00e0 travers un prisme r\u00e9solument moderne. C\u00f4t\u00e9 musique, le public pourra s\u2019\u00e9gosiller sur de grands tubes de la vari\u00e9t\u00e9 fran\u00e7aise et internationale, mais d\u00e9couvrira \u00e9galement, et c\u2019est une grande premi\u00e8re, des <b data-path-to-node=\"9\" data-index-in-node=\"315\">titres originaux<\/b> cr\u00e9\u00e9s sp\u00e9cialement pour le spectacle.<\/p>\n<p data-path-to-node=\"10\">La mise en sc\u00e8ne est une nouvelle fois confi\u00e9e \u00e0 <b data-path-to-node=\"10\" data-index-in-node=\"49\">Carole Chauvy<\/b>, directrice artistique embl\u00e9matique du Casino Barri\u00e8re Toulouse, qui signe ici le livret de son dixi\u00e8me spectacle pour l\u2019\u00e9tablissement. Pour enflammer la sc\u00e8ne, les chor\u00e9graphies ont \u00e9t\u00e9 confi\u00e9es au talentueux duo toulousain <b data-path-to-node=\"10\" data-index-in-node=\"288\">Romane Chaney et Antoine Nya<\/b>.<\/p>\n<p>Castings : Rejoignez la troupe de la rentr\u00e9e !<\/p>\n<p data-path-to-node=\"13\">\u00c0 seulement quelques jours du coup d\u2019envoi des auditions, l\u2019effervescence est palpable. Le Th\u00e9\u00e2tre du Casino Barri\u00e8re est \u00e0 la recherche de ses futures \u00e9toiles (voix, musiciens, performeurs visuels et danseurs) pour donner vie \u00e0 Very Love Trip.<\/p>\n<p data-path-to-node=\"14\">Voici le calendrier d\u00e9taill\u00e9 des auditions pr\u00e9vues les <b data-path-to-node=\"14\" data-index-in-node=\"55\">15, 29 et 30 mars 2026<\/b> :<\/p>\n<p data-path-to-node=\"16\">Pour les artistes retenus lors de ces premi\u00e8res \u00e9tapes, un <b data-path-to-node=\"16\" data-index-in-node=\"59\">Call Back g\u00e9n\u00e9ral<\/b> est programm\u00e9 le lundi 30 mars.<\/p>\n<p data-path-to-node=\"17\"><b data-path-to-node=\"17\" data-index-in-node=\"3\">Plus d\u2019informations sur le site officiel :<\/b> <a class=\"ng-star-inserted\" href=\"https:\/\/www.casinosbarriere.com\/toulouse\/actualites\/very-love-trip-casting-artistes\" target=\"_blank\" rel=\"noopener nofollow\" data-hveid=\"0\" data-ved=\"0CAAQ_4QMahcKEwib8p_kk5uTAxUAAAAAHQAAAAAQYg\">Casino Barri\u00e8re Toulouse \u2013 Actualit\u00e9s Castings<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Apr\u00e8s l\u2019immense succ\u00e8s de Time for Love, qui a fait vibrer plus de 15 000 spectateurs, le Th\u00e9\u00e2tre&hellip;\n","protected":false},"author":2,"featured_media":798264,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[2816],"tags":[1111,11,1777,674,1011,27,12,2680,25,2312],"class_list":["post-798263","post","type-post","status-publish","format-standard","has-post-thumbnail","category-toulouse","tag-actu","tag-actualites","tag-eu","tag-europe","tag-fr","tag-france","tag-news","tag-occitanie","tag-republique-francaise","tag-toulouse"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116227611546464559","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/798263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=798263"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/798263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/798264"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=798263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=798263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=798263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}