{"id":806361,"date":"2026-03-18T01:24:14","date_gmt":"2026-03-18T01:24:14","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/806361\/"},"modified":"2026-03-18T01:24:14","modified_gmt":"2026-03-18T01:24:14","slug":"cyril-hanouna-charme-par-delphine-wespiser-la-gueule-quil-fait","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/806361\/","title":{"rendered":"Cyril Hanouna charm\u00e9 par Delphine Wespiser ? \u00ab\u00a0La gueule qu&rsquo;il fait !\u00a0\u00bb"},"content":{"rendered":"<p>Le d\u00e9but de cette nouvelle quotidienne de Tout beau, tout neuf a<br \/>\ncommenc\u00e9 d&rsquo;une mani\u00e8re tr\u00e8s \u00e9tonnante. Il se trouve que les<br \/>\nchroniqueurs en plateau \u00e9taient tous recouverts de post-it. Mais<br \/>\npourquoi ? <strong>Cyril Hanouna a alors r\u00e9v\u00e9l\u00e9 que sur les r\u00e9seaux<br \/>\nsociaux, il y avait la trend du post-it.<\/strong> Le but \u00e9tant de<br \/>\ndanser pour que les petits papiers de couleurs se d\u00e9collent d&rsquo;eux.<br \/>\nTout \u00e7a, sans les enlever avec les mains.<\/p>\n<p>Jordan De Luxe mis \u00e0 nu en plein direct&#8230;<\/p>\n<p>Le premier \u00e0 \u00eatre pass\u00e9 au milieu du plateau est Jordan De Luxe.<br \/>\nSauf qu&rsquo;il y a eu un petit probl\u00e8me pendant sa danse&#8230; Il a craqu\u00e9<br \/>\nson pantalon ! Le chroniqueur ne s&rsquo;en ai pas tout de suite rendu<br \/>\ncompte. Cyril Hanouna lui a alors demand\u00e9 de ramasser un stylo et<br \/>\nson cale\u00e7on jaune a \u00e9t\u00e9 mis en lumi\u00e8re. <strong>\u00ab\u00a0Il s&rsquo;est<br \/>\nd\u00e9chir\u00e9 le pantalon ! Bravo \u00e0 lui ! Il a \u00e9t\u00e9<br \/>\nexcellent\u00a0\u00bb<\/strong>, a lanc\u00e9 l&rsquo;animateur \u00e0 Jordan De Luxe<br \/>\nparti en loge pour changer de pantalon.<\/p>\n<p>Apr\u00e8s Jordan De Luxe, c&rsquo;est G\u00e9raldine Maillet qui est pass\u00e9e et<br \/>\nelle a fait tomber la quasi totalit\u00e9 des post-it mis sur elle.<br \/>\nC&rsquo;\u00e9tait ensuite au tour de Raymond de r\u00e9aliser cette trend, mais il<br \/>\na fait beaucoup moins bien que sa camarade. <a href=\"https:\/\/www.melty.fr\/tele\/tbt9-cyril-hanouna-coupe-court-au-discours-de-delphine-wespiser-si-vous-avez-quelque-chose-a-me-dire-2303294.html\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\nDelphine Wespiser, qui a \u00e9t\u00e9 coup\u00e9 dans son discours par Cyril<br \/>\nHanouna<\/a>, a fait une jolie prestation. Matthieu Delormeau a<br \/>\nalors pris la parole pour dire <strong>: \u00ab\u00a0La gueule de Cyril<br \/>\n!\u00a0\u00bb<\/strong> Mais l&rsquo;animateur s&rsquo;est d\u00e9fendu en disant :<br \/>\n<strong>\u00ab\u00a0Pas du tout, je n&rsquo;ai pas du tout regard\u00e9<br \/>\nDelphine.\u00a0\u00bb<\/strong> G\u00e9raldine Maillet, elle, a ajout\u00e9 :<br \/>\n<strong>\u00ab\u00a0Il regarde tout le monde de la m\u00eame<br \/>\nmani\u00e8re.\u00a0\u00bb<\/strong><\/p>\n<p>Matthieu Delormeau moqu\u00e9 par Cyril Hanouna et G\u00e9raldine<br \/>\nMaillet<\/p>\n<p>C&rsquo;\u00e9tait ensuite au tour de Matthieu Delormeau de passer, mais<br \/>\ncontrairement \u00e0 ses camarades, les post-it ont eu beaucoup de mal \u00e0<br \/>\ntomber. Pourtant, le chroniqueur a mis de l&rsquo;intensit\u00e9, mais en<br \/>\nvain&#8230; De quoi faire r\u00e9agir Cyril Hanouna qui lui a annonc\u00e9 :<br \/>\n<strong>\u00ab\u00a0Il n&rsquo;y en a pas un qui s&rsquo;est d\u00e9coll\u00e9\u00a0\u00bb.<\/strong><br \/>\nQuant \u00e0 G\u00e9raldine Maillet, elle s&rsquo;est moqu\u00e9 de Matthieu Delormeau :<br \/>\n<strong>\u00ab\u00a0Mais tu fais du sport ? Parce que tu as l&rsquo;air<br \/>\nessouffl\u00e9. \u00ab\u00a0<\/strong><\/p>\n<p>Apr\u00e8s Val\u00e9rie B\u00e9na\u00efm, Olivier Dartigolles est pass\u00e9 \u00e0 son tour<br \/>\net \u00e7a a \u00e9t\u00e9 un grand moment pour le chroniqueur qui a r\u00e9ussi \u00e0<br \/>\nfaire tomber presque tous les post-it. \u00ab\u00a0Je pense qu&rsquo;il joue \u00e0 \u00e7a<br \/>\nchez lui\u00a0\u00bb, a balanc\u00e9 <a href=\"https:\/\/www.melty.fr\/tele\/tbt9-valerie-benaim-insupportable-matthieu-delormeau-vide-son-sac-je-la-deteste-2302472.html\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\nMatthieu Delormeau qui a vid\u00e9 son sac sur Val\u00e9rie B\u00e9na\u00efm.<\/a><\/p>\n<p>Qui a gagn\u00e9 le challenge lanc\u00e9 par<br \/>\nCyril Hanouna ?<\/p>\n<p>Pour terminer ce challenge, c&rsquo;est Polska qui est pass\u00e9e au<br \/>\nmilieu du plateau de Tout beau, tout neuf. Mais \u00e0 force de tourner<br \/>\nen rond, elle a eu la t\u00eate qui tourne. \u00ab\u00a0Je te ram\u00e8ne \u00e0 ta<br \/>\nplace, parce que je ne le sens pas\u00a0\u00bb, a lanc\u00e9 Cyril Hanouna. En<br \/>\nplein ramadan, Gilles Verdez a finalement d\u00e9clin\u00e9 le jeu. \u00ab\u00a0J&rsquo;ai<br \/>\nbien fait de l&rsquo;oublier, il allait tomber par terre\u00a0\u00bb, a dit<br \/>\nl&rsquo;animateur avant d&rsquo;annoncer les finalistes qui sont Jordan De<br \/>\nLuxe, Delphine Wespiser, Polska et Olivier Dartigolles. <strong>Le<br \/>\ngrand gagnant de ce challenge est Jordan De Luxe !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Le d\u00e9but de cette nouvelle quotidienne de Tout beau, tout neuf a commenc\u00e9 d&rsquo;une mani\u00e8re tr\u00e8s \u00e9tonnante. Il&hellip;\n","protected":false},"author":2,"featured_media":806362,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1359],"tags":[1083,33841,58,59,1011,27,973],"class_list":{"0":"post-806361","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-cyril-hanouna","9":"tag-delphine-wespiser","10":"tag-divertissement","11":"tag-entertainment","12":"tag-fr","13":"tag-france","14":"tag-people"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116247571079026319","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/806361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=806361"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/806361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/806362"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=806361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=806361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=806361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}