{"id":842635,"date":"2026-04-02T14:22:16","date_gmt":"2026-04-02T14:22:16","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/842635\/"},"modified":"2026-04-02T14:22:16","modified_gmt":"2026-04-02T14:22:16","slug":"grenoble-le-musee-sort-de-ses-murs-pour-fusionner-avec-la-science","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/842635\/","title":{"rendered":"Grenoble. Le mus\u00e9e sort de ses murs pour fusionner avec la science"},"content":{"rendered":"<p class=\"heading\">&#8230;pour lire la suite, rejoignez notre communaut\u00e9 d&rsquo;abonn\u00e9s<\/p>\n<p class=\"subtitle\">et acc\u00e9dez \u00e0 l&rsquo;int\u00e9gralit\u00e9 de nos articles sur le site et l&rsquo;application mobile<\/p>\n<p class=\"price-detail\">&#13;<br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\u00e0 partir de 1 \u20ac  le 1er mois, sans engagement de dur\u00e9e&#13;\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p class=\"listSKU\" style=\"display:none\">{&lsquo;skus&rsquo;: [&lsquo;ldlswgpremium16&rsquo;]}<\/p>\n<p class=\"google-sub-infos\">Google : 1\u20ac le 1er mois puis 12,99\u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"&#8230;pour lire la suite, rejoignez notre communaut\u00e9 d&rsquo;abonn\u00e9s et acc\u00e9dez \u00e0 l&rsquo;int\u00e9gralit\u00e9 de nos articles sur le site&hellip;\n","protected":false},"author":2,"featured_media":842636,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9566],"tags":[1111,11,2430,1687,112,1777,674,2271,1011,27,2731,2732,108,12,25,767],"class_list":{"0":"post-842635","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-grenoble","8":"tag-actu","9":"tag-actualites","10":"tag-auvergne-rhone-alpes","11":"tag-culture-loisirs","12":"tag-edition-grenoble-agglomeration","13":"tag-eu","14":"tag-europe","15":"tag-exposition-arts-plastiques","16":"tag-fr","17":"tag-france","18":"tag-grenoble","19":"tag-grenoble-bassin","20":"tag-isere","21":"tag-news","22":"tag-republique-francaise","23":"tag-science-et-technologie"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116335565228217035","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/842635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=842635"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/842635\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/842636"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=842635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=842635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=842635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}