{"id":852481,"date":"2026-04-07T06:01:20","date_gmt":"2026-04-07T06:01:20","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/852481\/"},"modified":"2026-04-07T06:01:20","modified_gmt":"2026-04-07T06:01:20","slug":"ce-bar-tabac-rouvre-ses-portes-avec-une-nouvelle-terrasse","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/852481\/","title":{"rendered":"ce bar-tabac rouvre ses portes avec une nouvelle terrasse"},"content":{"rendered":"<p>                    Par<br \/>\n        <strong><br \/>\n            <a href=\"https:\/\/actu.fr\/auteur\/laure-gentil\" title=\"Consulter tous les articles de Laure Gentil\" rel=\"nofollow noopener\" target=\"_blank\">Laure Gentil<\/a><br \/>\n                    <\/strong><\/p>\n<p>        Publi\u00e9 le<\/p>\n<p>            7 avr. 2026 \u00e0 7h00        <\/p>\n<p><b>Eric Lagunegrand<\/b>, 27\u00a0ans, ne cache pas son enthousiasme. Ce Nantais de naissance, qui habite aujourd\u2019hui \u00e0 <a href=\"https:\/\/actu.fr\/pays-de-la-loire\/reze_44143\" rel=\"nofollow noopener\" target=\"_blank\">Rez\u00e9<\/a>, a repris <b>le bar-tabac Le Chalet<\/b>,<b> boulevard des Belges<\/b> et l\u2019a enti\u00e8rement refait. Lors de sa f\u00eate de r\u00e9ouverture, pr\u00e9vue le 10\u00a0avril, il d\u00e9voilera son tout nouvel espace ext\u00e9rieur, calme et d\u00e9cor\u00e9 dans un \u00ab\u2009esprit lounge\u2009\u00bb. \u00ab\u2009Quand on est dans le jardin, on n\u2019a pas l\u2019impression d\u2019\u00eatre en centre-ville\u2009\u00bb, explique-t-il avec un grand sourire. \u00ab\u2009C\u2019est vraiment le c\u00f4t\u00e9, l\u2019axe que je veux d\u00e9velopper et faire conna\u00eetre.\u2009\u00bb<\/p>\n<p class=\" wall-content\"><a href=\"https:\/\/www.instagram.com\/p\/DWbWkx8DEkW\/embed\" title=\"Ouvrir le lien sur Instagram\" rel=\"nofollow noopener\" target=\"_blank\">Visualiser le contenu sur Instagram<\/a><\/p>\n<p>Un lieu o\u00f9 se retrouver<\/p>\n<p class=\" wall-content\">Le Chalet a bien chang\u00e9 depuis qu\u2019Eric a repris l\u2019affaire \u00e0 son ancien propri\u00e9taire. Finis les murs orange, ils sont maintenant bleus. Un <b>jeu de fl\u00e9chettes<\/b> et une <b>t\u00e9l\u00e9vision <\/b>ont \u00e9t\u00e9 install\u00e9s \u00e0 l\u2019int\u00e9rieur pour animer les soir\u00e9es et d\u00e9tendre les clients. <b>La carte a aussi \u00e9t\u00e9 \u00e9toff\u00e9e.<\/b><\/p>\n<blockquote class=\"ac-article-quote wall-content\">\n<p>J\u2019ai d\u00e9velopp\u00e9 le c\u00f4t\u00e9 bar avec une nouvelle carte un peu plus compl\u00e8te. Avant on n\u2019avait que trois bi\u00e8res, maintenant on est rendu \u00e0 quatre pressions (une bi\u00e8re IPA a \u00e9t\u00e9 ajout\u00e9e, N.D.L.R.). Une carte un peu plus large aussi sur les softs. L\u2019axe que j\u2019aimerais aussi d\u00e9velopper un peu plus, c\u2019est le c\u00f4t\u00e9 restauration rapide.<\/p>\n<p>Eric Lagunegrand<\/p><\/blockquote>\n<p class=\" wall-content\">Des croque-monsieur et des paninis devraient bient\u00f4t \u00eatre propos\u00e9s \u00e0 la vente. \u00c9ric songe aussi \u00e0 mettre en place une offre cocktails. Son objectif est clair\u2009: proposer \u00e0 sa client\u00e8le \u00ab\u2009un petit moment de d\u00e9tente\u2009\u00bb.<\/p>\n<p class=\" wall-content\">Pas de soir\u00e9es de folie. Eric veut \u00ab\u2009garder un endroit calme, chaleureux, agr\u00e9able \u00e0 venir\u2009\u00bb mais \u00ab\u2009o\u00f9 on peut quand m\u00eame faire la f\u00eate\u2009\u00bb. Agr\u00e9ablement ombrag\u00e9 par les arbres, le <b>jardin<\/b>, enti\u00e8rement refait pour approfondir cet effet \u00ab\u2009lounge\u2009\u00bb, est la cerise sur le g\u00e2teau. Sept tables ont \u00e9t\u00e9 dispos\u00e9es pour environ deux personnes chacune, compl\u00e9tant les <b>30 places assises \u00e0 l\u2019int\u00e9rieur.<\/b><\/p>\n<p>    <img   decoding=\"async\" loading=\"lazy\" class=\"size-large\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/04\/0e31f7f83dc964741f7f83dc96b41fv-960x640.jpeg\" alt=\"L'espace ext\u00e9rieur a \u00e9t\u00e9 r\u00e9am\u00e9nag\u00e9 pour donner une ambiance calme et confortable.\" width=\"960\" height=\"640\"\/><br \/>\n    L\u2019espace ext\u00e9rieur a \u00e9t\u00e9 r\u00e9am\u00e9nag\u00e9 pour donner une ambiance calme et confortable. \u00a9Laure Gentil \/ actu Nantes<\/p>\n<p class=\" wall-content\"><b>Le vendredi 10<\/b>\u00a0<b>avril<\/b>, le nouveau patron du Chalet a d\u00e9cid\u00e9 d\u2019organiser une f\u00eate pour la r\u00e9ouverture du bar-tabac mais aussi pour faire conna\u00eetre son nouveau concept. Un DJ sera l\u00e0 pour mettre de l\u2019ambiance. Bien \u00e9videmment tout le quartier est invit\u00e9 \u00e0 d\u00e9couvrir le nouveau visage de l\u2019\u00e9tablissement. Certains semblent m\u00eame d\u00e9j\u00e0 d\u00e9cid\u00e9s \u00e0 venir. \u00c0 la sortie, une habitante nous interpelle\u2009: \u00ab\u2009\u00c7a va \u00eatre bien\u2009!\u2009\u00bb<\/p>\n<p class=\" wall-content\">Personnalisez votre actualit\u00e9 en ajoutant vos villes et m\u00e9dias en favori avec <a href=\"https:\/\/moncompte.actu.fr\" title=\"D\u00e9couvez Mon Actu\" rel=\"nofollow noopener\" data-trk=\"{&quot;cta&quot;:{&quot;action&quot;:&quot;https:\\\/\\\/moncompte.actu.fr&quot;,&quot;category&quot;:&quot;mon compte&quot;,&quot;from&quot;:&quot;article footer&quot;,&quot;name&quot;:&quot;Mon actu&quot;,&quot;type&quot;:&quot;cta&quot;}}\" target=\"_blank\">Mon Actu<\/a>.<\/p>\n<p>                    <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Par Laure Gentil Publi\u00e9 le 7 avr. 2026 \u00e0 7h00 Eric Lagunegrand, 27\u00a0ans, ne cache pas son enthousiasme.&hellip;\n","protected":false},"author":2,"featured_media":852482,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2818],"tags":[1111,11,215,1777,674,1011,27,766,12,3147,2636,25,104],"class_list":{"0":"post-852481","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nantes","8":"tag-actu","9":"tag-actualites","10":"tag-commerce","11":"tag-eu","12":"tag-europe","13":"tag-fr","14":"tag-france","15":"tag-nantes","16":"tag-news","17":"tag-nouveaux-commerces","18":"tag-pays-de-la-loire","19":"tag-republique-francaise","20":"tag-societe"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116361906618924332","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/852481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=852481"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/852481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/852482"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=852481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=852481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=852481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}