{"id":853091,"date":"2026-04-07T12:45:17","date_gmt":"2026-04-07T12:45:17","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/853091\/"},"modified":"2026-04-07T12:45:17","modified_gmt":"2026-04-07T12:45:17","slug":"fiona-cailo-serra-championne-deurope-2025-2026","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/853091\/","title":{"rendered":"Fiona Cailo-Serra championne d\u2019Europe 2025-2026"},"content":{"rendered":"<p>Ce week-end, Fiona Caiolo-Serra s\u2019est offert le titre de championne d\u2019Europe 2025-2026 de snowboard-cross en terminant la saison avec une deuxi\u00e8me place et une victoire sur les deux derni\u00e8res \u00e9preuves. Candice B\u00e9n\u00e9ton l\u2019accompagne sur le podium avec une troisi\u00e8me place au g\u00e9n\u00e9ral. Andr\u00e9as Herranz remporte \u00e9galement le titre de champion de France de slopestyle. Accompagn\u00e9s par la commune des Deux-Alpes, ces r\u00e9sultats mettent une nouvelle fois en avant l\u2019excellence de ces sportifs locaux.<\/p>\n","protected":false},"excerpt":{"rendered":"Ce week-end, Fiona Caiolo-Serra s\u2019est offert le titre de championne d\u2019Europe 2025-2026 de snowboard-cross en terminant la saison&hellip;\n","protected":false},"author":2,"featured_media":853092,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1586],"tags":[11,113,1777,674,1011,27,20385,12,20647,25,14346,517,9589],"class_list":{"0":"post-853091","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europe","8":"tag-actualites","9":"tag-edition-gresivaudan-oisans","10":"tag-eu","11":"tag-europe","12":"tag-fr","13":"tag-france","14":"tag-les-deux-alpes","15":"tag-news","16":"tag-oisans","17":"tag-republique-francaise","18":"tag-snowboard","19":"tag-sport","20":"tag-sports-dhiver"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116363495305731635","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/853091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=853091"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/853091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/853092"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=853091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=853091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=853091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}