{"id":854154,"date":"2026-04-07T23:33:18","date_gmt":"2026-04-07T23:33:18","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/854154\/"},"modified":"2026-04-07T23:33:18","modified_gmt":"2026-04-07T23:33:18","slug":"les-hommes-de-17-a-45-ans-doivent-obtenir-un-accord-de-larmee-pour-certains-sejours-a-letranger","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/854154\/","title":{"rendered":"les hommes de 17 \u00e0 45 ans doivent obtenir un accord de l\u2019arm\u00e9e pour certains s\u00e9jours \u00e0 l\u2019\u00e9tranger"},"content":{"rendered":"<p>Publi\u00e9 le 8 avril 2026 \u00e0 00:05 par La r\u00e9daction <\/p>\n<p>Depuis le 1er janvier 2026, les Allemands de 17 \u00e0 45 ans doivent obtenir l&rsquo;accord de la Bundeswehr pour quitter le pays plus de trois mois.<\/p>\n<p>\u00c0 lire plus tardSauvegard\u00e9Suivre #Allemagne#Allemagne Suivi<\/p>\n<p class=\"first-paragraph\">Dans un contexte de tensions g\u00e9opolitiques croissantes en Europe, l&rsquo;Allemagne franchit une \u00e9tape majeure dans la r\u00e9organisation de sa d\u00e9fense. Depuis le 1er janvier 2026, une nouvelle loi sur le service militaire, port\u00e9e par le gouvernement du chancelier <strong>Friedrich Merz<\/strong>, impose des restrictions de mouvement in\u00e9dites pour une partie de la population masculine. D\u00e9sormais, les hommes \u00e2g\u00e9s de <strong>17 \u00e0 45 ans<\/strong> doivent obtenir l\u2019aval de la Bundeswehr pour tout s\u00e9jour hors du territoire f\u00e9d\u00e9ral d\u00e9passant <strong>trois mois<\/strong>.<\/p>\n<p class=\"post-podcast-title\">D\u00e9couvrir notre dernier podcast<\/p>\n<p><strong>Une proc\u00e9dure \u00ab r\u00e9put\u00e9e accord\u00e9e \u00bb pour apaiser la pol\u00e9mique<\/strong><\/p>\n<p>Cette mesure, r\u00e9v\u00e9l\u00e9e par le quotidien Frankfurter Rundschau, stipule que les citoyens concern\u00e9s doivent solliciter le centre de recrutement comp\u00e9tent avant leur d\u00e9part. L&rsquo;obligation s&rsquo;applique \u00e9galement \u00e0 ceux qui, d\u00e9j\u00e0 \u00e0 l&rsquo;\u00e9tranger, souhaiteraient prolonger leur s\u00e9jour au-del\u00e0 de la dur\u00e9e initialement autoris\u00e9e. L&rsquo;objectif affich\u00e9 par Berlin est clair : porter les effectifs de l&rsquo;arm\u00e9e active de 180 000 \u00e0 <strong>270 000 militaires d&rsquo;ici 2035<\/strong>, face aux menaces persistantes en provenance de la Russie.<\/p>\n<p>L&rsquo;annonce de cette restriction a provoqu\u00e9 une vive controverse outre-Rhin, certains y voyant une atteinte disproportionn\u00e9e \u00e0 la libert\u00e9 de circulation. Face au toll\u00e9, le minist\u00e8re de la D\u00e9fense a tent\u00e9 de calmer le jeu. Un porte-parole a pr\u00e9cis\u00e9 que, tant que le service militaire demeure sur une base volontaire, cette autorisation est <strong>\u00ab r\u00e9put\u00e9e accord\u00e9e \u00bb<\/strong> d&rsquo;office. L&rsquo;administration assure chercher une \u00ab proc\u00e9dure simple \u00bb pour ne pas p\u00e9naliser les \u00e9tudiants ou les expatri\u00e9s.<\/p>\n<p>Toutefois, le flou demeure pour les jeunes hommes pr\u00e9voyant un semestre d&rsquo;\u00e9tudes \u00e0 l&rsquo;\u00e9tranger ou une ann\u00e9e de c\u00e9sure. Si la loi est entr\u00e9e en vigueur, les autorit\u00e9s n&rsquo;ont pas encore communiqu\u00e9 sur les sanctions encourues par ceux qui omettraient de d\u00e9clarer leur d\u00e9part.<\/p>\n","protected":false},"excerpt":{"rendered":"Publi\u00e9 le 8 avril 2026 \u00e0 00:05 par La r\u00e9daction Depuis le 1er janvier 2026, les Allemands de&hellip;\n","protected":false},"author":2,"featured_media":854155,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1587],"tags":[11,672,1804,1805,1803,1777,674,1801,1146,12,1802],"class_list":{"0":"post-854154","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-allemagne","8":"tag-actualites","9":"tag-allemagne","10":"tag-bundesrepublik-deutschland","11":"tag-de","12":"tag-deutschland","13":"tag-eu","14":"tag-europe","15":"tag-germany","16":"tag-guerre","17":"tag-news","18":"tag-republique-federale-dallemagne"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116366043125837157","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/854154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=854154"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/854154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/854155"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=854154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=854154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=854154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}