{"id":862427,"date":"2026-04-11T16:25:26","date_gmt":"2026-04-11T16:25:26","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/862427\/"},"modified":"2026-04-11T16:25:26","modified_gmt":"2026-04-11T16:25:26","slug":"vaste-interdiction-prefectorale-dans-le-sud-de-lisere-tout-le-week-end","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/862427\/","title":{"rendered":"vaste interdiction pr\u00e9fectorale dans le sud de l\u2019Is\u00e8re tout le week-end"},"content":{"rendered":"<p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t11 Avril 2026\n\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/04\/1280x720_69da5709328cf-54993440829-7b2f335487-o.jpg\" alt=\"Rave party \u201cDes\u2019astres sonore\u201d : vaste interdiction pr\u00e9fectorale dans le sud de l\u2019Is\u00e8re tout le week-end\" title=\"Rave party \u201cDes\u2019astres sonore\u201d : vaste interdiction pr\u00e9fectorale dans le sud de l\u2019Is\u00e8re tout le week-end\" width=\"1280\" height=\"720\" class=\"img-fluid  mb-3\" loading=\"lazy\"\/>\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p itemprop=\"description\"><strong>La pr\u00e9fecture de l\u2019Is\u00e8re interdit tout rassemblement musical non autoris\u00e9 dans le sud du d\u00e9partement jusqu\u2019au lundi 13 avril \u00e0 8h.<\/strong><\/p>\n<p>\t\t\t\t\tUn arr\u00eat\u00e9 pr\u00e9fectoral proscrit ce week-end l\u2019ensemble des \u00e9v\u00e9nements festifs non d\u00e9clar\u00e9s dans l\u2019arrondissement de Grenoble ainsi que la circulation\u2026\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p><a class=\"trans-button\" href=\"https:\/\/www.grenoblemag.com\/article\/2750\/rave-party-des-astres-sonore-vaste-interdiction-prefectorale-dans-le-sud-de-l-isere-tout-le-week-end\" title=\"Rave party \u201cDes\u2019astres sonore\u201d : vaste interdiction pr\u00e9fectorale dans le sud de l\u2019Is\u00e8re tout le week-end\" target=\"_blank\" rel=\"nofollow noopener\"><br \/>\n\t\t\t\t\t\t\t\tLire la suite de l&rsquo;article sur Grenoblemag \u00bb<br \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"11 Avril 2026 La pr\u00e9fecture de l\u2019Is\u00e8re interdit tout rassemblement musical non autoris\u00e9 dans le sud du d\u00e9partement&hellip;\n","protected":false},"author":2,"featured_media":862428,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9566],"tags":[1111,66200,11,7733,66196,66213,66211,8279,2430,650,7734,66204,1777,674,66207,1011,27,66206,2731,66203,66201,4662,66212,66209,66202,12,1825,66205,66197,66198,66199,25,66208,66210],"class_list":{"0":"post-862427","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-grenoble","8":"tag-actu","9":"tag-actualite-grenoble","10":"tag-actualites","11":"tag-alpes","12":"tag-alpes-1-grenoble","13":"tag-alpes-de-hautes-provence-et-hautes-alpes","14":"tag-alpes-de-huez","15":"tag-alpes1","16":"tag-auvergne-rhone-alpes","17":"tag-cinema","18":"tag-ecoute","19":"tag-ecouter-alpes-1-grenoble","20":"tag-eu","21":"tag-europe","22":"tag-evenements-grenoble","23":"tag-fr","24":"tag-france","25":"tag-frequence-alpes-1-grenoble","26":"tag-grenoble","27":"tag-hits-grenoble","28":"tag-info-grenoble","29":"tag-journal","30":"tag-les-2-alpes","31":"tag-meteo-grenoble","32":"tag-musique-grenoble","33":"tag-news","34":"tag-radio","35":"tag-radio-en-ligne-grenoble","36":"tag-radio-grenoble","37":"tag-radio-isere","38":"tag-radio-locale-grenoble","39":"tag-republique-francaise","40":"tag-sorties-grenoble","41":"tag-trafic-grenoble"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/862427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=862427"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/862427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/862428"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=862427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=862427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=862427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}