{"id":872502,"date":"2026-04-16T08:10:12","date_gmt":"2026-04-16T08:10:12","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/872502\/"},"modified":"2026-04-16T08:10:12","modified_gmt":"2026-04-16T08:10:12","slug":"feria-de-la-crau-du-16-04-2026-au-19-04-2026-saint-martin-de-crau","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/872502\/","title":{"rendered":"Feria de la Crau &#8211; Du 16\/04\/2026 au 19\/04\/2026 &#8211; Saint-Martin-de-Crau"},"content":{"rendered":"<p class=\"spip\">Les traditions seront \u00e0 l\u2019honneur avec la nouvelle \u00e9dition de la Feria de la Crau. Orchestr\u00e9 par la Unica avec le soutien de la Municipalit\u00e9, cet \u00e9v\u00e9nement incontournable de la vie locale en perp\u00e9tue les coutumes. Au programme : le retour attendu des abrivados, les rendez-vous des aficionados aux ar\u00e8nes, les expositions et, bien s\u00fbr, les repas et soir\u00e9es bodega organis\u00e9s en centre-ville par les bars et restaurants. Autant de beaux instants festifs \u00e0 c\u00e9l\u00e9brer ensemble !<\/p>\n<p dir=\"auto\">Comme chaque ann\u00e9e, la Feria de la crau La unica, avec le soutien de la Municipalit\u00e9, propose de nombreuses manifestations tout public : exposition, stands d&rsquo;artistes et cr\u00e9ateurs, abrivados, soir\u00e9es bodega au Foirail et dans les bars et restaurants du centre-ville\u2026\u00a0<\/p>\n<p dir=\"auto\">Du 16 au 19 avril, Saint-Martin de Crau c\u00e9l\u00e8bre les traditions taurines locales et se pare de ses habits de lumi\u00e8re pour la traditionnelle Feria de la Crau. Un \u00e9v\u00e9nement incontournable sur la commune, organis\u00e9 par la Unica avec le soutien de la Municipalit\u00e9.<\/p>\n<p>Au programme\u00a0<a href=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/04\/12265.jpg\" data-fancybox=\"gallery\" class=\"grouped_elements\" rel=\"example_group\"><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/04\/12265.jpg\" class=\"include_img\" loading=\"lazy\"\/><\/a>La F\u00e9ria di Pichoun &#8211; 15 avril 2026<\/p>\n<p dir=\"auto\"><strong>\ud835\udde5\ud835\uddd8\ud835\uddda\ud835\udddf\ud835\uddd8\ud835\udde0\ud835\uddd8\ud835\udde1\ud835\udde7\ud835\uddd4\ud835\udde7\ud835\udddc\ud835\udde2\ud835\udde1 \ud835\uddd7\ud835\uddd8 \ud835\udddf\ud835\uddd4 \ud835\uddd6\ud835\udddc\ud835\udde5\ud835\uddd6\ud835\udde8\ud835\udddf\ud835\uddd4\ud835\udde7\ud835\udddc\ud835\udde2\ud835\udde1 \ud835\uddd8\ud835\udde7 \ud835\uddd7\ud835\udde8 \ud835\udde6\ud835\udde7\ud835\uddd4\ud835\udde7\ud835\udddc\ud835\udde2\ud835\udde1\ud835\udde1\ud835\uddd8\ud835\udde0\ud835\uddd8\ud835\udde1\ud835\udde7<\/strong><\/p>\n<p dir=\"auto\">La circulation et le stationnement seront r\u00e9glement\u00e9s par arr\u00eat\u00e9 municipal pour garantir la s\u00e9curit\u00e9 des visiteurs et le bon d\u00e9roulement de l\u2019\u00e9v\u00e9nement.<\/p>\n<p dir=\"auto\">\u00a0\ud835\udc79\ud835\udc86\ud835\udc95\ud835\udc93\ud835\udc90\ud835\udc96\ud835\udc97\ud835\udc86\ud835\udc9b \ud835\udc95\ud835\udc90\ud835\udc96\ud835\udc94 \ud835\udc8d\ud835\udc86\ud835\udc94 \ud835\ude56\ud835\ude67\ud835\ude67\ud835\ude5a\u0302\ud835\ude69\ud835\ude5a\u0301\ud835\ude68 \ud835\ude5a\ud835\ude69 \ud835\ude61\ud835\ude5a\ud835\ude68 \ud835\udc8a\ud835\udc8f\ud835\udc87\ud835\udc90\ud835\udc93\ud835\udc8e\ud835\udc82\ud835\udc95\ud835\udc8a\ud835\udc90\ud835\udc8f\ud835\udc94 \ud835\udc86\ud835\udc8f \ud835\udc8d\ud835\udc8a\ud835\udc86\ud835\udc8f \ud835\udc82\ud835\udc97\ud835\udc86\ud835\udc84 \ud835\udc8d\ud835\udc82 \ud835\udc6d\ud835\udc86\ud835\udc93\ud835\udc8a\ud835\udc82 \ud835\udc85\ud835\udc8a \ud835\udc77\ud835\udc8a\ud835\udc84\ud835\udc89\ud835\udc90\ud835\udc96\ud835\udc8f \ud835\udc86\ud835\udc95 \ud835\udc8d\ud835\udc82 \ud835\udc6d\ud835\udc86\ud835\udc93\ud835\udc8a\ud835\udc82 \ud835\udc85\ud835\udc86 \ud835\udc8d\ud835\udc82 \ud835\udc6a\ud835\udc93\ud835\udc82\ud835\udc96 \ud835\udc94\ud835\udc96\ud835\udc93 \ud835\udc84\ud835\udc86 \ud835\udc8d\ud835\udc8a\ud835\udc86\ud835\udc8f : <a tabindex=\"0\" href=\"https:\/\/www.saintmartindecrau.fr\/actualites\/arretes-municipaux-en-lien-avec-les-festivites\/?fbclid=IwZXh0bgNhZW0CMTAAYnJpZBEwbGZTT2ZBV3p6d25PbzFLUXNydGMGYXBwX2lkEDIyMjAzOTE3ODgyMDA4OTIAAR43WPeiKYywMRVeCCqKinrYt4Kyq79-BRD5HACBWwZBOlvGH3aBTNyef0vjBA_aem_z1fST9IOQZWsiPYTm_7a8g\" rel=\"nofollow noreferrer noopener noreferrer\" target=\"_blank\">https:\/\/www.saintmartindecrau.fr\/&#8230;\/arretes-municipaux&#8230;\/<\/a><\/p>\n<p>\t\t\t\t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Les traditions seront \u00e0 l\u2019honneur avec la nouvelle \u00e9dition de la Feria de la Crau. Orchestr\u00e9 par la&hellip;\n","protected":false},"author":2,"featured_media":872503,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9619],"tags":[1111,11,1777,674,1011,27,12,882,25,2310],"class_list":{"0":"post-872502","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-toulon","8":"tag-actu","9":"tag-actualites","10":"tag-eu","11":"tag-europe","12":"tag-fr","13":"tag-france","14":"tag-news","15":"tag-provence-alpes-cote-dazur","16":"tag-republique-francaise","17":"tag-toulon"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116413375609562110","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/872502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=872502"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/872502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/872503"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=872502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=872502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=872502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}