{"id":878032,"date":"2026-04-18T21:57:14","date_gmt":"2026-04-18T21:57:14","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/878032\/"},"modified":"2026-04-18T21:57:14","modified_gmt":"2026-04-18T21:57:14","slug":"nice-puel-presente-ses-condoleances-a-genesio","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/878032\/","title":{"rendered":"Nice : Puel pr\u00e9sente ses condol\u00e9ances \u00e0 Genesio"},"content":{"rendered":"<p>L\u2019OGC Nice a d\u00e9croch\u00e9 un point pr\u00e9cieux sur la pelouse du <a href=\"https:\/\/www.footmercato.net\/club\/losc\/\" rel=\"nofollow noopener\" target=\"_blank\">Lille<\/a> (0-0), ce samedi soir, lors de la 30e journ\u00e9e de <a href=\"https:\/\/www.footmercato.net\/france\/ligue-1\/\" rel=\"nofollow noopener\" target=\"_blank\">Ligue 1<\/a>. Toujours engag\u00e9 dans la lutte pour le maintien, le club azur\u00e9en a livr\u00e9 une prestation solide. Apr\u00e8s la rencontre, son entra\u00eeneur <a href=\"https:\/\/www.footmercato.net\/entraineur\/claude-puel\" rel=\"nofollow noopener\" target=\"_blank\">Claude Puel<\/a> s\u2019est montr\u00e9 satisfait de l\u2019\u00e9tat d\u2019esprit affich\u00e9 par ses joueurs face \u00e0 une \u00e9quipe lilloise en course pour l\u2019Europe. \u00abJ\u2019ai appr\u00e9ci\u00e9 une \u00e9quipe qui d\u00e9fendait avec des valeurs, qui a bien d\u00e9fendu sur des aspects pour coulisser. On a essay\u00e9 de bien repartir de derri\u00e8re. On marque un but sur une chaussure trop grande, mais en seconde p\u00e9riode on a surtout r\u00e9sist\u00e9 avec de l\u2019abn\u00e9gation, c\u2019est bien. Ma m\u00e9thode ? \u00catre proche des joueurs, \u00e9galement de temps en temps leur dire les choses. M\u00eame si \u00e7a ne fait pas plaisir, on se le dit. Il y a eu une bonne r\u00e9ponse. On a un calendrier difficile, je l\u2019ai dit apr\u00e8s le match du Havre qu\u2019on allait gratter des points partout et \u00e0 des clubs qui jouent la course \u00e0 la Ligue des Champions, il faut continuer\u00bb.<\/p>\n<p>            La suite apr\u00e8s cette publicit\u00e9<\/p>\n<p>Il a aussi tenu \u00e0 ajouter de jolis mots pour son confr\u00e8re lillois qui traverse un deuil. \u00ab <a href=\"https:\/\/www.footmercato.net\/entraineur\/bruno-genesio\" rel=\"nofollow noopener\" target=\"_blank\">Bruno<\/a> Genesio ? Je lui pr\u00e9sente toute mes condol\u00e9ances pour son papa. Il fait du tr\u00e8s bon travail ici, il a su temp\u00e9rer dans une situation difficile. C\u2019est le m\u00e9tier de rester soft, de prot\u00e9ger son groupe. Ils (Ndlr, les Lillois) sont bien lanc\u00e9s pour la course \u00e0 la Ligue des Champions \u00bb, a indiqu\u00e9 le technicien azur\u00e9en.<\/p>\n<p>\n    Pub. le 18\/04\/2026 23:54<br \/>\n            &#8211; MAJ le 18\/04\/2026 23:55\n    <\/p>\n","protected":false},"excerpt":{"rendered":"L\u2019OGC Nice a d\u00e9croch\u00e9 un point pr\u00e9cieux sur la pelouse du Lille (0-0), ce samedi soir, lors de&hellip;\n","protected":false},"author":2,"featured_media":878033,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2819],"tags":[1111,11,1777,674,1011,27,12,2401,882,25],"class_list":{"0":"post-878032","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nice","8":"tag-actu","9":"tag-actualites","10":"tag-eu","11":"tag-europe","12":"tag-fr","13":"tag-france","14":"tag-news","15":"tag-nice","16":"tag-provence-alpes-cote-dazur","17":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116427951116831581","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/878032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=878032"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/878032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/878033"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=878032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=878032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=878032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}