{"id":879206,"date":"2026-04-19T12:31:38","date_gmt":"2026-04-19T12:31:38","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/879206\/"},"modified":"2026-04-19T12:31:38","modified_gmt":"2026-04-19T12:31:38","slug":"toulouse-le-24eme-rallye-citoyen-au-lycee-bellevue","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/879206\/","title":{"rendered":"Toulouse : Le 24\u00e8me rallye citoyen au lyc\u00e9e Bellevue"},"content":{"rendered":"<p><strong>Communiqu\u00e9 de l\u2019officier de communication Alice Billy de la D\u00e9l\u00e9gation militaire d\u00e9partementale de la Haute Garonne<\/strong><\/p>\n<p><strong>Ce jeudi 16 avril, plus de 200 coll\u00e9giens et lyc\u00e9ens issus d\u2019un dizaine d\u2019\u00e9tablissements de la m\u00e9tropole toulousaine se sont retrouv\u00e9s au lyc\u00e9e Bellevue pour participer au 24\u00e8me rallye citoyen.<\/strong><\/p>\n<p><strong>Dans un contexte o\u00f9 les enjeux de r\u00e9silience et de coh\u00e9sion nationale se renforcent, cette journ\u00e9e immersive, organis\u00e9e par le trin\u00f4me acad\u00e9mique (Minist\u00e8re de l\u2019Education nationale, Minist\u00e8re des Arm\u00e9es, Minist\u00e8re de l\u2019Agriculture et IHEDN), vise \u00e0 sensibiliser les jeunes aux diff\u00e9rentes formes d\u2019engagement gr\u00e2ce \u00e0 une approche participative et concr\u00e8te.<\/strong><\/p>\n<p>R\u00e9partis en \u00e9quipes, les \u00e9l\u00e8ves ont pris part \u00e0 vingt ateliers propos\u00e9s par de nombreux acteurs engag\u00e9s (SDIS, associations civiles et militaires, don du sang, pr\u00e9fecture, police, EPIDE, arm\u00e9es\u2026).<\/p>\n<p>D\u00e9fis pratiques, mise en situation et \u00e9changes ont rythm\u00e9 la journ\u00e9e, permettant aux participants de se challenger dans un esprit ludique, exigeant et fair-play.<\/p>\n<p>Lieu charg\u00e9 d\u2019histoire, le lyc\u00e9e Bellevue incarne une m\u00e9moire forte de l\u2019engagement (Combat de Pech-David, prise en charge des bless\u00e9s de la premi\u00e8re guerre, \u00e9cole de l\u2019air temporaire\u2026).<\/p>\n<p>Au fil des ateliers, les \u00e9l\u00e8ves ont d\u00e9couvert que l\u2019engagement ne se limite pas \u00e0 un cadre unique mais constitue une responsabilit\u00e9 collective, accessible \u00e0 tous.<\/p>\n<p>\u00ab\u00a0Ce rallye permet aux jeunes de comprendre concr\u00e8tement ce que signifie s\u2019engager et l\u2019\u00e9ventail des possibilit\u00e9s qui s\u2019offrent \u00e0 eux\u00a0\u00bb, souligne une enseignante. Ou un autre enseignant confie avoir d\u00e9couvert ses \u00e9l\u00e8ves lors de cette journ\u00e9e.<\/p>\n<p>Tout au long de la journ\u00e9e, les participants ont pu exp\u00e9rimenter diff\u00e9rentes formes d\u2019engagement\u00a0:<\/p>\n<p>\u00d8\u00a0 Participation \u00e0 la vie d\u00e9mocratique\u00a0;<\/p>\n<p>\u00d8\u00a0 Engagement associatif et b\u00e9n\u00e9vole\u00a0;<\/p>\n<p>\u00d8\u00a0 Service civique\u00a0;<\/p>\n<p>\u00d8\u00a0 R\u00e9serve militaire et citoyenne\u00a0;<\/p>\n<p>\u00d8\u00a0 Solidarit\u00e9 et entraide au quotidien\u00a0;<\/p>\n<p>\u00d8\u00a0 Protection de l\u2019environnement.<\/p>\n<p>Chaque atelier permettait de remporter des points, donnant lieu \u00e0 un classement et \u00e0 la remise des prix dans une ambiance f\u00e9d\u00e9ratrice et conviviale.<\/p>\n<p>A del\u00e0 de la dimension comp\u00e9titive, cette journ\u00e9e a permis aux \u00e9l\u00e8ves de mieux se conna\u00eetre, de renforcer leur esprit d\u2019\u00e9quipe et de prendre conscience de leur r\u00f4le dans la soci\u00e9t\u00e9. Comme l\u2019illustre bien les propos d\u2019Anastasia, \u00e9l\u00e8ve de 3\u00e8me au coll\u00e8ge Ren\u00e9 Cassin \u00ab\u00a0Journ\u00e9e tr\u00e8s agr\u00e9able, les ateliers nous accueillent avec le sourire et sont tr\u00e8s sympathiques. De plus, notre \u00e9quipe est tr\u00e8s soud\u00e9e et nous nous entendons super bien avec le groupe qui est avec nous. La diversit\u00e9 des ateliers est tr\u00e8s enrichissante, l\u2019abord de plusieurs sujet et diff\u00e9rentes activit\u00e9s mises \u00e0 notre disposition est superbe.\u00a0\u00bb<\/p>\n<p>Une journ\u00e9e qui montre que l\u2019engagement n\u2019est pas une notion abstraite mais une exp\u00e9rience concr\u00e8te accessible \u00e0 tous.<\/p>\n<p>Rendez-vous l\u2019ann\u00e9e prochaine pour les 20 ans du dispositif\u00a0!<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Communiqu\u00e9 de l\u2019officier de communication Alice Billy de la D\u00e9l\u00e9gation militaire d\u00e9partementale de la Haute Garonne Ce jeudi&hellip;\n","protected":false},"author":2,"featured_media":879207,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2816],"tags":[1111,11,24794,1777,674,1011,27,94584,12,2680,94585,25,2312],"class_list":{"0":"post-879206","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-toulouse","8":"tag-actu","9":"tag-actualites","10":"tag-engagement","11":"tag-eu","12":"tag-europe","13":"tag-fr","14":"tag-france","15":"tag-lycees-toulousains","16":"tag-news","17":"tag-occitanie","18":"tag-rallye-citoyen","19":"tag-republique-francaise","20":"tag-toulouse"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116431387981130014","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/879206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=879206"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/879206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/879207"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=879206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=879206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=879206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}