{"id":897028,"date":"2026-04-28T01:19:16","date_gmt":"2026-04-28T01:19:16","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/897028\/"},"modified":"2026-04-28T01:19:16","modified_gmt":"2026-04-28T01:19:16","slug":"entraineur-suspendu-une-peine-bien-plus-contraignante-en-ligue-des-champions-quen-ligue-1","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/897028\/","title":{"rendered":"Entra\u00eeneur suspendu\u00a0: une peine bien plus contraignante en Ligue des champions qu&rsquo;en Ligue\u00a01"},"content":{"rendered":"<p>En vous abonnant, vous acc\u00e9dez<br data-v-ce6ccdc0=\"\"\/><b data-v-ce6ccdc0=\"\">\u00e0 la source de r\u00e9f\u00e9rence<\/b><br data-v-ce6ccdc0=\"\"\/> sur l&rsquo;actu sportive.En vous abonnant, vous acc\u00e9dez <b data-v-ce6ccdc0=\"\">\u00e0 la source de r\u00e9f\u00e9rence<\/b> sur l&rsquo;actu sportive.<\/p>\n<p>accepter les cookies et acc\u00e9der<br data-v-ce6ccdc0=\"\"\/> \u00e0 L&rsquo;\u00c9quipe gratuitementaccepter les cookies et acc\u00e9der \u00e0 L&rsquo;\u00c9quipe gratuitement<\/p>\n<p> L&rsquo;\u00c9quipe, <a class=\"Link\" href=\"https:\/\/www.lequipe.fr\/Page\/Informations-legales-de-l-equipe-et-les-societes-de-son-groupe\/1185337\" rel=\"noopener nofollow\" external=\"\" data-v-ce6ccdc0=\"\" data-v-9058edc2=\"\" target=\"_blank\"> les soci\u00e9t\u00e9s de son groupe<\/a> et  leurs 278 partenaires  utilisent des cookies ou traceurs pour stocker et\/ou acc\u00e9der \u00e0 des informations sur votre terminal et traiter des donn\u00e9es personnelles vous concernant. Cela nous permet de vous afficher de la publicit\u00e9 personnalis\u00e9e en fonction de votre navigation, de vos donn\u00e9es de profil ou de votre localisation, de personnaliser le contenu \u00e9ditorial, de mesurer l&rsquo;audience de notre site et de permettre l&rsquo;interaction avec les r\u00e9seaux sociaux. Pour acc\u00e9der gratuitement au site (hors contenus exclusifs abonn\u00e9s), vous devez accepter l&rsquo;utilisation des traceurs de publicit\u00e9 personnalis\u00e9e, par L&rsquo;\u00c9quipe et des tiers partenaires. En cas de refus, navigation et fonctionnalit\u00e9s seront limit\u00e9es sur le site. Vos pr\u00e9f\u00e9rences s&rsquo;appliqueront uniquement \u00e0 nos sites et pourront \u00eatre modifi\u00e9es \u00e0 tout moment via le menu \u00ab  param\u00e9trer mon consentement  \u00bb. Plus d&rsquo;informations : <a class=\"Link\" href=\"https:\/\/www.lequipe.fr\/Page\/Politique-de-confidentialite\/1183897\" rel=\"noopener nofollow\" external=\"\" data-v-ce6ccdc0=\"\" data-v-9058edc2=\"\" target=\"_blank\">politique de confidentialit\u00e9<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"En vous abonnant, vous acc\u00e9dez\u00e0 la source de r\u00e9f\u00e9rence sur l&rsquo;actu sportive.En vous abonnant, vous acc\u00e9dez \u00e0 la&hellip;\n","protected":false},"author":2,"featured_media":897029,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1888],"tags":[1111,1928,11,1927,86760,4782,94759,88127,1777,674,63,1011,27,447,12,1926,626,1925,92,94760,25,23077,54897],"class_list":{"0":"post-897028","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-paris","8":"tag-actu","9":"tag-actu-paris","10":"tag-actualites","11":"tag-actualites-paris","12":"tag-actus-et-infos","13":"tag-bayern-munich","14":"tag-demi-finales-aller","15":"tag-etienne-moatti","16":"tag-eu","17":"tag-europe","18":"tag-football","19":"tag-fr","20":"tag-france","21":"tag-ligue-des-champions","22":"tag-news","23":"tag-news-paris","24":"tag-paris","25":"tag-paris-news","26":"tag-paris-sg","27":"tag-paris-sg-bayern-munich","28":"tag-republique-francaise","29":"tag-saison-2025-2026","30":"tag-vincent-kompany"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116479706163231888","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/897028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=897028"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/897028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/897029"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=897028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=897028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=897028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}