{"id":904489,"date":"2026-05-01T11:54:26","date_gmt":"2026-05-01T11:54:26","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/904489\/"},"modified":"2026-05-01T11:54:26","modified_gmt":"2026-05-01T11:54:26","slug":"un-petit-millier-de-personnes-defilent-dans-les-rues-de-nice-pour-le-1er-mai-2026","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/904489\/","title":{"rendered":"Un petit millier de personnes d\u00e9filent dans les rues de Nice pour le 1er mai 2026"},"content":{"rendered":"<p class=\"fs-5 \">\u00ab Le<strong> 1er mai<\/strong> est et doit demeurer un jour f\u00e9ri\u00e9, ch\u00f4m\u00e9 et pay\u00e9 \u00bb, s\u2019\u00e9gosille au micro Alexandre Latruffe, le secr\u00e9taire g\u00e9n\u00e9ral de l\u2019union locale CGT.<\/p>\n<p class=\"fs-5 \">Le <a href=\"https:\/\/www.nicematin.com\/societe\/social\/la-grogne-monte-pourquoi-les-manifestants-defilent-a-cannes-ce-vendredi-1er-mai-10678949\" rel=\"nofollow noopener\" target=\"_blank\">traditionnel cort\u00e8ge revendicatif<\/a> vient d\u2019arriver sur la place Garibaldi, pile \u00e0 l\u2019heure du d\u00e9jeuner, et le syndicaliste insiste sur la valeur symbolique de cette journ\u00e9e internationale de lutte pour les droits des travailleurs c\u00e9l\u00e9br\u00e9e \u00ab depuis 140 ans dans 163 pays \u00bb.<\/p>\n<p>    N\u00e9 \u00ab\u00a0dans la r\u00e9pression et le sang\u00a0\u00bb<\/p>\n<p class=\"fs-5 \">Dans les rangs des manifestants, Patrice Cuti en rappelle l\u2019histoire n\u00e9e \u00ab \u00e0 Chicago \u00bb en 1896 alors que les travailleurs am\u00e9ricains \u00ab r\u00e9clamaient la journ\u00e9e de 8 heures \u00bb, \u00ab dans la r\u00e9pression et le sang \u00bb, \u00ab comme \u00e0 Fourmies en France \u00bb \u00e0 la fin du XIXe si\u00e8cle.<\/p>\n<p class=\"fs-5 \">Pour lui, le 1er Mai ce n\u2019est pas \u00ab la f\u00eate du travail \u00bb d\u00e9cr\u00e9t\u00e9e \u00ab par les p\u00e9tainistes \u00bb. C\u2019est \u00ab un <strong>symbole tr\u00e8s important de l\u2019histoire de la lutte des classes<\/strong> \u00bb, insiste ce militant fr\u00e9jusien qui a fait le d\u00e9placement pour le d\u00e9fendre.<\/p>\n<p class=\"fs-5 \">Car la <a href=\"https:\/\/www.nicematin.com\/societe\/social\/video-manif-du-1er-mai-plusieurs-centaines-de-personnes-dans-les-rues-de-toulon-45854\" rel=\"nofollow noopener\" target=\"_blank\">traditionnelle manif du 1er mai<\/a> avait une dimension toute particuli\u00e8re ce vendredi, \u00e0 <strong>Nice <\/strong>comme partout en France.<\/p>\n<p class=\"fs-5 \">Le gouvernement envisage en effet <a href=\"https:\/\/www.nicematin.com\/societe\/il-nous-fallait-plus-de-temps-pour-s-organiser-a-menton-les-boulangers-et-les-fleuristes-reagissent-a-l-autorisation-d-ouverture-ce-vendredi-1-mai-il-nous-fallait-plus-de-temps-pour-s-organiser-10678836\" rel=\"nofollow noopener\" target=\"_blank\">d\u2019autoriser l\u2019ouverture de certains commerces comme les boulangeries et les fleuristes<\/a>.<\/p>\n<p class=\"fs-5 \">Julien Picot, le chef de file des communistes Ni\u00e7ois, estime qu\u2019il s\u2019agit d\u2019un cheval de Troie \u00ab\u00a0de la droite et de l\u2019extr\u00eame droite\u00a0\u00bb pour revenir sur cet acquis des travailleurs.<\/p>\n<p class=\"fs-5 \">\u00ab Car certaines cha\u00eenes de boulangerie emploient en r\u00e9alit\u00e9 plusieurs milliers de salari\u00e9s. Revenir sur le 1er mai c\u2019est les contraindre \u00e0 aller travailler. Et apr\u00e8s eux&#8230; tous les autres \u00bb, d\u00e9fend l\u2019\u00e9lu municipal.<\/p>\n<p>    \u00ab\u00a0Plus de badauds que de manifestants sur la Prom\u2019\u00a0\u00bb<\/p>\n<p class=\"fs-5 \">Dans les rangs du <strong>cort\u00e8ge<\/strong>, ils sont nombreux \u00e0 partager son avis. Et \u00e0 d\u00e9plorer, comme Pascale, qui d\u00e9plore qu\u2019il y ait \u00ab plus de badauds qui se baladent sur la Prom que de manifestants \u00bb. <\/p>\n<p class=\"fs-5 \">\u00ab Il devrait y avoir plus de monde \u00bb, souffle cette Lorraine d\u2019origine qui est venue avec ses parents \u00e2g\u00e9s de 92 ans pour \u00ab poursuivre le combat qu\u2019ils ont men\u00e9 toute leur vie dans les usines du bassin minier \u00bb.<\/p>\n<p class=\"fs-5 \">Lorsque la manifestation s\u2019est mise en route vers 10 heures face au Th\u00e9\u00e2tre de Verdure, ils n\u2019\u00e9taient que quelques centaines. <strong>Un millier tout au plus<\/strong> \u00e0 l\u2019arriv\u00e9e place Garibaldi.<\/p>\n<p class=\"fs-5 \">\u00ab C\u2019est peu\u00a0\u00bb, reconna\u00eet un \u00e9lu azur\u00e9en, qui pensait que le pav\u00e9 ni\u00e7ois serait \u00ab\u00a0noir de monde compte tenu de l\u2019enjeu de ce 1er mai \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"\u00ab Le 1er mai est et doit demeurer un jour f\u00e9ri\u00e9, ch\u00f4m\u00e9 et pay\u00e9 \u00bb, s\u2019\u00e9gosille au micro&hellip;\n","protected":false},"author":2,"featured_media":904490,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2819],"tags":[1111,11,1777,674,1011,27,12,2401,882,25],"class_list":{"0":"post-904489","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nice","8":"tag-actu","9":"tag-actualites","10":"tag-eu","11":"tag-europe","12":"tag-fr","13":"tag-france","14":"tag-news","15":"tag-nice","16":"tag-provence-alpes-cote-dazur","17":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116499190104193398","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/904489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=904489"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/904489\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/904490"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=904489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=904489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=904489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}