{"id":904668,"date":"2026-05-01T13:56:23","date_gmt":"2026-05-01T13:56:23","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/904668\/"},"modified":"2026-05-01T13:56:23","modified_gmt":"2026-05-01T13:56:23","slug":"tennis-3e-division-nationale-difficile-apprentissage-pour-lasptt-agen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/904668\/","title":{"rendered":"Tennis \u2013 3e division nationale\u00a0: difficile apprentissage pour l\u2019ASPTT Agen"},"content":{"rendered":"<p>\n                                                                    l&rsquo;essentiel<br \/>\n                                                                Tennis agenais en pleine ascension. Pour sa premi\u00e8re saison en Nationale\u202f3, l\u2019ASPTT\u202fAgen s\u2019incline de peu face \u00e0 Entraigues apr\u00e8s un super tie-break d\u00e9cisif, tandis que son \u00e9quipe\u202fII brille \u00e0 N\u00eemes avec un succ\u00e8s 5\u20111.\n                            <\/p>\n<p>L\u2019\u00e9quipe fanion de l\u2019ASPTT Agen qui \u00e9volue pour la premi\u00e8re fois de son histoire au niveau de la 3e division nationale, a d\u00fb s\u2019incliner, dimanche 26\u00a0avril, sur ses installations de Saint-Hilaire-de-Lusignan, contre l\u2019US Smash club Entraigues (Vaucluse).<\/p>\n<p class=\"std-elt__inline\">\n        <strong>\u00c0 lire aussi :<\/strong><br \/>\n        <a href=\"https:\/\/www.ladepeche.fr\/2026\/03\/21\/tennis-championnats-par-equipes-cest-parfait-de-debuter-ainsi-lasptt-agen-commence-par-une-victoire-contre-cazaux-13283805.php\" rel=\"nofollow noopener\" target=\"_blank\">Tennis \u2013 Championnats par \u00e9quipes\u00a0: \u00ab\u00a0C\u2019est parfait de d\u00e9buter ainsi\u2026\u00a0\u00bb L\u2019ASPTT Agen commence par une victoire contre Cazaux<\/a>\n    <\/p>\n<p>La matin\u00e9e n\u2019avait pourtant pas trop mal d\u00e9but\u00a0\u00bb puisqu\u2019\u00e0 l\u2019issue des quatre simples, les deux \u00e9quipes se retrouvaient \u00e0 deux points partout. On notera la belle victoire du jeune Enzo Dotzis (18 ans) qui s\u2019impose de fort belle mani\u00e8re (6\/4\u00a0; 6\/1) contre un joueur class\u00e9 qu\u2019un \u00e9chelon en dessous de lui. La hi\u00e9rarchie des classements ayant d\u2019ailleurs \u00e9t\u00e9 parfaitement respect\u00e9e lors des quatre rencontres.<\/p>\n<p>Un double perdu au super tie-break<\/p>\n<p>Si le deuxi\u00e8me double a \u00e9t\u00e9 remport\u00e9 ais\u00e9ment par les adversaires, c\u2019est lors du premier que les Agenais ont laiss\u00e9 passer la possibilit\u00e9 de terminer la rencontre sur un prometteur score de parit\u00e9. Jo\u00ebl Alan Barreiro et Diego Flores Fernandez avaient pourtant r\u00e9ussi \u00e0 \u00e9galiser \u00e0 un set partout, apr\u00e8s avoir perdu la premi\u00e8re manche. Tout s\u2019est donc jou\u00e9 dans un super tie-break d\u00e9cisif qu\u2019ils ont perdu sur le score de 10 \u00e0 7.<br \/>Le d\u00e9placement, ce dimanche \u00e0 Aix-en-Provence, contre une \u00e9quipe qui a d\u00fb s\u2019incliner lors de la premi\u00e8re journ\u00e9e (\u00e0 l\u2019ext\u00e9rieur contre le Stade Toulousain) s\u2019av\u00e8re d\u00e9j\u00e0 d\u00e9cisif.<\/p>\n<p>L\u2019\u00e9quipe II s\u2019impose \u00e0 N\u00eemes<\/p>\n<p>L\u2019\u00e9quipe II de l\u2019ASPTT Agen d\u00e9butait, quant \u00e0 elle, son championnat de National 4 \u00e0 N\u00eemes et est revenue avec une fort belle victoire (5 \u00e0 1). Cette \u00e9quipe a une belle carte \u00e0 jouer dans cette poule A de N4 et devra confirmer, \u00e0 domicile ce dimanche 3\u00a0mai, contre Valence tennis Epervi\u00e8re.<\/p>\n<p class=\"std-elt__inline\">\n        <strong>\u00c0 lire aussi :<\/strong><br \/>\n        <a href=\"https:\/\/www.ladepeche.fr\/2026\/04\/30\/le-pruneau-dagen-se-muscle-lembleme-du-sud-ouest-sallie-a-lathlete-hyrox-arnaud-pejac-pour-seduire-les-sportifs-13350877.php\" rel=\"nofollow noopener\" target=\"_blank\">Le Pruneau d\u2019Agen se muscle\u00a0: l\u2019embl\u00e8me du Sud-Ouest s\u2019allie \u00e0 l\u2019athl\u00e8te Hyrox Arnaud P\u00e9jac pour s\u00e9duire les sportifs<\/a>\n    <\/p>\n<p>En division sup\u00e9rieure r\u00e9gionale B (DSR B), l\u2019\u00e9quipe III avait perdu \u00e0 domicile contre le TC Artigues lors de la cinqui\u00e8me et derni\u00e8re journ\u00e9e, le 19\u00a0avril. Cette \u00e9quipe termine \u00e0 une honorable quatri\u00e8me place qui lui garantit le maintien. Dans cette m\u00eame poule, l\u2019\u00e9quipe I de l\u2019AS Passage d\u2019Agen a accumul\u00e9 cinq d\u00e9faites. Par contre, dans la poule H, l\u2019\u00e9quipe I du TC Marmande termine premi\u00e8re en \u00e9tant rest\u00e9e invaincue (quatre victoires et un nul).<\/p>\n","protected":false},"excerpt":{"rendered":"l&rsquo;essentiel Tennis agenais en pleine ascension. Pour sa premi\u00e8re saison en Nationale\u202f3, l\u2019ASPTT\u202fAgen s\u2019incline de peu face \u00e0&hellip;\n","protected":false},"author":2,"featured_media":904669,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1415],"tags":[8837,1011,27,8838,517,60,1467],"class_list":{"0":"post-904668","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tennis","8":"tag-agen","9":"tag-fr","10":"tag-france","11":"tag-lot-et-garonne","12":"tag-sport","13":"tag-sports","14":"tag-tennis"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116499669805715256","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/904668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=904668"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/904668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/904669"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=904668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=904668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=904668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}