{"id":910450,"date":"2026-05-04T11:23:33","date_gmt":"2026-05-04T11:23:33","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/910450\/"},"modified":"2026-05-04T11:23:33","modified_gmt":"2026-05-04T11:23:33","slug":"video-un-monster-truck-hors-de-controle-fonce-dans-la-foule-lors-dun-show-une-fillette-de-10-et-deux-autres-personnes-meurent-lors-de-laccident","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/910450\/","title":{"rendered":"VIDEO Un monster truck hors de contr\u00f4le fonce dans la foule lors d\u2019un show\u00a0: une fillette de 10 et deux autres personnes meurent lors de l\u2019accident"},"content":{"rendered":"<p>\n                                                                Au moins trois personnes, dont une fillette, ont perdu la vie et 38 autres ont \u00e9t\u00e9 bless\u00e9es dimanche \u00e0 Popay\u00e1n, dans le sud-ouest de la Colombie, lorsqu\u2019un monster truck a percut\u00e9 la foule lors d\u2019un spectacle automobile. La conductrice, incapable de freiner apr\u00e8s une cascade, a franchi les barri\u00e8res de s\u00e9curit\u00e9 et fonc\u00e9 sur les spectateurs. Les autorit\u00e9s locales ont annonc\u00e9 l\u2019ouverture d\u2019une enqu\u00eate pour d\u00e9terminer les causes de cet accident dramatique.\n                            <\/p>\n<p>Au moins trois personnes sont mortes et 38 autres ont \u00e9t\u00e9 bless\u00e9es dimanche lors d\u2019un spectacle automobile dans le sud-ouest de la Colombie, lorsqu\u2019un monster truck a percut\u00e9 des dizaines de spectateurs, ont indiqu\u00e9 les autorit\u00e9s.<\/p>\n<p>Le bilan est pass\u00e9 de deux \u00e0 trois morts, a indiqu\u00e9 dans la soir\u00e9e sur le r\u00e9seau social X Juan Carlos Mu\u00f1oz, maire de la ville de Popay\u00e1n, o\u00f9 l\u2019accident s\u2019est produit.<\/p>\n<p>\u00ab\u00a0Nous sommes profond\u00e9ment attrist\u00e9s par cet accident\u00a0\u00bb<\/p>\n<p>Des images circulant sur les r\u00e9seaux sociaux montrent le v\u00e9hicule, un 4X4 aux roues surdimensionn\u00e9es connu sous le nom de monster truck, en train de franchir un parcours d\u2019obstacles pendant une d\u00e9monstration.<\/p>\n<blockquote data-class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">BREAKING: Monster truck plows into crowd during event in Popayan, Colombia, killing 2 people and injuring 38 others, authorities say. Reports say the driver lost control. <a href=\"https:\/\/t.co\/1tsgirHO4a\" rel=\"nofollow\">pic.twitter.com\/1tsgirHO4a<\/a><\/p>\n<p>\u2014 AZ Intel (@AZ_Intel_) <a href=\"https:\/\/twitter.com\/AZ_Intel_\/status\/2051095027191885901?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">May 4, 2026<\/a><\/p><\/blockquote>\n<p>La conductrice n\u2019est pas parvenue \u00e0 freiner apr\u00e8s une cascade et, subitement, son v\u00e9hicule s\u2019est pr\u00e9cipit\u00e9 vers les spectateurs, apr\u00e8s avoir renvers\u00e9 les barri\u00e8res m\u00e9talliques qui s\u00e9paraient le public de la piste.<\/p>\n<p>\u00ab\u00a0Nous sommes profond\u00e9ment attrist\u00e9s par cet accident [\u2026] qui a fait, selon des chiffres provisoires, plus de 38 bless\u00e9s et 3 morts\u00a0\u00bb, a d\u00e9clar\u00e9 M. Mu\u00f1oz.<\/p>\n<p>Une fillette parmi les victimes<\/p>\n<p>Parmi les personnes d\u00e9c\u00e9d\u00e9es figure une fillette et plusieurs autres mineurs ont \u00e9t\u00e9 bless\u00e9s, ont rapport\u00e9 les m\u00e9dias locaux.<\/p>\n<p>Les pompiers et les ambulanciers ont pris en charge les bless\u00e9s, certains d\u2019entre eux ayant \u00e9t\u00e9 transport\u00e9s dans des h\u00f4pitaux de la ville, selon Octavio Guzm\u00e1n, gouverneur du d\u00e9partement du Cauca, dont la capitale est Popay\u00e1n.<\/p>\n<p>Le maire de la ville a dit avoir ordonn\u00e9 l\u2019ouverture d\u2019une \u00ab\u00a0enqu\u00eate rigoureuse\u00a0\u00bb afin de faire la lumi\u00e8re sur cet accident, qui n\u2019aurait \u00ab\u00a0jamais d\u00fb se produire\u00a0\u00bb.<\/p>\n<p>                                                                                                                                                                                                        <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Au moins trois personnes, dont une fillette, ont perdu la vie et 38 autres ont \u00e9t\u00e9 bless\u00e9es dimanche&hellip;\n","protected":false},"author":2,"featured_media":910451,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[11,118,1011,27,14,12,28],"class_list":{"0":"post-910450","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-international","8":"tag-actualites","9":"tag-faits-divers","10":"tag-fr","11":"tag-france","12":"tag-international","13":"tag-news","14":"tag-world"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116516055105276834","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/910450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=910450"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/910450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/910451"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=910450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=910450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=910450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}