{"id":910452,"date":"2026-05-04T11:24:17","date_gmt":"2026-05-04T11:24:17","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/910452\/"},"modified":"2026-05-04T11:24:17","modified_gmt":"2026-05-04T11:24:17","slug":"il-y-avait-beaucoup-de-jalousie-les-proches-de-manon-relandeau-parlent-dun-couple-qui-ne-fonctionnait-pas-normalement","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/910452\/","title":{"rendered":"\u00ab\u00a0Il y avait beaucoup de jalousie\u00a0\u00bb\u00a0: les proches de Manon Relandeau parlent d\u2019un couple \u00ab\u00a0qui ne fonctionnait pas normalement\u00a0\u00bb"},"content":{"rendered":"<p class=\"paragraph text_align_left lp-f-body-02\">Elle avait \u00ab pris conscience que son couple ne fonctionnait pas normalement \u00bb. Une semaine apr\u00e8s l\u2019interpellation d\u2019<a href=\"https:\/\/www.leparisien.fr\/faits-divers\/une-enquete-ouverte-apres-la-disparition-dune-mere-et-de-son-bebe-de-15-mois-en-loire-atlantique-son-conjoint-a-fui-a-letranger-20-04-2026-6JNTBNCB4JCDZFQXJY6GJKFO2E.php\" rel=\"nofollow noopener\" target=\"_blank\">Abdelkarim B.<\/a>, soup\u00e7onn\u00e9 d\u2019\u00eatre impliqu\u00e9 dans la disparition de sa conjointe, Manon Relandeau, les proches de la jeune femme de 31 ans sont revenus, aupr\u00e8s de nos confr\u00e8res de <a href=\"https:\/\/www.ouest-france.fr\/faits-divers\/disparition\/disparition-de-manon-relandeau-une-femme-rayonnante-un-couple-qui-ne-fonctionnait-pas-normalement-4cbf1afc-455e-11f1-8e6a-4938cf63b665\" target=\"_blank\" rel=\"noreferrer nofollow noopener\">Ouest-France<\/a>, sur la relation qu\u2019entretenait le couple.<\/p>\n<p class=\"\">Dans les mois qui ont pr\u00e9c\u00e9d\u00e9 la disparition de Manon Relandeau, introuvable depuis le 27 mars dernier, la relation entre la jeune femme et son compagnon de 41 ans s\u2019\u00e9tait nettement d\u00e9grad\u00e9e, <a href=\"https:\/\/www.leparisien.fr\/faits-divers\/disparition-de-manon-la-jeune-femme-avait-rendez-vous-avec-une-association-daide-aux-victimes-de-violences-conjugales-28-04-2026-EP7FAOJNKBFSZMFEDDMZFPBM5U.php\" target=\"_blank\" rel=\"noreferrer nofollow noopener\">laissant place aux insultes et aux menaces<\/a>, selon nos informations.<\/p>\n<p>\u00ab Il y avait beaucoup de jalousie \u00bb<\/p>\n<p class=\"\">\u00ab Il y avait beaucoup de jalousie, il l\u2019emp\u00eachait de parler \u00e0 des hommes, la coupait de sa famille \u00bb, se souvient sa marraine aupr\u00e8s de nos confr\u00e8res. <a href=\"https:\/\/www.leparisien.fr\/faits-divers\/je-suis-innocent-depuis-lalgerie-abdelkarim-b-se-defend-sur-un-live-tiktok-davoir-tue-sa-compagne-manon-relandeau-28-04-2026-NAP54RHKUVDBNKPRU5D2WKFYWA.php\" target=\"_blank\" rel=\"noreferrer nofollow noopener\">Au cours d\u2019un live TikTok,<\/a> Abdelkarim B., qui a quitt\u00e9 la France pour l\u2019Alg\u00e9rie le 2 avril dernier avec leur petite fille de 15 mois, Inaya, a reconnu avoir install\u00e9 des cam\u00e9ras \u00e0 leur domicile pour surveiller ce qu\u2019il s\u2019y passait. \u00ab J\u2019ai tap\u00e9 des jours de garde \u00e0 vue \u00e0 cause de ma copine \u00bb, a-t-il d\u00e9clar\u00e9, sans pr\u00e9ciser de quelle \u00ab copine \u00bb il parlait.<\/p>\n<p class=\"\">Car en 2019, l\u2019homme de 41 ans avait \u00e9t\u00e9 jug\u00e9 \u00e0 Nantes pour des violences sur une ex-compagne en mars, octobre et novembre 2018, et condamn\u00e9 \u00e0 une peine d\u2019emprisonnement avec sursis et mise \u00e0 l\u2019\u00e9preuve. Manon connaissait-elle le pass\u00e9 judiciaire de son compagnon ? Ce qui est s\u00fbr, c\u2019est que la jeune femme de 31 ans, qui g\u00e9rait un centre \u00e9questre \u00e0 Saint-\u00c9tienne-de-Montluc, avait \u00ab pris conscience que son couple ne fonctionnait pas normalement \u00bb, affirment ses proches.<\/p>\n<p class=\"\">R\u00e9cemment, Manon Relandeau s\u2019\u00e9tait m\u00eame rapproch\u00e9e d\u2019une association venant en aide aux femmes victimes de violences conjugales \u00e0 Nantes, Citad\u2019elles. Selon les informations du Parisien, elle avait m\u00eame rendez-vous le 3 avril avec cette structure. Mais la jeune agricultrice, qui est port\u00e9e disparue depuis le 27 mars dernier, ne s\u2019est jamais pr\u00e9sent\u00e9e au rendez-vous.<\/p>\n<p>\u00ab Elle est tomb\u00e9e follement amoureuse de lui \u00bb<\/p>\n<p class=\"\">C\u2019est en 2022 que Manon Relandeau a rencontr\u00e9 Abdelkarim B., peu apr\u00e8s s\u2019\u00eatre s\u00e9par\u00e9e de son ancien conjoint avec qui elle \u00e9tait depuis une dizaine d\u2019ann\u00e9es. \u00c0 l\u2019\u00e9poque, la jeune femme venait de racheter la Ferme du Ch\u00eane Creux, une exploitation de 65 hectares, en bordure de marais, \u00e0 Saint-\u00c9tienne-de-Montluc.<\/p>\n<p class=\"\">Un terrain sur lequel elle a mont\u00e9 une pension pour chevaux et o\u00f9 elle \u00e9l\u00e8ve aussi des vaches de race Nantaise, une esp\u00e8ce rustique d\u00e9laiss\u00e9e par l\u2019agriculture moderne qui a failli s\u2019\u00e9teindre. \u00ab J\u2019ai \u00e9t\u00e9 fi\u00e8re de la voir devenir agricultrice. C\u2019est un bout de femme qui en voulait \u00bb, <a href=\"https:\/\/www.leparisien.fr\/faits-divers\/on-pense-encore-davantage-a-une-sequestration-les-proches-de-manon-relandeau-disparue-depuis-fin-mars-veulent-garder-espoir-23-04-2026-SC2VYSAACZAITIPLJLUXRHAVRU.php\" target=\"_blank\" rel=\"noreferrer nofollow noopener\">avait confi\u00e9 sa marraine \u00e0 Ouest-France, mi-avril.<\/a><\/p>\n<p class=\"lp-card-podcast-highlighting__title  lp-f-subtitle-05\">[2\/2] Juge Fran\u00e7ois Renaud\u00a0: le \u00ab\u00a0sh\u00e9rif\u00a0\u00bb de Lyon assassin\u00e9<\/p>\n<p><a class=\"lp-card-podcast-highlighting__call-to-action\" data-page-type=\"HP\" data-block-name=\"podcast-highlight\">\u00c9couter<\/a><\/p>\n<p class=\"\">\u00ab Elle est tomb\u00e9e follement amoureuse de lui \u00bb, se souvient sa marraine. Et quelques ann\u00e9es plus tard, le couple a accueilli Inaya, leur petite fille, le \u00ab petit bonheur \u00bb de Manon. \u00ab Elle est tellement belle en maman \u00bb, selon sa m\u00e8re. Mais depuis le 27 mars dernier, les proches de Manon Relandeau n\u2019ont plus aucune nouvelle d\u2019elle.<\/p>\n<p class=\"\">La derni\u00e8re fois qu\u2019ils ont vu la jeune agricultrice de 31 ans, \u00ab c\u2019\u00e9tait le week-end du 21 mars, pour mon anniversaire \u00bb, explique son beau-p\u00e8re. Ce jour-l\u00e0, Manon \u00ab \u00e9tait rayonnante, tellement heureuse \u00bb, selon sa m\u00e8re. Mais depuis, plus rien. Sa m\u00e8re et son beau-p\u00e8re suivent au jour le jour les avanc\u00e9es de l\u2019enqu\u00eate. Ils esp\u00e8rent que l\u2019interpellation d\u2019Abdelkarim B., le 27 avril dernier, pourra leur apporter des r\u00e9ponses sur la disparition de la jeune femme et souhaitent le \u00ab retour \u00bb de leur petite-fille, Inaya, \u00e2g\u00e9e de 15 mois, emmen\u00e9 par l\u2019homme en Alg\u00e9rie le 2 avril dernier<\/p>\n","protected":false},"excerpt":{"rendered":"Elle avait \u00ab pris conscience que son couple ne fonctionnait pas normalement \u00bb. Une semaine apr\u00e8s l\u2019interpellation d\u2019Abdelkarim&hellip;\n","protected":false},"author":2,"featured_media":910453,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[11,459,118,1011,27,12,25],"class_list":{"0":"post-910452","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-france","8":"tag-actualites","9":"tag-departements-horsidfo","10":"tag-faits-divers","11":"tag-fr","12":"tag-france","13":"tag-news","14":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116516059193552817","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/910452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=910452"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/910452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/910453"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=910452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=910452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=910452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}