{"id":911490,"date":"2026-05-04T22:20:15","date_gmt":"2026-05-04T22:20:15","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/911490\/"},"modified":"2026-05-04T22:20:15","modified_gmt":"2026-05-04T22:20:15","slug":"delphine-wespiser-absente-de-tout-beau-tout-neuf-durant-plusieurs-semaines-elle-explique-pourquoi-cest-ma-derniere-dans-lemission","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/911490\/","title":{"rendered":"Delphine Wespiser absente de Tout beau, tout neuf durant plusieurs semaines, elle explique pourquoi : \u00ab\u00a0C&rsquo;est ma derni\u00e8re dans l&rsquo;\u00e9mission\u00a0\u00bb"},"content":{"rendered":"<p>Vous ne reverrez pas Delphine Wespiser dans Tout beau, tout neuf avant plusieurs semaines. Ce lundi 4 mai, la chroniqueuse de <a href=\"https:\/\/www.programme-tv.net\/biographie\/25805-hanouna-cyril\/\" data-link-people=\"5dcd4d55-b4fe-4234-abc6-b74b4abdaf5c\" rel=\"nofollow noopener\" target=\"_blank\">Cyril Hanouna<\/a> a annonc\u00e9 qu&rsquo;elle serait absente de l&rsquo;\u00e9mission pour le reste de la saison. \u00ab\u00a0Ce soir, c&rsquo;est ma derni\u00e8re dans l&rsquo;\u00e9mission\u00a0\u00bb, a-t-elle annonc\u00e9. L&rsquo;animateur pensait qu&rsquo;elle serait pr\u00e9sente demain soir mais l&rsquo;ancienne Miss France lui a appris son d\u00e9part anticip\u00e9.<\/p>\n<p>\u00ab\u00a0Et demain, tu ne peux pas ?\u00a0\u00bb, a questionn\u00e9 Cyril Hanouna \u00e0 Delphine Wespiser qui a inform\u00e9 qu&rsquo;elle n&rsquo;est \u00ab\u00a0pas dispo\u00a0\u00bb pour venir dans l&rsquo;\u00e9mission. \u00ab\u00a0J&rsquo;ai un rendez-vous professionnel et ensuite je prends le train \u00e0 15 heures\u00a0\u00bb, a-t-elle expliqu\u00e9 avant de d\u00e9voiler la raison de son absence les prochaines semaines : \u00ab\u00a0Je pars \u00e0 Fort Boyard, mais je rentre d&rsquo;ici fin mai.\u00a0\u00bb<\/p>\n<p>                        Delphine Wespiser est devenue une chroniqueuse embl\u00e9matique de Tout beau, tout neuf<\/p>\n<p>Trois ans apr\u00e8s avoir quitt\u00e9 Touche pas \u00e0 mon poste, <a href=\"https:\/\/www.programme-tv.net\/news\/tv\/395873-delphine-wespiser-reintegre-la-bande-de-cyril-hanouna-apres-trois-ans-d-absence-son-compagnon-roger-a-joue-un-role-dans-son-retour\/\" data-api-deeplink=\"teleloisirs:\/\/news\/395873\" rel=\"nofollow noopener\" target=\"_blank\">Delphine Wespiser avait r\u00e9int\u00e9gr\u00e9 l&rsquo;\u00e9quipe de Cyril Hanouna dans Tout beau, tout neuf sur W9 en janvier 2026<\/a>. \u00ab\u00a0\u00c7a fait trois ans que je n&rsquo;ai pas revu le plateau, trois ans que je ne vous ai pas revus\u00a0\u00bb avait-elle exprim\u00e9 avant de se r\u00e9jouir de son retour : \u00ab\u00a0\u00c7a me fait tr\u00e8s plaisir et surtout \u00e7a me fait extr\u00eamement plaisir de revoir le public.\u00a0\u00bb<\/p>\n<p>Au cours de la saison, Delphine Wespiser est venue une chroniqueuse embl\u00e9matique de Tout beau, tout neuf. Elle n&rsquo;a jamais h\u00e9sit\u00e9 \u00e0 se faire entendre face \u00e0 Cyril Hanouna et \u00e0 faire des confidences sur sa vie priv\u00e9e, notamment sa relation avec son compagnon Roger atteint d&rsquo;un cancer.<\/p>\n<p>Mais son quotidien a \u00e9t\u00e9 impact\u00e9 par les tournages de l&rsquo;\u00e9mission puisqu&rsquo;elle a d\u00fb multiplier les allers-retours entre sa r\u00e9gion et Paris. Delphine Wespiser s&rsquo;\u00e9tait d&rsquo;ailleurs confi\u00e9e sur <a href=\"https:\/\/www.programme-tv.net\/news\/tv\/398226-je-rentre-a-l-hotel-delphine-wespiser-evoque-son-quotidien-loin-de-son-compagnon-roger-pour-venir-dans-l-emission-de-cyril-hanouna\/\" data-api-deeplink=\"teleloisirs:\/\/news\/398226\" rel=\"nofollow noopener\" target=\"_blank\">la distance avec son conjoint \u00e0 cause des nuits pass\u00e9es \u00e0 l&rsquo;h\u00f4tel pour TBT9<\/a>.<\/p>\n<p>Cyril Hanouna fait une annonce concernant la prochaine saison de Tout beau, tout neuf sur W9<\/p>\n<p>Apr\u00e8s l&rsquo;annonce du d\u00e9part de Delphine Wespiser, <a href=\"https:\/\/www.programme-tv.net\/news\/tv\/400930-cyril-hanouna-annonce-une-nouvelle-saison-de-tout-beau-tout-neuf-et-le-retour-d-un-ancien-chroniqueur-sur-w9\/\" data-api-deeplink=\"teleloisirs:\/\/news\/400930\" rel=\"nofollow noopener\" target=\"_blank\">Cyril Hanouna a donn\u00e9 des informations sur la prochaine saison de Tout beau, tout neuf sur W9<\/a>. \u00a0\u00bb Il y aura un, voire deux retours\u00a0\u00bb, a r\u00e9v\u00e9l\u00e9 l&rsquo;animateur avant de pr\u00e9ciser : \u00ab\u00a0une fille et un gar\u00e7on\u00a0\u00bb. \u00ab\u00a0Je suis d\u00e9j\u00e0 en recrutement sur l&rsquo;ann\u00e9e prochaine. Et il y a du bon monde\u00a0\u00bb, a-t-il promis aux t\u00e9l\u00e9spectateurs.<\/p>\n<p>Cyril Hanouna a \u00e9galement indiqu\u00e9 qu&rsquo;il y aura \u00ab\u00a0des nouveaut\u00e9s\u00a0\u00bb et \u00ab\u00a0beaucoup de nouveaux projets\u00a0\u00bb \u00e0 la rentr\u00e9e prochaine dans TBT9. \u00ab\u00a0On va on va s&rsquo;amuser, on va faire une belle saison\u00a0\u00bb, a-t-il esp\u00e9r\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"Vous ne reverrez pas Delphine Wespiser dans Tout beau, tout neuf avant plusieurs semaines. Ce lundi 4 mai,&hellip;\n","protected":false},"author":2,"featured_media":911491,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1359],"tags":[244,33841,58,59,1011,27,973,22497,49534,2395,1630],"class_list":{"0":"post-911490","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-commentaire","9":"tag-delphine-wespiser","10":"tag-divertissement","11":"tag-entertainment","12":"tag-fr","13":"tag-france","14":"tag-people","15":"tag-tout-beau","16":"tag-tout-n9uf","17":"tag-w9","18":"tag-zapping"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116518638561867964","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/911490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=911490"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/911490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/911491"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=911490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=911490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=911490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}