{"id":911899,"date":"2026-05-05T02:53:17","date_gmt":"2026-05-05T02:53:17","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/911899\/"},"modified":"2026-05-05T02:53:17","modified_gmt":"2026-05-05T02:53:17","slug":"kiev-repond-par-sa-propre-treve-au-cessez-le-feu-decrete-par-la-russie","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/911899\/","title":{"rendered":"Kiev r\u00e9pond par sa propre tr\u00eave au cessez-le-feu d\u00e9cr\u00e9t\u00e9 par la Russie"},"content":{"rendered":"<p>L&rsquo;Ukraine va observer sa propre tr\u00eave avec la Russie \u00e0 partir de mercredi, a d\u00e9clar\u00e9 Volodymyr Zelensky. Une d\u00e9claration faite apr\u00e8s l&rsquo;annonce par Moscou lundi d&rsquo;un cessez-le-feu unilat\u00e9ral avec Kiev \u00e0 l&rsquo;occasion des comm\u00e9morations de la victoire sovi\u00e9tique sur l&rsquo;Allemagne nazie en 1945.<\/p>\n<p>Le Kremlin a menac\u00e9 de lancer une \u00ab\u00a0frappe massive de missiles\u00a0\u00bb sur Kiev si l&rsquo;Ukraine violait cette tr\u00eave organis\u00e9e 81 ans apr\u00e8s la fin de la Seconde Guerre mondiale.<\/p>\n<p>Les autorit\u00e9s ukrainiennes ont r\u00e9pondu en d\u00e9clarant leur propre tr\u00eave \u00e0 partir de mercredi, avertissant qu&rsquo;elles comptaient alors \u00ab\u00a0agir de mani\u00e8re r\u00e9ciproque\u00a0\u00bb.<\/p>\n<p>Ces annonces interviennent \u00e0 un moment o\u00f9 les Etats-Unis recentrent leur attention sur le conflit au Moyen-Orient apr\u00e8s leurs efforts d\u00e9ploy\u00e9s pour mettre fin \u00e0 la guerre en Ukraine, provoqu\u00e9e par l&rsquo;invasion russe \u00e0 grande \u00e9chelle du pays en 2022.<\/p>\n<p>Menaces russes<\/p>\n<p>\u00ab\u00a0Conform\u00e9ment \u00e0 une d\u00e9cision du Commandant supr\u00eame des forces arm\u00e9es de la F\u00e9d\u00e9ration de Russie, (le pr\u00e9sident) Vladimir Poutine, un cessez-le-feu a \u00e9t\u00e9 d\u00e9cr\u00e9t\u00e9 du 8 au 9 mai 2026\u00a0\u00bb, a indiqu\u00e9 le minist\u00e8re dans un message publi\u00e9 sur MAX, une application de messagerie soutenue par l&rsquo;Etat.<\/p>\n<p>\u00ab\u00a0Si le r\u00e9gime de Kiev tente de mettre en oeuvre ses plans criminels visant \u00e0 perturber les c\u00e9l\u00e9brations du 81e anniversaire de la Victoire lors de la Grande Guerre patriotique, les forces arm\u00e9es russes lanceront une frappe massive de missiles de repr\u00e9sailles sur le centre de Kiev\u00a0\u00bb, a d\u00e9clar\u00e9 le minist\u00e8re russe de la D\u00e9fense dans un communiqu\u00e9 diffus\u00e9 \u00e9galement sur MAX.<\/p>\n<p>\u00ab\u00a0Nous avertissons la population civile de Kiev et les employ\u00e9s des missions diplomatiques \u00e9trang\u00e8res de la n\u00e9cessit\u00e9 de quitter la ville sans d\u00e9lai\u00a0\u00bb, a-t-il ajout\u00e9 sans autre explication.<\/p>\n<p>\u00ab\u00a0Aucune demande officielle\u00a0\u00bb<\/p>\n<p>La Russie comm\u00e9more chaque ann\u00e9e la Journ\u00e9e de la Victoire sovi\u00e9tique contre l&rsquo;Allemagne nazie en 1945 en organisant un vaste d\u00e9fil\u00e9 militaire sur la place Rouge \u00e0 Moscou.<\/p>\n<p> &gt;&gt; Voir le sujet diffus\u00e9 le 9 mai 2025 dans le 19h30\u00a0:   <img decoding=\"async\" class=\"embed-responsive-item\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/05\/jyeky4-28879265.image.jpeg\" alt=\"Comm\u00e9moration : contexte hautement s\u00e9curitaire pour les Russes\"\/>    Comm\u00e9moration : contexte hautement s\u00e9curitaire pour les Russes \/ 19h30 \/ 2 min. \/ le 9 mai 2025 <\/p>\n<p>De son c\u00f4t\u00e9, Volodymyr Zelensky, a d\u00e9clar\u00e9 lundi n&rsquo;avoir re\u00e7u \u00ab\u00a0aucune demande officielle\u00a0\u00bb concernant une telle tr\u00eave.<\/p>\n<p>\u00ab\u00a0Nous annon\u00e7ons un r\u00e9gime de cessez-le-feu \u00e0 partir de 00h00 dans la nuit du 5 au 6 mai\u00a0\u00bb, a-t-il ajout\u00e9. \u00ab\u00a0Nous agirons de mani\u00e8re r\u00e9ciproque \u00e0 partir de ce moment-l\u00e0\u00a0\u00bb. Le pr\u00e9sident ukrainien a ensuite atterri \u00e0 Bahre\u00efn pour des discussions sur la \u00ab\u00a0coop\u00e9ration en mati\u00e8re de s\u00e9curit\u00e9\u00a0\u00bb avec ce pays du Golfe, a indiqu\u00e9 une source au sein de la d\u00e9l\u00e9gation ukrainienne.<\/p>\n<p>Attaques meurtri\u00e8res<\/p>\n<p>Lundi, une frappe de missile russe a co\u00fbt\u00e9 la vie \u00e0 sept civils dans la ville de Merefa, situ\u00e9e pr\u00e8s de Kharkiv dans l&rsquo;est de l&rsquo;Ukraine, et une attaque de drone a provoqu\u00e9 la mort d&rsquo;un couple dans une localit\u00e9 du sud, selon les autorit\u00e9s ukrainiennes.<\/p>\n<p>Selon des informations pr\u00e9liminaires, l&rsquo;attaque a \u00e9t\u00e9 men\u00e9e \u00e0 l&rsquo;aide d&rsquo;un missile balistique de type Iskander, a pr\u00e9cis\u00e9 le parquet r\u00e9gional.<\/p>\n<p>L&rsquo;Ukraine se bat depuis plus de quatre ans contre l&rsquo;invasion russe \u00e0 grande \u00e9chelle et la r\u00e9gion de Kharkiv, frontali\u00e8re de la Russie, est tr\u00e8s r\u00e9guli\u00e8rement vis\u00e9e par des attaques russes. Une partie importante de ce territoire avait \u00e9t\u00e9 occup\u00e9e par l&rsquo;arm\u00e9e russe au d\u00e9but de la guerre, puis largement reprise par les forces ukrainiennes.<\/p>\n<p>Contenu externe<\/p>\n<p> Ce contenu externe ne peut pas \u00eatre affich\u00e9 car il est susceptible de collecter des donn\u00e9es personnelles. Pour voir ce contenu vous devez autoriser la cat\u00e9gorie <strong>Infographies<\/strong>. <\/p>\n<p> Accepter Plus d&rsquo;info <\/p>\n<p class=\"sources\">afp\/jtr<\/p>\n","protected":false},"excerpt":{"rendered":"L&rsquo;Ukraine va observer sa propre tr\u00eave avec la Russie \u00e0 partir de mercredi, a d\u00e9clar\u00e9 Volodymyr Zelensky. Une&hellip;\n","protected":false},"author":2,"featured_media":911900,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1591],"tags":[11,834,221,2120,3576,312,1887,131,3577,43503,11229,3343,12,316,33040,2543,1885,1886,132,220,1264,7137],"class_list":{"0":"post-911899","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-russie","8":"tag-actualites","9":"tag-attaque","10":"tag-cessez-le-feu","11":"tag-conflit","12":"tag-conflit-arme","13":"tag-diplomatie","14":"tag-federation-de-russie","15":"tag-guerre-en-ukraine","16":"tag-guerre-et-paix","17":"tag-invasion-de-lukraine-par-la-russie-en-2022","18":"tag-kiev","19":"tag-missile","20":"tag-news","21":"tag-politique","22":"tag-processus-de-paix","23":"tag-relations-internationales","24":"tag-russia","25":"tag-russian-federation","26":"tag-russie","27":"tag-ukraine","28":"tag-victoire","29":"tag-volodymyr-zelenskyy"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116519713147956488","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/911899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=911899"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/911899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/911900"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=911899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=911899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=911899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}