{"id":913281,"date":"2026-05-05T17:44:54","date_gmt":"2026-05-05T17:44:54","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/913281\/"},"modified":"2026-05-05T17:44:54","modified_gmt":"2026-05-05T17:44:54","slug":"usa-les-ventes-de-maisons-neuves-plus-elevees-quattendues-en-fevrier-et-mars-05-05-2026-a-1817","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/913281\/","title":{"rendered":"USA: les ventes de maisons neuves plus \u00e9lev\u00e9es qu&rsquo;attendues en f\u00e9vrier et mars &#8211; 05\/05\/2026 \u00e0 18:17"},"content":{"rendered":"<p>        <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/05\/d2ed4b8f3bab5228c1598f7969657d80-760x495.jpg\" alt=\"( AFP \/ FREDERIC J. BROWN )\" loading=\"eager\" fetchpriority=\"high\" width=\"760\" height=\"495\" style=\"max-width: 100%!important; height: auto;\"\/><\/p>\n<p class=\"c-image-news__legend\">( AFP \/ FREDERIC J. BROWN )<\/p>\n<p>\n Les ventes de maisons neuves aux \u00c9tats-Unis ont augment\u00e9 aux mois de f\u00e9vier et mars, faisant dans les deux cas mieux qu&rsquo;attendu par les march\u00e9s, selon les donn\u00e9es publi\u00e9es en d\u00e9cal\u00e9 mardi par le d\u00e9partement du Commerce.\n<\/p>\n<p>\n Au mois de f\u00e9vrier, 635.000 logements neufs ont \u00e9t\u00e9 vendus en rythme annualis\u00e9 \u2014 estimation du nombre total de ventes sur un an selon le rythme observ\u00e9 sur ce mois \u2014, en hausse de 8,9% par rapport au premier mois de l&rsquo;ann\u00e9e.\n<\/p>\n<p>\n Pour le mois de mars, elles atteignent 682.000 en rythme annualis\u00e9, soit une nouvelle hausse de 7,4% par rapport au mois de f\u00e9vrier, et de 3,3% sur un an.\n<\/p>\n<p>\n Dans les deux cas, c&rsquo;est un peu mieux qu&rsquo;envisag\u00e9 par les analystes, qui anticipaient 631.000 unit\u00e9s vendues en f\u00e9vrier et 660.000 en mars, selon le consensus publi\u00e9 par MarketWatch.\n<\/p>\n<p>\n Bonne nouvelle pour les acheteurs potentiels, les prix continuent de baisser au mois de mars, sur un mois comme sur un an, tant pour le prix m\u00e9dian que pour le prix moyen.\n<\/p>\n<p>\n Les ventes ont \u00e9t\u00e9, en effet, r\u00e9alis\u00e9es pour un prix m\u00e9dian de 387.400 dollars sur le troisi\u00e8me mois de l&rsquo;ann\u00e9e, soit 5,3% de moins qu&rsquo;au mois de f\u00e9vrier et m\u00eame 6,2% de moins qu&rsquo;en mars 2025.\n<\/p>\n<p>\n Le prix moyen est bien entendu plus \u00e9lev\u00e9, \u00e0 503.100 dollars mais \u00e9galement en baisse, de 3,4% par rapport au f\u00e9vrier et 1,2% de moins qu&rsquo;un an plus t\u00f4t.\n<\/p>\n<p>\n Le march\u00e9 am\u00e9ricain de l&rsquo;immobilier souffre toujours largement d&rsquo;un contexte difficile, avec des taux de pr\u00eats immobiliers toujours \u00e0 un niveau \u00e9lev\u00e9.\n<\/p>\n<p>\n Les pr\u00eats \u00e0 30 ans, les plus populaires au \u00c9tats-Unis, restent ainsi toujours assortis d&rsquo;un taux d&rsquo;int\u00e9r\u00eat moyen de 6,30%, selon les donn\u00e9es actualis\u00e9es au 30 avril de l&rsquo;agence de refinancement Freddie Mac.\n<\/p>\n<p>\n La guerre au Moyen-Orient a de nouveau propuls\u00e9 les taux \u00e0 la hausse alors que la tendance observ\u00e9e \u00e9tait au contraire \u00e0 un atterrissage depuis mai 2025, avec un taux moyen qui \u00e9tait pass\u00e9 sous la barre symbolique des 6% fin f\u00e9vrier.<\/p>\n","protected":false},"excerpt":{"rendered":"( AFP \/ FREDERIC J. BROWN ) Les ventes de maisons neuves aux \u00c9tats-Unis ont augment\u00e9 aux mois&hellip;\n","protected":false},"author":2,"featured_media":913282,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1589],"tags":[400,11,398,408,405,73,1866,403,402,399,404,12,401,406,1864,1865,1863,308,407],"class_list":{"0":"post-913281","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-etats-unis","8":"tag-action-cac-40","9":"tag-actualites","10":"tag-bourse-de-paris","11":"tag-boursorama","12":"tag-cotations","13":"tag-etats-unis","14":"tag-etats-unis-damerique","15":"tag-indices-devises","16":"tag-investir","17":"tag-investissement","18":"tag-marche-boursier","19":"tag-news","20":"tag-sicav","21":"tag-trackers","22":"tag-united-states","23":"tag-united-states-of-america","24":"tag-us","25":"tag-usa","26":"tag-warrants"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116523220707795714","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/913281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=913281"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/913281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/913282"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=913281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=913281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=913281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}