{"id":919149,"date":"2026-05-08T08:39:38","date_gmt":"2026-05-08T08:39:38","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/919149\/"},"modified":"2026-05-08T08:39:38","modified_gmt":"2026-05-08T08:39:38","slug":"un-projet-de-mega-soiree-pres-de-nantes-cherche-ses-benevoles","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/919149\/","title":{"rendered":"Un \u00ab\u00a0projet de m\u00e9ga soir\u00e9e\u00a0\u00bb pr\u00e8s de Nantes cherche ses b\u00e9n\u00e9voles"},"content":{"rendered":"<p>Le jeune<a href=\"https:\/\/www.facebook.com\/p\/Breizh-PMS-61557782154665\/\" rel=\"nofollow noopener\" target=\"_blank\"> festival PMS Breizh\u00a0(projet m\u00e9ga soir\u00e9e)<\/a> de Gu\u00e9men\u00e9-Penfao est \u00e0 la recherche de nouveaux b\u00e9n\u00e9voles. <a href=\"https:\/\/nantes.maville.com\/actu\/actudet_-des-jeunes-organisent-un-festival-pour-la-deuxieme-fois-dans-cette-commune-de-loire-atlantique-_8-7184039_actu.Htm\" rel=\"nofollow noopener\" target=\"_blank\">La quatri\u00e8me \u00e9dition <\/a>se d\u00e9roulera le samedi 11\u00a0juillet sur le site de Lizien.<\/p>\n<p>Au fil de trois\u00a0\u00e9ditions, ce festival se d\u00e9veloppe, m\u00eame s\u2019il reste \u00e0 taille humaine. Max\u00a0Patrigeon et son \u00e9quipe misent sur cinq cents\u00a0festivaliers.<\/p>\n<p>Nous souhaitons recruter des \u00e9quipiers, notamment pour le p\u00f4le S\u00e9curit\u00e9. Un festival r\u00e9ussi est avant tout un festival bien structur\u00e9 o\u00f9 chacun sait ce qu\u2019il a \u00e0 faire. Il faut simplement avoir le sens du contact et un \u00e9tat d\u2019esprit plut\u00f4t bienveillant. C\u2019est important d\u2019avoir un staff qui veille \u00e0 la fluidit\u00e9 des passages et \u00e0 la s\u00e9curisation des lieux, assure Max Patrigeon.<\/p>\n<p>Billetterie ouverte<\/p>\n<p>La programmation se veut \u00e9clectique avec des styles musicaux diff\u00e9rents\u00a0: rock, reggae, metal, rap ou encore techno. Le public va d\u00e9couvrir sur sc\u00e8ne plusieurs groupes\u00a0: Alvan, Boogie, Dyxxiz, KP Levrai, Dhamma Djarra, Good Morning Roger, KJD Blues Band\u00a0et Grande Surface.<\/p>\n<p>La billetterie est ouverte depuis le mois d\u2019avril dernier.<\/p>\n<p>Animations, march\u00e9, jam feu, camping, bar et restauration.<br \/><a href=\"https:\/\/www.breizhpms.fr\/\" rel=\"nofollow noopener\" target=\"_blank\">www.breizhpms.fr<\/a> \u2013 Facebook\u00a0: <a href=\"https:\/\/www.facebook.com\/search\/top\/?q=Breizh%20PMS\" rel=\"nofollow noopener\" target=\"_blank\">Breizh PMS<\/a><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Le jeune festival PMS Breizh\u00a0(projet m\u00e9ga soir\u00e9e) de Gu\u00e9men\u00e9-Penfao est \u00e0 la recherche de nouveaux b\u00e9n\u00e9voles. La quatri\u00e8me&hellip;\n","protected":false},"author":2,"featured_media":919150,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2818],"tags":[1111,11,15089,1809,1777,674,1011,27,30075,766,12,2636,3762,1095,25,3272,953],"class_list":{"0":"post-919149","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nantes","8":"tag-actu","9":"tag-actualites","10":"tag-benevoles","11":"tag-cherche","12":"tag-eu","13":"tag-europe","14":"tag-fr","15":"tag-france","16":"tag-mega","17":"tag-nantes","18":"tag-news","19":"tag-pays-de-la-loire","20":"tag-pres","21":"tag-projet","22":"tag-republique-francaise","23":"tag-saint-nazaire","24":"tag-soiree"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116538059407190636","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/919149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=919149"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/919149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/919150"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=919149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=919149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=919149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}