{"id":921290,"date":"2026-05-09T09:07:15","date_gmt":"2026-05-09T09:07:15","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/921290\/"},"modified":"2026-05-09T09:07:15","modified_gmt":"2026-05-09T09:07:15","slug":"qui-est-benjamin-voisin-le-futur-interprete-de-johnny-hallyday-au-cinema","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/921290\/","title":{"rendered":"Qui est Benjamin Voisin, le futur interpr\u00e8te de Johnny Hallyday au cin\u00e9ma ?"},"content":{"rendered":"<p>\n    <strong>PORTRAIT &#8211; <\/strong>L\u2019acteur de 29 ans, c\u00e9saris\u00e9 pour Les Illusions perdues, ne craint pas le contrepied et passe d\u2019une adaptation de L\u2019\u00c9tranger au biopic le plus rock\u2019n\u2019roll et le plus attendu de 2027. Il mouille d\u00e9j\u00e0 la chemise.<\/p>\n<p class=\"fig-paragraph\">Il n\u2019\u00e9tait plus \u00e0 un monstre pr\u00e8s. En d\u00e9cembre dernier, Benjamin Voisin a re\u00e7u un coup de t\u00e9l\u00e9phone lui proposant de se glisser dans la peau de Johnny Hallyday, apr\u00e8s avoir pr\u00eat\u00e9 ses traits \u00e0 des h\u00e9ros de Balzac, C\u00e9line et\u00a0<a href=\"http:\/\/www.lefigaro.fr\/culture\/mostra-de-venise-avec-l-etranger-adapte-par-francois-ozon-le-cinema-francais-bien-accueilli-20250902\" target=\"_blank\" data-fig-type=\"Article\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\">Camus<\/a>. Il a fallu \u00e0 l\u2019acteur de 29 ans \u00ab\u00a0quelques jours pour redescendre\u00a0\u00bb, ainsi qu\u2019il le confie \u00e0 Paris Match. Les audacieux sont condamn\u00e9s \u00e0 trembler plus que les autres. Le tournage d\u00e9marre au d\u00e9but du mois de juin.<\/p>\n<p class=\"fig-paragraph\">Le blouson de Johnny Hallyday ne devait pas lui revenir. Impliqu\u00e9e dans ce film biographique destin\u00e9 \u00e0 comm\u00e9morer les dix ans de la disparition de son \u00e9poux, Laeticia Hallyday souhaitait Rapha\u00ebl Quenard, visage atypique du cin\u00e9ma dont elle vantait le \u00ab\u00a0charisme presque animal\u00a0\u00bb. Arguant des contraintes d\u2019agenda, l\u2019acteur a annonc\u00e9 en janvier\u00a0<a href=\"http:\/\/www.lefigaro.fr\/cinema\/raphael-quenard-annonce-avec-regret-qu-il-n-incarnera-finalement-pas-johnny-hallyday-20260122\" target=\"_blank\" data-fig-type=\"NewsFlash\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\">se retirer du projet<\/a>. Alors que le nom de Pierre Lottin circulait \u00e9galement, Benjamin Voisin a h\u00e9rit\u00e9 du personnage. Et de la pression.<\/p>\n<p class=\"fig-body-link\">\n            \u00c0 lire aussi<br \/>\n        <a class=\"fig-body-link__link\" href=\"http:\/\/www.lefigaro.fr\/cinema\/le-biopic-sur-johnny-hallyday-incarne-par-benjamin-voisin-demarre-son-tournage-le-1er-juin-20260507\" target=\"_blank\" data-fig-type=\"NewsFlash\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\"><br \/>\n                Johnny Hallyday\u00a0: les premi\u00e8res images du biopic avec Benjamin Voisin d\u00e9voil\u00e9es<br \/>\n    <\/a>\n<\/p>\n<p>                                            <a class=\"fig-a11y-skip\" href=\"#fig-a11y-skip-main-inarticle\" is=\"fig-a11y-skip\" data-trigger-mode=\"visible-once\"><br \/>\n    Passer la publicit\u00e9<br \/>\n<\/a>            <\/p>\n<p>                                            Travail intensif<\/p>\n<p class=\"fig-paragraph\">\u00ab\u00a0C\u2019est du 8 heures \u00e0 22 heures tous les jours\u00a0\u00bb, confie \u00e0\u00a0<a href=\"https:\/\/www.parismatch.com\/culture\/cinema\/je-comprends-son-rapport-charnel-au-public-benjamin-voisin-plus-johnny-que-nature-268688\" target=\"_blank\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\">Match<\/a> \u00a0celui qui travaille la danse, la guitare et le chant. Il devra donner de la voix dans ce film qui embrasse la carri\u00e8re de Johnny jusqu\u2019en 1993 &#8211; les tables de mixage ach\u00e8veront de donner du cr\u00e9dit \u00e0 ses interpr\u00e9tations. Lors de ses pr\u00e9c\u00e9dents tournages, il a appris \u00e0 \u00e9monder pour la s\u00e9rie d\u2019Apple TV\u00a0<a href=\"http:\/\/tvmag.lefigaro.fr\/programme-tv\/series\/des-trois-mousquetaires-a-careme-martin-bourboulon-passeur-d-histoire-en-quete-de-liberte-20250503\" target=\"_blank\" data-fig-type=\"Article\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"TVMAG\">Car\u00eame<\/a> , \u00e0 boxer comme un professionnel pour le thriller familial Jouer avec le feu. Dans L\u2019\u00c9tranger, le combat n\u2019\u00e9tait pas moins violent, mais tout en int\u00e9riorit\u00e9.<\/p>\n<p class=\"fig-paragraph\">\u00ab Pour atteindre l\u2019absurdit\u00e9 camusienne, on se plonge dans un dr\u00f4le d\u2019\u00e9tat, on traverse une sorte de vertige. J\u2019ai pris des risques pour ma sant\u00e9 mentale\u00a0\u00bb, assurait dans\u00a0<a href=\"http:\/\/www.lefigaro.fr\/cinema\/benjamin-voisin-pour-atteindre-l-absurdite-camusienne-on-traverse-une-sorte-de-vertige-20251028\" target=\"_blank\" data-fig-type=\"Article\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\">Le Figaro<\/a> \u00a0Benjamin Voisin, \u00e0 la sortie du film de Fran\u00e7ois Ozon, salu\u00e9 par la critique. Ce fils d\u2019un professeur de th\u00e9\u00e2tre s\u2019investit dans ses r\u00f4les, ce dont t\u00e9moignait son exemplaire de L\u2019\u00c9tranger. Il dit avoir crois\u00e9 \u00ab\u00a0des plus chanceux, des plus talentueux\u00a0\u00bb que lui, mais peu de plus travailleurs. Les concerts de Johnny tournent d\u00e9sormais dans ses oreillettes. \u00ab\u00a0Je comprends son rapport charnel au public\u00a0\u00bb, commente le quasi-trentenaire, bravache.<\/p>\n<p class=\"fig-paragraph\">Xavier Giannoli dirait qu\u2019il peut se le permettre. \u00ab\u00a0Il suffit de voir son assurance face \u00e0 Depardieu. C\u2019est le m\u00eame m\u00e9tal\u00a0\u00bb, s\u2019enthousiasmait le r\u00e9alisateur qui l\u2019a fait tourner dans Les Illusions perdues (2021). Le r\u00f4le de Rubempr\u00e9 a valu au com\u00e9dien un C\u00e9sar du meilleur espoir masculin, apr\u00e8s une premi\u00e8re nomination \u00e0 la suite d\u2019<a href=\"https:\/\/www.lefigaro.fr\/cinema\/francois-ozon-replonge-a-l-ete-85-20200713\" target=\"_blank\" data-fig-type=\"Article\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\">\u00c9t\u00e9 85<\/a> \u00a0(2020). Avec un biopic \u00e0 45 millions de dollars de budget, le Parisien tient son grand r\u00f4le populaire.<\/p>\n<p>                                            Plus Dosto\u00efevski qu\u2019Instagram<\/p>\n<p class=\"fig-paragraph\">\u00ab\u00a0D\u2019une certaine fa\u00e7on, Benjamin s\u2019y pr\u00e9pare depuis des ann\u00e9es, cet acharn\u00e9 de travail ne craint pas de prendre sa place\u00a0\u00bb, t\u00e9moigne \u00e0 son propos son ami Martin Riedler, mannequin et apprenti com\u00e9dien. Il se souvient de lui tenant la drag\u00e9e haute \u00e0 Vincent Lindon sur le tournage de\u00a0<a href=\"http:\/\/www.lefigaro.fr\/culture\/notre-critique-de-jouer-avec-le-feu-ses-enfants-apres-lui-20250121\" target=\"_blank\" data-fig-type=\"Article\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\">Jouer avec le feu<\/a> . \u00ab\u00a0J\u2019ai en t\u00eate une sc\u00e8ne de combat de MMA dans une usine d\u00e9saffect\u00e9e, Benjamin envoyait chacune de ses r\u00e9pliques sans d\u00e9vier au milieu de cent cinquante figurants qui hurlaient.\u00a0\u00bb<\/p>\n<p class=\"fig-paragraph\">Pas f\u00e9brile devant ses partenaires chevronn\u00e9s &#8211; Lindon, mais aussi Depardieu ou Deneuve -, Benjamin Voisin tra\u00eene sa silhouette d\u00e9sinvolte dans les couloirs du septi\u00e8me art, d\u2019une s\u00e9rie en costume \u00e0 un futur film Netflix sur Quasimodo. Faux-semblant\u00a0? \u00ab\u00a0Ce lion cache un gars avec du c\u0153ur, une vieille \u00e2me\u00a0\u00bb, avance Martin Riedler \u00e0 propos de ce com\u00e9dien admiratif de\u00a0<a href=\"http:\/\/www.lefigaro.fr\/cinema\/il-y-a-40-ans-patrick-dewaere-disparaissait-un-fauve-le-dernier-jour-d-un-acteur-unique-20220716\" target=\"_blank\" data-fig-type=\"Article\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\">Patrick Dewaere<\/a>, qui pr\u00e9f\u00e8re Dosto\u00efevski \u00e0 Instagram (m\u00eame s\u2019il a fini par c\u00e9der). Un trait commun avec Johnny Hallyday, qui cachait le gamin sensible derri\u00e8re la b\u00eate de sc\u00e8ne.<\/p>\n","protected":false},"excerpt":{"rendered":"PORTRAIT &#8211; L\u2019acteur de 29 ans, c\u00e9saris\u00e9 pour Les Illusions perdues, ne craint pas le contrepied et passe&hellip;\n","protected":false},"author":2,"featured_media":921291,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1359],"tags":[56296,12975,58,59,1011,27,1304,973],"class_list":{"0":"post-921290","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-people","8":"tag-benjamin-voisin","9":"tag-biopic","10":"tag-divertissement","11":"tag-entertainment","12":"tag-fr","13":"tag-france","14":"tag-johnny-hallyday","15":"tag-people"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116543831963437683","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/921290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=921290"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/921290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/921291"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=921290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=921290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=921290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}