{"id":923281,"date":"2026-05-10T08:04:17","date_gmt":"2026-05-10T08:04:17","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/923281\/"},"modified":"2026-05-10T08:04:17","modified_gmt":"2026-05-10T08:04:17","slug":"inventeurs-dici-3-4-avoir-une-bonne-idee-ne-suffit-pas-comment-se-faire-accompagner-pour-transformer-son-genie-en-entreprise","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/923281\/","title":{"rendered":"Inventeurs d\u2019ici (3\/4)\u00a0: \u00ab\u00a0Avoir une bonne id\u00e9e ne suffit pas\u00a0\u00bb\u2026 Comment se faire accompagner pour transformer son g\u00e9nie en entreprise"},"content":{"rendered":"<p>\n                                                                Le prestigieux concours L\u00e9pine, organis\u00e9 depuis 1901, r\u00e9unit, jusqu\u2019au 11\u00a0mai 2026, 205 inventeurs \u00e0 la Foire de Paris. Et ils sont nombreux ces \u201cG\u00e9o Trouvetou\u201d d\u2019Occitanie en qu\u00eate d\u2019une m\u00e9daille. Mais comment bien g\u00e9rer le succ\u00e8s\u00a0? Catherine Pommier-Duffour est la directrice d\u00e9l\u00e9gu\u00e9e d\u00e9veloppement \u00e9conomique et innovation de Montpellier M\u00e9diterran\u00e9e M\u00e9tropole et Florent Desserre, responsable d\u2019unit\u00e9 accompagnement des entreprises au sein de l\u2019incubateur du BIC de Montpellier. Ces deux experts d\u00e9montrent que derri\u00e8re une bonne id\u00e9e, il y a tout un travail pour fonder une entreprise qui marche.\n                            <\/p>\n<p class=\"txt-question\">Avoir une bonne id\u00e9e, est-ce la garantie du succ\u00e8s d\u2019une entreprise\u00a0?<\/p>\n<p>\u00c9videmment non. On peut avoir la meilleure des id\u00e9es, mais si \u00e7a ne rencontre pas son march\u00e9, si \u00e7a ne fonctionne pas, \u00e7a n\u2019ira pas plus loin. La premi\u00e8re \u00e9tape est de v\u00e9rifier que le concept qu\u2019on imagine, qui fonctionne \u00e0 petite \u00e9chelle, peut passer \u00e0 plus grande \u00e9chelle et \u00e0 des co\u00fbts acceptables. Des contraintes techniques peuvent emp\u00eacher la r\u00e9plicabilit\u00e9. Il faut aussi \u00e9tudier la faisabilit\u00e9 commerciale, trouver le mod\u00e8le \u00e9conomique, v\u00e9rifier le march\u00e9 potentiel et les \u00e9ventuels concurrents. Enfin, il faut calibrer les besoins pour aller chercher les financements qui permettent de d\u00e9velopper chaque \u00e9tape en attendant que l\u2019id\u00e9e soit rentable.<\/p>\n<p class=\"txt-question\">Combien de temps faut-il compter pour parvenir \u00e0 une entreprise stable\u00a0?<\/p>\n<p>Entre trois et cinq ans\u2026 mais plut\u00f4t cinq ans. C\u2019est le bon timing pour avoir d\u00e9risqu\u00e9 pas mal de choses et stabilis\u00e9 financi\u00e8rement l\u2019entreprise sur son march\u00e9. Cela d\u00e9pend aussi du degr\u00e9 de rupture. Plus c\u2019est innovant, plus il y a de verrous \u00e0 lever, plus cela demande de l\u2019argent aussi.<\/p>\n<blockquote>\n<p>Un taux de survie \u00e0 5 ans de 85\u00a0% avec un accompagnement.<\/p>\n<\/blockquote>\n<p>                    <img decoding=\"async\" class=\"responsive-img\" src=\"https:\/\/www.europesays.com\/fr\/wp-content\/uploads\/2026\/05\/zfsf58-O.jpg\"\/><br \/>\n                <a class=\"stretched-link\" href=\"#paywall\" rel=\"js-anchor\"><\/p>\n<p>        <\/a><\/p>\n<p class=\"txt-question\">Cela peut \u00eatre une jungle. Il vaut mieux \u00eatre accompagn\u00e9\u00a0?<\/p>\n<p>Les entreprises pass\u00e9es par notre incubateur, le Bic de Montpellier, ont un taux de survie \u00e0 5 ans de 85\u00a0%, alors que la moyenne nationale est de 60\u00a0%. Cela montre l\u2019importance d\u2019un accompagnement individuel, avec un interlocuteur d\u00e9di\u00e9 qui d\u00e9risque toutes les phases et am\u00e8ne un \u0153il ext\u00e9rieur, donc des conseils pr\u00e9cieux, \u00e0 chaque \u00e9tape du d\u00e9veloppement du projet. C\u2019est aussi un acc\u00e8s \u00e0 un programme de formations, une solution d\u2019h\u00e9bergement dans nos locaux et l\u2019acc\u00e8s \u00e0 un r\u00e9seau de start-up ou de financeurs. On forme ainsi des personnes qui, normalement ne sont pas entrepreneurs, \u00e0 l\u2019entrepreneuriat\u00a0; on les aide \u00e0 g\u00e9rer une entreprise, \u00e0 la construire et \u00e0 la d\u00e9velopper.<\/p>\n<p class=\"txt-question\">Combien de candidatures arrivent au Bic\u00a0?<\/p>\n<p>Le Bic de Montpellier a 39 ans, il est l\u2019un des premiers incubateurs d\u00e9di\u00e9s aux entreprises innovantes d\u2019Europe. Nous recevons donc chaque ann\u00e9e quelque 180 dossiers de candidature et nous en s\u00e9lectionnons 40, pour rester \u00e0 120 entreprises accompagn\u00e9es. Nous avons trois crit\u00e8res principaux\u00a0: le degr\u00e9 d\u2019innovation\u00a0; la compl\u00e9mentarit\u00e9 de l\u2019\u00e9quipe\u00a0; la taille du march\u00e9 potentiel.<\/p>\n<p class=\"std-elt__inline\">\n        <strong>\u00c0 lire aussi :<\/strong><br \/>\n        <a href=\"https:\/\/www.midilibre.fr\/2026\/05\/10\/inventeurs-dici-14-professeur-bricolus-ou-macgyver-qui-sont-ces-geo-trouvetou-doccitanie-en-quete-dune-medaille-lepine-13362558.php\" rel=\"nofollow noopener\" target=\"_blank\">Inventeurs d\u2019ici (1\/4)\u00a0: Professeur Bricolus ou MacGyver\u2026 Qui sont ces \u201cG\u00e9o Trouvetou\u201d d\u2019Occitanie en qu\u00eate d\u2019une m\u00e9daille L\u00e9pine\u00a0?<\/a>\n    <\/p>\n<p>\u00a0<\/p>\n<p class=\"txt-question\">\u00c0 l\u2019heure de l\u2019IA, les projets qui vous sont pr\u00e9sent\u00e9s sont-ils surtout num\u00e9riques\u00a0?<\/p>\n<p>L\u2019intelligence artificielle est en effet devenue le levier de beaucoup de nouveaux projets\u00a0; en tout cas, le num\u00e9rique est forc\u00e9ment tr\u00e8s pr\u00e9sent \u00e0 un moment ou un autre. Et \u00e0 Montpellier, au regard de notre \u00e9cosyst\u00e8me \u00e9conomique et universitaire, nous recevons beaucoup de candidatures dans la sant\u00e9 ou l\u2019environnement.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Le prestigieux concours L\u00e9pine, organis\u00e9 depuis 1901, r\u00e9unit, jusqu\u2019au 11\u00a0mai 2026, 205 inventeurs \u00e0 la Foire de Paris.&hellip;\n","protected":false},"author":2,"featured_media":923282,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9599],"tags":[1111,11,1777,674,1011,27,7089,74682,2208,12,2680,83450,25],"class_list":{"0":"post-923281","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-montpellier","8":"tag-actu","9":"tag-actualites","10":"tag-eu","11":"tag-europe","12":"tag-fr","13":"tag-france","14":"tag-herault","15":"tag-le-dossier-du-dimanche","16":"tag-montpellier","17":"tag-news","18":"tag-occitanie","19":"tag-rendez-vous-de-la-redaction","20":"tag-republique-francaise"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116549247432281417","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/923281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=923281"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/923281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/923282"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=923281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=923281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=923281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}