{"id":923864,"date":"2026-05-10T15:10:22","date_gmt":"2026-05-10T15:10:22","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/923864\/"},"modified":"2026-05-10T15:10:22","modified_gmt":"2026-05-10T15:10:22","slug":"guerre-en-ukraine-ca-ne-peut-pas-etre-son-pote-vladimir-poutine-voudrait-quun-vieil-ami-et-ancien-dirigeant-europeen-devienne-le-mediateur-entre-la-russie-et-lue","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/923864\/","title":{"rendered":"Guerre en Ukraine : \u00ab\u00a0\u00e7a ne peut pas \u00eatre son pote\u00a0\u00bb&#8230; Vladimir Poutine voudrait qu&rsquo;un vieil ami et ancien dirigeant europ\u00e9en devienne le m\u00e9diateur entre la Russie et l&rsquo;UE"},"content":{"rendered":"<p>\n                                                                    l&rsquo;essentiel<br \/>\n                                                                Vladimir Poutine aimerait que son vieil ami Gerhard Schroeder, l&rsquo;ex-chancelier allemand, joue le m\u00e9diateur entre la Russie et l&rsquo;Union europ\u00e9enne. Une proposition qui h\u00e9risse Berlin.\n                            <\/p>\n<p>Alors qu&rsquo;il a affirm\u00e9, ce samedi 9 mai, que la guerre en Ukraine \u00ab\u00a0touchait \u00e0 sa fin\u00a0\u00bb, sans en pr\u00e9ciser davantage sur ses intentions, Vladimir Poutine a d\u00e9livr\u00e9 un autre message aux Europ\u00e9ens.\u00a0<\/p>\n<p class=\"std-elt__inline\">\n        <strong>\u00c0 lire aussi :<\/strong><br \/>\n        <a href=\"https:\/\/www.ladepeche.fr\/2026\/05\/02\/guerre-en-ukraine-leconomie-russe-au-bord-de-la-faillite-vladimir-poutine-reconnait-un-declin-la-suede-predit-une-catastrophe-financiere-13350691.php\" rel=\"nofollow noopener\" target=\"_blank\">Guerre en Ukraine\u00a0: l\u2019\u00e9conomie russe au bord de la faillite\u00a0? Vladimir Poutine reconna\u00eet un d\u00e9clin, la Su\u00e8de pr\u00e9dit une \u00ab\u00a0catastrophe financi\u00e8re\u00a0\u00bb<\/a>\n    <\/p>\n<p>Interrog\u00e9 sur son candidat id\u00e9al pour fluidifier le dialogue entre Moscou et l&rsquo;UE, en vue des discussions sur la future architecture de s\u00e9curit\u00e9 sur le Vieux Continent,\u00a0le ma\u00eetre du Kremlin a sa petite id\u00e9e. Et c&rsquo;est tout sauf une surprise. Le pr\u00e9sident russe a ainsi fait savoir qu&rsquo;il pr\u00e9f\u00e9rait \u00ab\u00a0personnellement\u00a0\u00bb, que ce soit Gerhard Schroeder, son ami et ex-chancelier allemand de 1998 \u00e0 2005.<\/p>\n<p class=\"std-elt__inline\">\n        <strong>\u00c0 lire aussi :<\/strong><br \/>\n        <a href=\"https:\/\/www.ladepeche.fr\/2026\/05\/09\/guerre-au-moyen-orient-une-livraison-de-5-000-drones-pour-attaquer-les-troupes-americaines-dans-le-golfe-le-plan-secret-de-vladimir-poutine-pour-aider-13363908.php\" rel=\"nofollow noopener\" target=\"_blank\">Guerre au Moyen-Orient : une livraison de 5 000 drones pour attaquer les troupes am\u00e9ricaines dans le Golfe, le plan secret de Vladimir Poutine pour aider l&rsquo;Iran<\/a>\n    <\/p>\n<p>Une proposition qui fait pol\u00e9mique outre-Rhin, \u00e0 l&rsquo;image de la r\u00e9action Michael Roth, ancien pr\u00e9sident social-d\u00e9mocrate de la commission des affaires \u00e9trang\u00e8res du Bundestag qui s&rsquo;est exprim\u00e9 dans <a href=\"https:\/\/www.tagesspiegel.de\/politik\/putin-wunscht-sich-schroder-als-friedensvermittler-uneinigkeit-in-der-spd--bundesregierung-spricht-von-scheinangebot-15579232.html\" target=\"_blank\" rel=\"nofollow noopener\">Tagesspiegel<\/a>. Pour lui, le m\u00e9diateur\u00a0entre la Russie et l&rsquo;UE ne peut \u00ab\u00a0tout simplement pas \u00eatre le pote de Poutine\u00a0\u00bb. D&rsquo;autres voix, comme le d\u00e9put\u00e9 Ralf Stegner dans le <a href=\"https:\/\/www.spiegel.de\/politik\/deutschland\/ukraine-spd-politiker-offen-fuer-putins-vorschlag-zu-schroeder-als-vermittler-a-6d13007a-1338-4c28-ab01-4d6d7fd78015\" target=\"_blank\" rel=\"nofollow noopener\">Spiegel<\/a>, se montrent plus ouvert \u00e0 l&rsquo;id\u00e9e : \u00ab\u00a0Si l\u2019on ne veut pas que Poutine et Trump d\u00e9cident seuls de l\u2019avenir de l\u2019Ukraine, il faut saisir chaque chance. M\u00eame si elle est infime \u00ab\u00a0.<\/p>\n<p class=\"std-elt__inline\">\n        <strong>\u00c0 lire aussi :<\/strong><br \/>\n        <a href=\"https:\/\/www.ladepeche.fr\/2026\/05\/08\/vladimir-poutine-je-vais-tous-les-tuer-la-colere-froide-du-maitre-du-kremlin-le-matin-de-la-tentative-de-putsch-devgueni-prigojine-13362221.php\" rel=\"nofollow noopener\" target=\"_blank\">Vladimir Poutine : \u00ab\u00a0Je vais tous les tuer\u00a0\u00bb&#8230; La col\u00e8re froide du ma\u00eetre du Kremlin le matin de la tentative de putsch d\u2019Evgueni Prigojine<\/a>\n    <\/p>\n<p>\u00ab\u00a0Offre de fa\u00e7ade\u00a0\u00bb<\/p>\n<p>Pour rappel Gerhard Schroeder (82 ans) avait refus\u00e9 de condamner l&rsquo;invasion russe en Ukraine en 2022, ce qui lui avait valu de vives critiques dans son pays. L&rsquo;ancien dirigeant de l&rsquo;Allemagne avait, apr\u00e8s sa carri\u00e8re en politique, eu des r\u00f4les cl\u00e9s dans les projets de gazoducs Nord Stream 1 et 2. Et m\u00eame obtenu une place au conseil d&rsquo;administration de Rosneft, le g\u00e9ant p\u00e9trolier russe, qu&rsquo;il a abandonn\u00e9e en 2022.<\/p>\n<p class=\"std-elt__inline\">\n        <strong>\u00c0 lire aussi :<\/strong><br \/>\n        <a href=\"https:\/\/www.ladepeche.fr\/2026\/05\/07\/poutine-retranche-dans-un-bunker-crainte-dun-coup-detat-le-maitre-du-kremlin-vit-coupe-de-la-realite-dans-une-forme-de-paranoia-permanente-13357983.php\" rel=\"nofollow noopener\" target=\"_blank\">Poutine\u00a0: retranch\u00e9 dans un bunker, crainte d\u2019un coup d\u2019\u00c9tat\u2026 le ma\u00eetre du Kremlin vit coup\u00e9 de la r\u00e9alit\u00e9, dans une forme de \u00ab\u00a0parano\u00efa permanente\u00a0\u00bb<\/a>\n    <\/p>\n<p>Comme l&rsquo;explique Reuters, le gouvernement allemand a oppos\u00e9 une fin de non-recevoir \u00e0 la proposition de Vladimir Poutine, qualifi\u00e9e d'\u00a0\u00bboffre de fa\u00e7ade\u00a0\u00bb faisant partie d&rsquo;une \u00ab\u00a0strat\u00e9gie hybride russe\u00a0\u00bb.<\/p>\n<p>De son c\u00f4t\u00e9, indique <a href=\"https:\/\/www.dw.com\/en\/no-comment-after-schr%C3%B6der-named-by-putin-for-ukraine-talks\/a-77110295\" target=\"_blank\" rel=\"nofollow noopener\">Deutesche Welle<\/a>, le bureau de Gerhard Schroeder n&rsquo;a pas fait de commentaire.<\/p>\n","protected":false},"excerpt":{"rendered":"l&rsquo;essentiel Vladimir Poutine aimerait que son vieil ami Gerhard Schroeder, l&rsquo;ex-chancelier allemand, joue le m\u00e9diateur entre la Russie&hellip;\n","protected":false},"author":2,"featured_media":923865,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1591],"tags":[11,1887,131,14,12,1885,1886,132],"class_list":{"0":"post-923864","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-russie","8":"tag-actualites","9":"tag-federation-de-russie","10":"tag-guerre-en-ukraine","11":"tag-international","12":"tag-news","13":"tag-russia","14":"tag-russian-federation","15":"tag-russie"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116550921639380816","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/923864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=923864"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/923864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/923865"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=923864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=923864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=923864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}