{"id":924886,"date":"2026-05-11T03:33:29","date_gmt":"2026-05-11T03:33:29","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/924886\/"},"modified":"2026-05-11T03:33:29","modified_gmt":"2026-05-11T03:33:29","slug":"classement-ligue-1-le-psg-sapproche-du-titre-marseille-dit-adieu-a-la-c1-la-bonne-operation-du-losc","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/924886\/","title":{"rendered":"Classement Ligue 1 : le PSG s\u2019approche du titre, Marseille dit adieu \u00e0 la C1, la bonne op\u00e9ration du Losc"},"content":{"rendered":"<p>\n    D\u00e9couvrez le classement du championnat de France de football \u00e0 l\u2019issue du multiplex comptant pour la 33e journ\u00e9e, toujours domin\u00e9 par le PSG.<\/p>\n<p class=\"fig-paragraph\">Le Paris Saint-Germain se rapproche du titre. Et peut remercier D\u00e9sir\u00e9 Dou\u00e9, seul buteur de la soir\u00e9e (83e). Gr\u00e2ce \u00e0 sa victoire ce dimanche soir au Parc des Princes face \u00e0 Brest (1-0) lors du\u00a0<a href=\"http:\/\/www.lefigaro.fr\/sports\/football\/ligue-1\/ligue-1-le-psg-fonce-vers-le-titre-lille-double-l-ol-pour-la-c1-l-om-se-relance-enfin-auxerre-envoie-provisoirement-nice-en-barrage-20260510\" target=\"_blank\" data-fig-type=\"NewsFlash\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\">multiplex de la 33e journ\u00e9e de Ligue 1<\/a>, le PSG a augment\u00e9 son avance sur son dauphin du RC Lens, qu\u2019il affrontera mercredi dans un match en retard. Avec six points d\u2019avance et le m\u00eame nombre de journ\u00e9es, les Parisiens sont en (tr\u00e8s) bon chemin pour glaner le 14e titre de champion de France de leur histoire.<\/p>\n<p class=\"fig-body-link\">\n            \u00c0 lire aussi<br \/>\n        <a class=\"fig-body-link__link\" href=\"http:\/\/www.lefigaro.fr\/sports\/football\/ligue-1\/psg-brest-doue-allume-la-lumiere-le-cup-fait-la-fete-des-brestois-inoffensifs-coups-de-coeur-et-coups-de-griffe-20260510\" target=\"_blank\" data-fig-type=\"NewsFlash\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\"><br \/>\n                PSG-Brest\u00a0: Dou\u00e9 allume la lumi\u00e8re, le CUP fait la f\u00eate, des Brestois inoffensifs&#8230; Coups de c\u0153ur et coups de griffe<br \/>\n    <\/a>\n<\/p>\n<p class=\"fig-paragraph\">Derri\u00e8re le duo de t\u00eate, l\u2019Olympique Lyonnais &#8211; qui s\u2019est inclin\u00e9 \u00e0 Toulouse (1-2) &#8211; a vu sa troisi\u00e8me place \u00eatre prise par le Losc, qui s\u2019est impos\u00e9 \u00e0 Monaco (1-0). Les Mon\u00e9gasques sortent du Top 6 et sont d\u00e9sormais 7es. L\u2019Olympique de Marseille, en plein cauchemar ces derniers temps avec trois matches de suite sans victoire et des brouilles dans les vestiaires, s\u2019est relanc\u00e9 sur la pelouse du Havre gr\u00e2ce \u00e0 un penalty marqu\u00e9 par Mason Greenwood (1-0)&#8230; Mais a dit adieu \u00e0 la Ligue des champions. Avec quatre points d\u2019\u00e9cart sur la troisi\u00e8me place &#8211; tours pr\u00e9liminaires de la C1 &#8211; les Marseillais ne pourront pas la rattraper et au mieux accrocher une place en Ligue Europa lors de la derni\u00e8re journ\u00e9e.<\/p>\n<p>                                            <a class=\"fig-a11y-skip\" href=\"#fig-a11y-skip-main-inarticle\" is=\"fig-a11y-skip\" data-trigger-mode=\"visible-once\"><br \/>\n    Passer la publicit\u00e9<br \/>\n<\/a>            <\/p>\n<p class=\"fig-paragraph\">En bas de tableau, Metz, d\u00e9j\u00e0 rel\u00e9gu\u00e9, s\u2019est encore lourdement inclin\u00e9 \u00e0 domicile face \u00e0 Lorient (0-4). Auxerre a remport\u00e9 le choc de bas de tableau face \u00e0 l\u2019OGC Nice (2-1), qui se voit \u00eatre, \u00e0 une journ\u00e9e de la fin, barragiste. La mauvaise op\u00e9ration de la soir\u00e9e.<\/p>\n<p class=\"fig-paragraph\">Le classement complet de Ligue 1 est<a href=\"https:\/\/www.lefigaro.fr\/sports\/football\/ligue-1\/classement\" target=\"_blank\" rel=\"noopener nofollow\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\">\u00a0\u00e0 retrouver ici.<\/a><\/p>\n<tr>\n<td>1. Paris Saint-Germain<\/td>\n<td>73 points<\/td>\n<\/tr>\n<tr>\n<td>2. Lens<\/td>\n<td>67 points<\/td>\n<\/tr>\n<tr>\n<td>3. Lille<\/td>\n<td>61 points<\/td>\n<\/tr>\n<tr>\n<td>4. Lyon<\/td>\n<td>60 points<\/td>\n<\/tr>\n<tr>\n<td>5. Rennes<\/td>\n<td>59 points<\/td>\n<\/tr>\n<tr>\n<td>6. Marseille<\/td>\n<td>56 points<\/td>\n<\/tr>\n<tr>\n<td>7. Monaco<\/td>\n<td>54 points<\/td>\n<\/tr>\n<tr>\n<td>8. Strasbourg<\/td>\n<td>47 points<\/td>\n<\/tr>\n<tr>\n<td>9. Lorient<\/td>\n<td>45 points<\/td>\n<\/tr>\n<tr>\n<td>10. Toulouse<\/td>\n<td>44 points<\/td>\n<\/tr>\n<tr>\n<td>11. Paris FC<\/td>\n<td>41 points<\/td>\n<\/tr>\n<tr>\n<td>12. Brest<\/td>\n<td>38 points<\/td>\n<\/tr>\n<tr>\n<td>13. Angers<\/td>\n<td>35 points<\/td>\n<\/tr>\n<tr>\n<td>14. Le Havre<\/td>\n<td>32 points<\/td>\n<\/tr>\n<tr>\n<td>15. Auxerre<\/td>\n<td>31 points<\/td>\n<\/tr>\n<tr>\n<td>16. Nice<\/td>\n<td>31 points<\/td>\n<\/tr>\n<tr>\n<td>17. Nantes<\/td>\n<td>23 points<\/td>\n<\/tr>\n<tr>\n<td>18. Metz<\/td>\n<td>18 points<\/td>\n<\/tr>\n","protected":false},"excerpt":{"rendered":"D\u00e9couvrez le classement du championnat de France de football \u00e0 l\u2019issue du multiplex comptant pour la 33e journ\u00e9e,&hellip;\n","protected":false},"author":2,"featured_media":924887,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2814],"tags":[1111,11,525,1981,814,1777,674,2257,63,1011,27,3309,66,1307,884,955,12,1176,978,882,93,25,1980],"class_list":{"0":"post-924886","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-marseille","8":"tag-actu","9":"tag-actualites","10":"tag-calendrier","11":"tag-classement","12":"tag-direct","13":"tag-eu","14":"tag-europe","15":"tag-foot","16":"tag-football","17":"tag-fr","18":"tag-france","19":"tag-l1","20":"tag-ligue-1","21":"tag-lille","22":"tag-marseille","23":"tag-match","24":"tag-news","25":"tag-olympique-de-marseille","26":"tag-olympique-lyonnais","27":"tag-provence-alpes-cote-dazur","28":"tag-psg","29":"tag-republique-francaise","30":"tag-resultats"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116553843050064675","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/924886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=924886"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/924886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/924887"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=924886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=924886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=924886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}