{"id":926454,"date":"2026-05-11T20:26:16","date_gmt":"2026-05-11T20:26:16","guid":{"rendered":"https:\/\/www.europesays.com\/fr\/926454\/"},"modified":"2026-05-11T20:26:16","modified_gmt":"2026-05-11T20:26:16","slug":"jappelle-le-17-plus-souvent-que-ma-mere-a-nice-la-detresse-des-habitants-apres-une-nouvelle-fusillade-aux-moulins","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/fr\/926454\/","title":{"rendered":"\u00abJ\u2019appelle le 17 plus souvent que ma m\u00e8re\u00bb : \u00e0 Nice, la d\u00e9tresse des habitants apr\u00e8s une nouvelle fusillade aux Moulins"},"content":{"rendered":"<p>\n    Voisins et riverains crient leur col\u00e8re et leur exasp\u00e9ration, dans ce quartier min\u00e9 par une \u00ab\u00e9ni\u00e8me\u00bb trag\u00e9die.<\/p>\n<p class=\"fig-paragraph\">Sabrina est forc\u00e9e de s\u2019asseoir. La t\u00eate alourdie par l\u2019\u00e9cho des tirs et leur r\u00e9p\u00e9tition, la quadrag\u00e9naire, impuissante, relate en boucle que sa fille \u00abde 10 ans \u00e9tait en train de rentrer de l\u2019\u00e9cole quand elle a entendu les tirs. Elle n\u2019arr\u00eate pas de pleurer depuis\u00bb. Pour la deuxi\u00e8me fois, \u00e0 quelques jours d\u2019intervalle, le\u00a0<a href=\"http:\/\/www.lefigaro.fr\/nice\/un-homme-poignarde-au-visage-dans-le-quartier-des-moulins-a-nice-20251202\" data-fig-type=\"NewsFlash\" data-gtm-custom-categorie=\"navigation\" data-gtm-custom-action=\"crossclick\" data-gtm-custom-label=\"Contextuel\" data-gtm-event=\"customEventSPE\" data-fig-domain=\"LEFIGARO\" rel=\"nofollow noopener\" target=\"_blank\">quartier des Moulins<\/a>, \u00e0 l\u2019ouest de Nice (Alpes-Maritimes) a \u00e9t\u00e9 le th\u00e9\u00e2tre d\u2019une \u00ab\u00e9ni\u00e8me\u00bb trag\u00e9die, cette fois encore sur la place centrale des Amaryllis.<\/p>\n<p class=\"fig-paragraph\">\u00abDepuis mon appartement, on voit tout\u00bb, assure-t-elle \u00e0 regret. Ce lundi 11 mai, la m\u00e8re a \u00abseulement entendu les rafales\u00bb qui r\u00e9sonnaient sur la petite place, am\u00e9nag\u00e9e pour les enfants. Il est 15h30 quand un homme a fait irruption sur une trottinette \u00e9lectrique, arme de guerre \u00e0 la main ; il se dirige vers une \u00e9picerie, Le palais sucr\u00e9, et aurait successivement fait feu \u00e0 l\u2019ext\u00e9rieur, \u00e0 travers la vitre, puis \u00e0 l\u2019int\u00e9rieur de la petite \u00e9choppe. Le tireur est ensuite reparti, r\u00e9cup\u00e9r\u00e9 par une voiture qui l\u2019attendait\u2026<\/p>\n<p class=\"fig-premium-paywall__infos\">\n        Cet article est r\u00e9serv\u00e9 aux abonn\u00e9s.        Il vous reste 84% \u00e0 d\u00e9couvrir.\n    <\/p>\n<p>                <img  data- alt=\"Le Figaro\" class=\"fig-img--complete fig-img\"\/><\/p>\n<p class=\"fig-premium-paywall__title\">Vente Flash<\/p>\n<p class=\"fig-premium-paywall__subtitle\">-70% sur votre abonnement. Sans engagement.<\/p>\n<p class=\"fig-premium-paywall__connect\">\n                D\u00e9j\u00e0 abonn\u00e9\u00a0?                <a class=\"fig-premium-paywall__connect-link\" href=\"https:\/\/connect.lefigaro.fr\/login?client=horizon_web&amp;type=main&amp;redirect_uri=https%3A%2F%2Fwww.lefigaro.fr%2Fnice%2Fj-appelle-le-17-plus-souvent-que-ma-mere-a-nice-la-detresse-des-habitants-apres-une-nouvelle-fusillade-aux-moulins-20260511\" data-js-gtm=\"{&quot;event&quot;:&quot;customEventGA4&quot;,&quot;eventName&quot;:&quot;click_action&quot;,&quot;feature&quot;:&quot;paywall&quot;,&quot;location&quot;:&quot;paywall&quot;,&quot;button_action&quot;:&quot;connect&quot;,&quot;click_text&quot;:&quot;Connectez-vous&quot;}\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n                    Connectez-vous<br \/>\n                <\/a>\n            <\/p>\n","protected":false},"excerpt":{"rendered":"Voisins et riverains crient leur col\u00e8re et leur exasp\u00e9ration, dans ce quartier min\u00e9 par une \u00ab\u00e9ni\u00e8me\u00bb trag\u00e9die. Sabrina&hellip;\n","protected":false},"author":2,"featured_media":926455,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2819],"tags":[1111,11,1777,674,1011,27,3832,12,2401,882,10210,25,887],"class_list":{"0":"post-926454","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nice","8":"tag-actu","9":"tag-actualites","10":"tag-eu","11":"tag-europe","12":"tag-fr","13":"tag-france","14":"tag-fusillade","15":"tag-news","16":"tag-nice","17":"tag-provence-alpes-cote-dazur","18":"tag-reglement-de-compte","19":"tag-republique-francaise","20":"tag-trafic-de-drogue"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@fr\/116557826517635261","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/926454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/comments?post=926454"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/posts\/926454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media\/926455"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/media?parent=926454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/categories?post=926454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/fr\/wp-json\/wp\/v2\/tags?post=926454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}